{"id":307,"date":"2021-10-27T12:12:52","date_gmt":"2021-10-27T12:12:52","guid":{"rendered":"https:\/\/d66.nl\/zwolle\/?page_id=307"},"modified":"2021-11-25T20:41:35","modified_gmt":"2021-11-25T20:41:35","slug":"zorg-gezondheid-en-sport","status":"publish","type":"topics","link":"https:\/\/d66.nl\/zwolle\/standpunten\/zorg-gezondheid-en-sport\/","title":{"rendered":"Zorg, gezondheid en sport"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--100 wrapper__spacing-bottom-desktop--140 wrapper__spacing-bottom-mobile--110  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--0 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section\n  class=\"block-small-hero\"\n  data-video-url=\"\"\n>\n  <div class=\"block-small-hero__wrapper\">\n\t<div class=\"block-small-hero__heading\">\n\t  <div class=\"block-small-hero__title\">\n\t\t<h1 class=\"heading heading__align--left heading__color--black heading__size--giant  heading__weight--normal\" id=\"nav-introductie3953\" data-nav-heading=\"Introductie\" data-nav-heading-mobile=\"Introductie\">\n\tVrij van zorgen over zorg<\/h1>\t  <\/div>\n\t  \t<\/div>\n\n\t\n\t\t  <div class=\"block-small-hero__image\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/3\/2021\/10\/d66\u2014zorg-en-gezondheid_zorg_patient_ziekenhuis_iStock-1024x576.jpg\" class=\"image block-small-hero__img\" alt=\"\" \/>\n\t\t\t<div class=\"image__caption-wrapper block-small-hero__caption-wrapper\">\n\t\t\t<div class=\"image__caption block-small-hero__caption\">\n\t\t\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--small paragraph__weight--medium\">\n\t\ten vrije samenleving begint bij een goede gezondheid. Als je niet gezond bent, dan word je zoveel mogelijk geholpen, zodat ook jij zoveel mogelijk vrij kunt zijn. <i>&#x2022;<\/i> Beeld: iStock\t<\/p>\t\t\t<\/div>\n\t\t<\/div>\t  <\/div>\n\t\t<div class=\"block-small-hero__columns block-small-hero__columns--two\" data-accordion-active=\"0\">\n\t  <div class=\"block-small-hero__column\">\n\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default\">\n\t\tEen vrije samenleving begint bij een goede gezondheid. Als je niet gezond bent, dan word je zoveel mogelijk geholpen, zodat ook jij zoveel mogelijk vrij kunt zijn. Door de coronacrisis beseffen we meer dan ooit: goede, toegankelijke en betaalbare zorg is letterlijk van levensbelang.<br><br>Als je zorg nodig hebt, moet die zorg er zijn. Van goede kwaliteit. We maken dus keuzes voor goede zorg voor iedereen. Zodat niemand een belemmering voelt om naar de dokter te gaan. Je niet twintig weken hoeft te wachten voordat je met een psycholoog kunt praten.\t<\/p>\t  <\/div>\n\t  \t  <div class=\"block-small-hero__column\">\n\t\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default\">\n\t\tOnze ouderen voldoende aandacht krijgen in het verpleeghuis, omdat er meer zorgpersoneel is.\u00a0Er\u00a0voldoende medicijnen beschikbaar zijn, omdat Europa eindelijk onafhankelijk is van de medicijnproductie in China en India.<br><br>Gezondheid is meer dan alleen \u2018niet ziek zijn\u2019. Schone lucht, goed werk, voldoende sporten en geestelijke gezondheid zijn het startpunt van een gezond leven. Voorkomen dat mensen ziek worden is ten slotte het beste medicijn voor een vrije samenleving.\t<\/p>\t  <\/div>\n\t  \t  \t<\/div>\n  <\/div>\n<\/section>\n\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper wrapper__spacing-top-large--0 wrapper__spacing-bottom-large--60  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<h2 class=\"heading heading__align--left heading__color--black heading__size--huge heading__font--sans heading__weight--semiBold  block-heading__heading\" id=\"nav-standpunten2251\" data-nav-heading=\"Standpunten\" data-nav-heading-mobile=\"Standpunten\" >\n\tOnze standpunten<\/h2>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--100  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--22 wrapper__width-mobile--24\">\n\t\t<div class=\"js-article-grid\">\n\t\t<div\n\t\tclass=\"block-article-listing js-block-article-listing\"\n\t\tdata-latest-post-id=\"481\"\n\t\tdata-how-many-to-load=\"12\"\n\t\tdata-post-type=\"manifesto\"\n\t\tdata-filtering=\"no-filter\"\t\tdata-categories=\"18\"\t\tdata-sites=\"\"\n\t\tdata-syndication=\"current-site\"\n\t\tdata-nothing-found-text=\"\"\n\n\t\t\t\t>\n\t\t<input type=\"hidden\" id=\"_wpnonce\" name=\"_wpnonce\" value=\"4ec248308f\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/zwolle\/wp-json\/wp\/v2\/standpunten\/307\" \/><div class=\"block-point-of-view-grid-new js-block-point-of-view-grid-new\">\n\t<div class=\"block-point-of-view-grid-new__grid\">\n\n\t\t\t\t\t<div class=\"block-point-of-view-grid-new__row-desktop block-point-of-view-grid-new__row-desktop-bottom\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-point-of-view-grid-new__item block-point-of-view-grid-new__item--first\">\n\t\t\t\t\t\t\t<article class=\"small-article-card js-small-article-card  block-point-of-view-grid-new__small-article-card\">\n\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t\t\n\t<a class=\"small-article-card__wrapper small-article-card__color--rosePink\" style=\"background-image: url('https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/78\/2022\/01\/bart-ros-8KAeo3tt13U-unsplash-1024x683.jpg')\" href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/tot-slot\/\">\n\t\t\n\t\t<div class=\"small-article-card__heading\">\n<h2 class=\"heading heading__align--left heading__color--white heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-tot-slot8751\" data-nav-heading-mobile=\"Tot slot\">\n\tTot slot<\/h2>\n<\/div>\t\t\t\t\t\t\t<div class=\"small-article-card__button-wrapper\">\n\t\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   small-article-card__buttonV2\" id=\"\" style=\"--buttonV2-text-color: var(--global-colors-white)\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t\t<\/div>\n\t\t\t<\/a>\n<\/article>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-point-of-view-grid-new__item block-point-of-view-grid-new__item--second\">\n\t\t\t\t\t\t\t<div class=\"mini-card  mini-card__style mini-card__style--spacious   block-point-of-view-grid-new__mini-card\" data-post-id=\"0\">\n\t\n\t\t\t\t<div class=\"mini-card__heading  mini-card__limit-lines mini-card__limit-lines--2\">\n\t\t\t<a href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/brede-welvaart-als-doel-gezonde-gemeentefinancien-als-basis\/\" class=\"mini-card__link\">\n\t\t\t\t<h2 class=\"heading heading__align--left heading__color--black heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-brede-welvaart-als-doel--gezonde-gemeentefinanci--n-als-basis6690\">\n\tBrede welvaart als doel, gezonde gemeentefinanci\u00ebn als basis<\/h2>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\n\t\t\t<div class=\"mini-card__paragraph  mini-card__limit-lines mini-card__limit-lines--3\">\n\t\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default paragraph__weight--medium\">\n\t\tBrede welvaart als doel, gezonde gemeentefinanci\u00ebn als basis. D66 staat voor gezonde transparante gemeentefinanci\u00ebn. Niet alleen voor de korte termijn (komende gemeenteraadsperiode), maar duurzaam voor langere tijd en los van de partijpolitieke kleuren van het Zwolse stadsbestuur.\t<\/p>\t\t<\/div>\n\t\n\t<a href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/brede-welvaart-als-doel-gezonde-gemeentefinancien-als-basis\/\" class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default buttonV2__link  mini-card__buttonV2\" id=\"\" target=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/a><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-point-of-view-grid-new__item block-point-of-view-grid-new__item--third\">\n\t\t\t\t\t\t\t<article class=\"small-article-card js-small-article-card  block-point-of-view-grid-new__small-article-card\">\n\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t\t\n\t<a class=\"small-article-card__wrapper small-article-card__color--yellow\" style=\"background-image: url('https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/78\/2022\/01\/hoite-prins-eiHIKdhEZJo-unsplash-1024x726.jpg')\" href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/klimaat-en-natuur\/\">\n\t\t\n\t\t<div class=\"small-article-card__heading\">\n<h2 class=\"heading heading__align--left heading__color--white heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-klimaat-en-natuur9797\" data-nav-heading-mobile=\"Klimaat en natuur\">\n\tKlimaat en natuur<\/h2>\n<\/div>\t\t\t\t\t\t\t<div class=\"small-article-card__button-wrapper\">\n\t\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   small-article-card__buttonV2\" id=\"\" style=\"--buttonV2-text-color: var(--global-colors-white)\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t\t<\/div>\n\t\t\t<\/a>\n<\/article>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"block-point-of-view-grid-new__row-desktop block-point-of-view-grid-new__row-desktop-bottom\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-point-of-view-grid-new__item block-point-of-view-grid-new__item--fourth\">\n\t\t\t\t\t\t\t<article class=\"small-article-card js-small-article-card  block-point-of-view-grid-new__small-article-card\">\n\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t\t\n\t<a class=\"small-article-card__wrapper small-article-card__color--skyBlue\" style=\"background-image: url('https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/78\/2022\/01\/edwin-westerhoff-NDdlTLFCwR0-unsplash-1024x683.jpg')\" href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/sociaal-en-gezond\/\">\n\t\t\n\t\t<div class=\"small-article-card__heading\">\n<h2 class=\"heading heading__align--left heading__color--white heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-sociaal-en-gezond7811\" data-nav-heading-mobile=\"Sociaal en gezond\">\n\tSociaal en gezond<\/h2>\n<\/div>\t\t\t\t\t\t\t<div class=\"small-article-card__button-wrapper\">\n\t\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   small-article-card__buttonV2\" id=\"\" style=\"--buttonV2-text-color: var(--global-colors-white)\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t\t<\/div>\n\t\t\t<\/a>\n<\/article>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-point-of-view-grid-new__item block-point-of-view-grid-new__item--fifth\">\n\t\t\t\t\t\t\t<article class=\"small-article-card js-small-article-card  block-point-of-view-grid-new__small-article-card\">\n\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t\t\n\t<a class=\"small-article-card__wrapper small-article-card__color--tomato\" style=\"background-image: url('https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/78\/2022\/01\/bart-ros-ats8JSla8xA-unsplash-1024x683.jpg')\" href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/economie-arbeidsmarkt-onderwijs\/\">\n\t\t\n\t\t<div class=\"small-article-card__heading\">\n<h2 class=\"heading heading__align--left heading__color--white heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-economie--arbeidsmarkt-en-onderwijs7469\" data-nav-heading-mobile=\"Economie, arbeidsmarkt en onderwijs\">\n\tEconomie, arbeidsmarkt en onderwijs<\/h2>\n<\/div>\t\t\t\t\t\t\t<div class=\"small-article-card__button-wrapper\">\n\t\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   small-article-card__buttonV2\" id=\"\" style=\"--buttonV2-text-color: var(--global-colors-white)\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t\t<\/div>\n\t\t\t<\/a>\n<\/article>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-point-of-view-grid-new__item block-point-of-view-grid-new__item--sixth\">\n\t\t\t\t\t\t\t<article class=\"small-article-card js-small-article-card  block-point-of-view-grid-new__small-article-card\">\n\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t\t\n\t<a class=\"small-article-card__wrapper small-article-card__color--romanSilver\" style=\"background-image: url('https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/78\/2022\/01\/marjan-samuel-bredewold-bFBWnW21zwY-unsplash-576x1024.jpg')\" href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/wonen-en-leven\/\">\n\t\t\n\t\t<div class=\"small-article-card__heading\">\n<h2 class=\"heading heading__align--left heading__color--white heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-wonen-en-leven3004\" data-nav-heading-mobile=\"Wonen en leven\">\n\tWonen en leven<\/h2>\n<\/div>\t\t\t\t\t\t\t<div class=\"small-article-card__button-wrapper\">\n\t\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   small-article-card__buttonV2\" id=\"\" style=\"--buttonV2-text-color: var(--global-colors-white)\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t\t<\/div>\n\t\t\t<\/a>\n<\/article>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\n\t<\/div>\n\t\t\t<div class=\"block-point-of-view-grid-new__accordions\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-point-of-view-grid-new block-point-of-view-grid-new--first\">\n\t\t\t\t\t\t<article class=\"small-article-card js-small-article-card  block-point-of-view-grid-new__small-article-card\">\n\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t\t\n\t<a class=\"small-article-card__wrapper small-article-card__color--rosePink\" style=\"background-image: url('https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/78\/2022\/01\/bart-ros-8KAeo3tt13U-unsplash-1024x683.jpg')\" href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/tot-slot\/\">\n\t\t\n\t\t<div class=\"small-article-card__heading\">\n<h2 class=\"heading heading__align--left heading__color--white heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-tot-slot142\" data-nav-heading-mobile=\"Tot slot\">\n\tTot slot<\/h2>\n<\/div>\t\t\t\t\t\t\t<div class=\"small-article-card__button-wrapper\">\n\t\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   small-article-card__buttonV2\" id=\"\" style=\"--buttonV2-text-color: var(--global-colors-white)\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t\t<\/div>\n\t\t\t<\/a>\n<\/article>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-point-of-view-grid-new block-point-of-view-grid-new--second\">\n\t\t\t\t\t\t<div class=\"mini-card  mini-card__style mini-card__style--spacious   block-point-of-view-grid-new__mini-card\" data-post-id=\"0\">\n\t\n\t\t\t\t<div class=\"mini-card__heading  mini-card__limit-lines mini-card__limit-lines--2\">\n\t\t\t<a href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/brede-welvaart-als-doel-gezonde-gemeentefinancien-als-basis\/\" class=\"mini-card__link\">\n\t\t\t\t<h2 class=\"heading heading__align--left heading__color--black heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-brede-welvaart-als-doel--gezonde-gemeentefinanci--n-als-basis6162\">\n\tBrede welvaart als doel, gezonde gemeentefinanci\u00ebn als basis<\/h2>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\n\t\t\t<div class=\"mini-card__paragraph  mini-card__limit-lines mini-card__limit-lines--3\">\n\t\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default paragraph__weight--medium\">\n\t\tBrede welvaart als doel, gezonde gemeentefinanci\u00ebn als basis. D66 staat voor gezonde transparante gemeentefinanci\u00ebn. Niet alleen voor de korte termijn (komende gemeenteraadsperiode), maar duurzaam voor langere tijd en los van de partijpolitieke kleuren van het Zwolse stadsbestuur.\t<\/p>\t\t<\/div>\n\t\n\t<a href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/brede-welvaart-als-doel-gezonde-gemeentefinancien-als-basis\/\" class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default buttonV2__link  mini-card__buttonV2\" id=\"\" target=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/a><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-point-of-view-grid-new block-point-of-view-grid-new--third\">\n\t\t\t\t\t\t<article class=\"small-article-card js-small-article-card  block-point-of-view-grid-new__small-article-card\">\n\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t\t\n\t<a class=\"small-article-card__wrapper small-article-card__color--yellow\" style=\"background-image: url('https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/78\/2022\/01\/hoite-prins-eiHIKdhEZJo-unsplash-1024x726.jpg')\" href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/klimaat-en-natuur\/\">\n\t\t\n\t\t<div class=\"small-article-card__heading\">\n<h2 class=\"heading heading__align--left heading__color--white heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-klimaat-en-natuur7523\" data-nav-heading-mobile=\"Klimaat en natuur\">\n\tKlimaat en natuur<\/h2>\n<\/div>\t\t\t\t\t\t\t<div class=\"small-article-card__button-wrapper\">\n\t\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   small-article-card__buttonV2\" id=\"\" style=\"--buttonV2-text-color: var(--global-colors-white)\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t\t<\/div>\n\t\t\t<\/a>\n<\/article>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-point-of-view-grid-new block-point-of-view-grid-new--fourth\">\n\t\t\t\t\t\t<article class=\"small-article-card js-small-article-card  block-point-of-view-grid-new__small-article-card\">\n\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t\t\n\t<a class=\"small-article-card__wrapper small-article-card__color--skyBlue\" style=\"background-image: url('https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/78\/2022\/01\/edwin-westerhoff-NDdlTLFCwR0-unsplash-1024x683.jpg')\" href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/sociaal-en-gezond\/\">\n\t\t\n\t\t<div class=\"small-article-card__heading\">\n<h2 class=\"heading heading__align--left heading__color--white heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-sociaal-en-gezond5423\" data-nav-heading-mobile=\"Sociaal en gezond\">\n\tSociaal en gezond<\/h2>\n<\/div>\t\t\t\t\t\t\t<div class=\"small-article-card__button-wrapper\">\n\t\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   small-article-card__buttonV2\" id=\"\" style=\"--buttonV2-text-color: var(--global-colors-white)\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t\t<\/div>\n\t\t\t<\/a>\n<\/article>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-point-of-view-grid-new block-point-of-view-grid-new--fifth\">\n\t\t\t\t\t\t<article class=\"small-article-card js-small-article-card  block-point-of-view-grid-new__small-article-card\">\n\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t\t\n\t<a class=\"small-article-card__wrapper small-article-card__color--tomato\" style=\"background-image: url('https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/78\/2022\/01\/bart-ros-ats8JSla8xA-unsplash-1024x683.jpg')\" href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/economie-arbeidsmarkt-onderwijs\/\">\n\t\t\n\t\t<div class=\"small-article-card__heading\">\n<h2 class=\"heading heading__align--left heading__color--white heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-economie--arbeidsmarkt-en-onderwijs3077\" data-nav-heading-mobile=\"Economie, arbeidsmarkt en onderwijs\">\n\tEconomie, arbeidsmarkt en onderwijs<\/h2>\n<\/div>\t\t\t\t\t\t\t<div class=\"small-article-card__button-wrapper\">\n\t\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   small-article-card__buttonV2\" id=\"\" style=\"--buttonV2-text-color: var(--global-colors-white)\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t\t<\/div>\n\t\t\t<\/a>\n<\/article>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-point-of-view-grid-new block-point-of-view-grid-new--sixth\">\n\t\t\t\t\t\t<article class=\"small-article-card js-small-article-card  block-point-of-view-grid-new__small-article-card\">\n\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t\t\n\t<a class=\"small-article-card__wrapper small-article-card__color--romanSilver\" style=\"background-image: url('https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/78\/2022\/01\/marjan-samuel-bredewold-bFBWnW21zwY-unsplash-576x1024.jpg')\" href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/wonen-en-leven\/\">\n\t\t\n\t\t<div class=\"small-article-card__heading\">\n<h2 class=\"heading heading__align--left heading__color--white heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-wonen-en-leven9316\" data-nav-heading-mobile=\"Wonen en leven\">\n\tWonen en leven<\/h2>\n<\/div>\t\t\t\t\t\t\t<div class=\"small-article-card__button-wrapper\">\n\t\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   small-article-card__buttonV2\" id=\"\" style=\"--buttonV2-text-color: var(--global-colors-white)\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t\t<\/div>\n\t\t\t<\/a>\n<\/article>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div><div class=\"block-point-of-view-grid-new js-block-point-of-view-grid-new\">\n\t<div class=\"block-point-of-view-grid-new__grid\">\n\n\t\t\t\t\t<div class=\"block-point-of-view-grid-new__row-desktop block-point-of-view-grid-new__row-desktop-bottom\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-point-of-view-grid-new__item block-point-of-view-grid-new__item--first\">\n\t\t\t\t\t\t\t<article class=\"small-article-card js-small-article-card  block-point-of-view-grid-new__small-article-card\">\n\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t\t\n\t<a class=\"small-article-card__wrapper small-article-card__color--yellow\" style=\"background-image: url('https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/78\/2021\/11\/randy-peters-eOaTXkCVX6k-unsplash-819x1024.jpg')\" href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/onderliggende-principes\/\">\n\t\t\n\t\t<div class=\"small-article-card__heading\">\n<h2 class=\"heading heading__align--left heading__color--white heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-inleiding1213\" data-nav-heading-mobile=\"Inleiding\">\n\tInleiding<\/h2>\n<\/div>\t\t\t\t\t\t\t<div class=\"small-article-card__button-wrapper\">\n\t\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   small-article-card__buttonV2\" id=\"\" style=\"--buttonV2-text-color: var(--global-colors-white)\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t\t<\/div>\n\t\t\t<\/a>\n<\/article>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n\t\t\t<div class=\"block-point-of-view-grid-new__accordions\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-point-of-view-grid-new block-point-of-view-grid-new--first\">\n\t\t\t\t\t\t<article class=\"small-article-card js-small-article-card  block-point-of-view-grid-new__small-article-card\">\n\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t\t\n\t<a class=\"small-article-card__wrapper small-article-card__color--yellow\" style=\"background-image: url('https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/78\/2021\/11\/randy-peters-eOaTXkCVX6k-unsplash-819x1024.jpg')\" href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/onderliggende-principes\/\">\n\t\t\n\t\t<div class=\"small-article-card__heading\">\n<h2 class=\"heading heading__align--left heading__color--white heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-inleiding6657\" data-nav-heading-mobile=\"Inleiding\">\n\tInleiding<\/h2>\n<\/div>\t\t\t\t\t\t\t<div class=\"small-article-card__button-wrapper\">\n\t\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   small-article-card__buttonV2\" id=\"\" style=\"--buttonV2-text-color: var(--global-colors-white)\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t\t<\/div>\n\t\t\t<\/a>\n<\/article>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div><p\n\t\tclass=\"paragraph paragraph__align--center      js-article-listing-pagination\"\n\t\t\t>\n\t\tToont 7 van 7\t<\/p><br \/>\t<\/div>\n<\/div>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper wrapper__spacing-top-large--0 wrapper__spacing-bottom-large--60  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<h2 class=\"heading heading__align--left heading__color--black heading__size--huge heading__font--sans heading__weight--semiBold  block-heading__heading\" id=\"nav-nieuws3904\" data-nav-heading=\"Nieuws\" data-nav-heading-mobile=\"Nieuws\" >\n\tLaatste nieuws<\/h2>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--220 wrapper__spacing-bottom-tablet--190 wrapper__spacing-bottom-mobile--140  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t\n<section class=\"block-stories-wall-slider-dynamic block-stories-wall-slider-dynamic__posttype--post js-block-stories-wall-slider-dynamic\">\n\t<div class=\"block-stories-wall-slider-dynamic__header-wrapper block-stories-wall-slider-dynamic__header-wrapper--default\">\n\t\t<div class=\"block-stories-wall-slider-dynamic__title\">\n\t\t\t<h2 class=\"heading heading__align--left heading__color--black heading__size--huge  heading__weight--bold\" id=\"nav-6692\" data-nav-heading-mobile=\"\">\n\t<\/h2>\t\t<\/div>\n\t\t\t<\/div>\n\n\t<div class=\"block-stories-wall-slider-dynamic__slider\">\n\t\t<div class=\"carousel-slider js-carousel-slider carousel-slider__for--cards\" data-is-slider-initialized=\"0\">\n\t<div class=\"carousel-slider__wrapper js-carousel-wrapper\">\n\t\t<div class=\"swiper\">\n\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<article class=\"article-card article-card__color--tomato\" data-gtm-event=\"click\" data-gtm-group=\"updates\" data-gtm-target=\"Betere aanpak nodig voor psychisch kwetsbare personen\">\n\t\t<a class=\"article-card__link\" href=\"https:\/\/d66.nl\/zwolle\/nieuws\/betere-aanpak-nodig-voor-psychisch-kwetsbare-personen\/\" aria-label=\"Link naar artikel\">\n\t\t<header class=\"article-card__header\">\n\n\t\t\t\t\t\t<div class=\"article-card__meta-row-wrapper\">\n\t\t\t\t<div class=\"article-card__date\">\n\t\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--semiBold\">\n\t\t01.03.2022\t<\/p>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/header>\n\n\t\t<div class=\"article-card__body\">\n\t\t\t\t\t\t\t<h3 class=\"heading   heading__size--large heading__font--sans heading__weight--bold\" id=\"nav-betere-aanpak-nodig-voor-psychisch-kwetsbare-personen7244\">\n\tBetere aanpak nodig voor psychisch kwetsbare personen<\/h3>\t\t\t\t\t\t\t\t\t\t<div class=\"article-card__excerpt\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--default paragraph__weight--medium\">\n\t\tD66 vindt dat de huidige aanpak voor psychisch kwetsbare personen tekort schiet en komt met idee\u00ebn voor een gerichtere aanpak.\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   article-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<article class=\"article-card article-card__color--skyBlue\" data-gtm-event=\"click\" data-gtm-group=\"updates\" data-gtm-target=\"Investeer in sport en bewegen in de openbare ruimte\">\n\t\t<a class=\"article-card__link\" href=\"https:\/\/d66.nl\/zwolle\/nieuws\/investeer-in-sport-en-bewegen-in-de-openbare-ruimte\/\" aria-label=\"Link naar artikel\">\n\t\t<header class=\"article-card__header\">\n\n\t\t\t\t\t\t<div class=\"article-card__meta-row-wrapper\">\n\t\t\t\t<div class=\"article-card__date\">\n\t\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--semiBold\">\n\t\t12.11.2021\t<\/p>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/header>\n\n\t\t<div class=\"article-card__body\">\n\t\t\t\t\t\t\t<h3 class=\"heading   heading__size--large heading__font--sans heading__weight--bold\" id=\"nav-investeer-in-sport-en-bewegen-in-de-openbare-ruimte1354\">\n\tInvesteer in sport en bewegen in de openbare ruimte<\/h3>\t\t\t\t\t\t\t\t\t\t<div class=\"article-card__excerpt\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--default paragraph__weight--medium\">\n\t\tSport brengt mensen bij elkaar en is fysiek en mentaal heel gezond. Daarom wil D66 dat alle Zwollenaren de mogelijkheid hebben om te sporten.\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   article-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<article class=\"article-card article-card__color--romanSilver  article-card__variation--full-height-img\" style=\"background-image: url('https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/3\/2021\/10\/d66-geschiedenis-overwinning-2021-1024x576.jpg')\" data-gtm-event=\"click\" data-gtm-group=\"updates\" data-gtm-target=\"D66 is de tweede partij van Nederland\">\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t<a class=\"article-card__link\" href=\"https:\/\/d66.nl\/zwolle\/nieuws\/d66-is-de-tweede-partij-van-nederland\/\" aria-label=\"Link naar artikel\">\n\t\t<header class=\"article-card__header\">\n\n\t\t\t\t\t\t<div class=\"article-card__meta-row-wrapper\">\n\t\t\t\t<div class=\"article-card__date\">\n\t\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--semiBold\">\n\t\t18.03.2021\t<\/p>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/header>\n\n\t\t<div class=\"article-card__body\">\n\t\t\t\t\t\t\t<h3 class=\"heading   heading__size--large heading__font--sans heading__weight--bold\" id=\"nav-d66-is-de-tweede-partij-van-nederland6076\">\n\tD66 is de tweede partij van Nederland<\/h3>\t\t\t\t\t\t\t\t\t\t<div class=\"article-card__excerpt\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--default paragraph__weight--medium\">\n\t\tD66 won de Tweede Kamerverkiezingen van 2021. Sigrid Kaag reageert op de uitslag.\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   article-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"carousel-slider-navigation js-carousel-slider-navigation carousel-slider-navigation__offset--always\">\n\t<div class=\"carousel-slider-navigation__fraction-pagination-wrapper\">\n\t\t<span class=\"custom-swiper-pagination-current\">1<\/span> \/ <span class=\"custom-swiper-pagination-total\">X<\/span>\n\t<\/div>\n\t<div class=\"carousel-slider-navigation__pagination-wrapper\">\n\t\t<div class=\"carousel-slider-navigation__pagination js-swiper-progressbar\"><\/div>\n\t<\/div>\n\t<div class=\"carousel-slider-navigation__navigation\">\n\t\t<button class=\"carousel-slider-navigation__nav-button carousel-slider-navigation__nav-button--prev js-swiper-prev\" aria-label=\"Previous slide\"><\/button>\n\t\t<button class=\"carousel-slider-navigation__nav-button carousel-slider-navigation__nav-button--next js-swiper-next\" aria-label=\"Next slide\"><\/button>\n\t<\/div>\n<\/div>\t\n<\/div>\t<\/div>\n\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper wrapper__spacing-top-large--0 wrapper__spacing-bottom-large--60  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<h2 class=\"heading heading__align--left heading__color--black heading__size--huge heading__font--sans heading__weight--semiBold  block-heading__heading\" id=\"nav-verkiezingsprogramma3125\" data-nav-heading=\"Verkiezingsprogramma\" data-nav-heading-mobile=\"Verkiezingsprogramma\" >\n\tHet verkiezings-<br>programma<\/h2>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--60 wrapper__spacing-bottom-desktop--60 wrapper__spacing-bottom-mobile--30  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--24 wrapper__width-mobile--24 wrapper__offset-desktop--0 wrapper__offset-mobile--0\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tSamen met inwoners, ondernemers en leden hebben we nagedacht en gesproken over onze idee\u00ebn voor de toekomst. In het verkiezingsprogramma lees je deze plannen waarmee we de komende jaren aan de slag willen gaan.\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--100 wrapper__spacing-bottom-desktop--60 wrapper__spacing-bottom-mobile--40  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--17 wrapper__width-mobile--24\">\n\t\t<div class=\"cta block-cta__cta\">\n  <div class=\"box box__style--full-width-on-mobile cta__box\" style=\"--box-bg-color: var(--global-colors-romanSilver);--box-text-color: var(--global-colors-white)\">\n\t<h2 class=\"heading heading__align--left heading__color--white heading__size--largest heading__font--sans heading__weight--semiBold  cta__heading\" id=\"nav-lees-ons-programma9594\" data-nav-heading-mobile=\"Lees ons programma\">\n\tLees ons programma<\/h2><div class=\"cta__image\">\n\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/3\/2021\/10\/d66-events-191109-212-D66-Congres110-JeroenMooijman-1024x576.jpg\" class=\"image cta__img\" alt=\"\" \/>\n\t<\/div><p class=\"paragraph paragraph__align--left paragraph__color--white paragraph__size--default paragraph__weight--medium  cta__paragraph\">\n\t\tJe bent pas vrij als iedereen dat is. D66 gelooft in gelijke kansen voor iedereen en hulp voor wie het nodig heeft.\t<\/p><div class=\"cta__buttons-wrapper\"><a href=\"https:\/\/d66.nl\/zwolle\/verkiezingsprogramma\/\" class=\"btn btn__color--white btn__size--default btn__size-width--default    cta__btn\" id=\"\" title=\"Verkiezingsprogramma\" data-last-site-id=\"1\">\n\t<div class=\"btn__top-wrapper\">\n\t\t\n\t\t<span class=\"btn__title\">\n\t\t\tVerkiezingsprogramma\t\t<\/span>\n\n\t\t\t<\/div>\n\n\t<span class=\"btn__description\">\n\t\t\t<\/span>\n\n\t<span class=\"btn__spinner btn__spinner--white btn__spinner--default\" aria-hidden=\"true\"><\/span>\n<\/a><\/div><\/div><\/div>\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"author":6,"featured_media":300000212,"parent":0,"menu_order":0,"template":"with-navigation.php","meta":{"_acf_changed":false},"search-tags":[6],"topic-subtopics":[],"themes-or-point-of-view":[24],"class_list":["post-307","topics","type-topics","status-publish","has-post-thumbnail","hentry","search-tags-zorg-gezondheid-sport","themes-or-point-of-view-theme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D66 Zwolle &#8212; Zorg, gezondheid en sport | Standpunten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/zwolle\/standpunten\/zorg-gezondheid-en-sport\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D66 Zwolle &#8212; Zorg, gezondheid en sport | Standpunten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/zwolle\/standpunten\/zorg-gezondheid-en-sport\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Zwolle\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-25T20:41:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@D66Zwolle\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/\",\"name\":\"D66 Zwolle &#8212; Zorg, gezondheid en sport | Standpunten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/10\\\/d66\u2014zorg-en-gezondheid_zorg_patient_ziekenhuis_iStock.jpg\",\"datePublished\":\"2021-10-27T12:12:52+00:00\",\"dateModified\":\"2021-11-25T20:41:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/zwolle\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/10\\\/d66\u2014zorg-en-gezondheid_zorg_patient_ziekenhuis_iStock.jpg\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/10\\\/d66\u2014zorg-en-gezondheid_zorg_patient_ziekenhuis_iStock.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zorg, gezondheid en sport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/\",\"name\":\"D66 Zwolle\",\"description\":\"Just another D66 Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/zwolle\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D66 Zwolle &#8212; Zorg, gezondheid en sport | Standpunten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/zwolle\/standpunten\/zorg-gezondheid-en-sport\/","og_locale":"nl_NL","og_type":"article","og_title":"D66 Zwolle &#8212; Zorg, gezondheid en sport | Standpunten","og_url":"https:\/\/d66.nl\/zwolle\/standpunten\/zorg-gezondheid-en-sport\/","og_site_name":"D66 Zwolle","article_modified_time":"2021-11-25T20:41:35+00:00","twitter_card":"summary_large_image","twitter_site":"@D66Zwolle","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/zwolle\/standpunten\/zorg-gezondheid-en-sport\/","url":"https:\/\/d66.nl\/zwolle\/standpunten\/zorg-gezondheid-en-sport\/","name":"D66 Zwolle &#8212; Zorg, gezondheid en sport | Standpunten","isPartOf":{"@id":"https:\/\/d66.nl\/zwolle\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d66.nl\/zwolle\/standpunten\/zorg-gezondheid-en-sport\/#primaryimage"},"image":{"@id":"https:\/\/d66.nl\/zwolle\/standpunten\/zorg-gezondheid-en-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/3\/2021\/10\/d66\u2014zorg-en-gezondheid_zorg_patient_ziekenhuis_iStock.jpg","datePublished":"2021-10-27T12:12:52+00:00","dateModified":"2021-11-25T20:41:35+00:00","breadcrumb":{"@id":"https:\/\/d66.nl\/zwolle\/standpunten\/zorg-gezondheid-en-sport\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/zwolle\/standpunten\/zorg-gezondheid-en-sport\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/zwolle\/standpunten\/zorg-gezondheid-en-sport\/#primaryimage","url":"https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/3\/2021\/10\/d66\u2014zorg-en-gezondheid_zorg_patient_ziekenhuis_iStock.jpg","contentUrl":"https:\/\/d66.nl\/zwolle\/wp-content\/uploads\/sites\/3\/2021\/10\/d66\u2014zorg-en-gezondheid_zorg_patient_ziekenhuis_iStock.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/zwolle\/standpunten\/zorg-gezondheid-en-sport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/zwolle\/"},{"@type":"ListItem","position":2,"name":"Zorg, gezondheid en sport"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/zwolle\/#website","url":"https:\/\/d66.nl\/zwolle\/","name":"D66 Zwolle","description":"Just another D66 Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/zwolle\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/zwolle\/wp-json\/wp\/v2\/standpunten\/307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/zwolle\/wp-json\/wp\/v2\/standpunten"}],"about":[{"href":"https:\/\/d66.nl\/zwolle\/wp-json\/wp\/v2\/types\/topics"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/zwolle\/wp-json\/wp\/v2\/users\/6"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d66.nl\/zwolle\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/zwolle\/wp-json\/wp\/v2\/media?parent=307"}],"wp:term":[{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/zwolle\/wp-json\/wp\/v2\/search-tags?post=307"},{"taxonomy":"topic-sub-topics","embeddable":true,"href":"https:\/\/d66.nl\/zwolle\/wp-json\/wp\/v2\/topic-subtopics?post=307"},{"taxonomy":"themes-or-point-of-view","embeddable":true,"href":"https:\/\/d66.nl\/zwolle\/wp-json\/wp\/v2\/themes-or-point-of-view?post=307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}