{"id":25,"count":11,"description":"","link":"https:\/\/d66.nl\/zoetermeer\/themes-or-point-of-view\/point-of-view\/","name":"Point of view","slug":"point-of-view","taxonomy":"themes-or-point-of-view","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Point of view Archives &#8212; D66 Zoetermeer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/zoetermeer\/themes-or-point-of-view\/point-of-view\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Point of view Archives &#8212; D66 Zoetermeer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/zoetermeer\/themes-or-point-of-view\/point-of-view\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Zoetermeer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/themes-or-point-of-view\\\/point-of-view\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/themes-or-point-of-view\\\/point-of-view\\\/\",\"name\":\"Point of view Archives &#8212; D66 Zoetermeer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/themes-or-point-of-view\\\/point-of-view\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/themes-or-point-of-view\\\/point-of-view\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Point of view\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/\",\"name\":\"D66 Zoetermeer\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/zoetermeer\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Point of view Archives &#8212; D66 Zoetermeer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/zoetermeer\/themes-or-point-of-view\/point-of-view\/","og_locale":"nl_NL","og_type":"article","og_title":"Point of view Archives &#8212; D66 Zoetermeer","og_url":"https:\/\/d66.nl\/zoetermeer\/themes-or-point-of-view\/point-of-view\/","og_site_name":"D66 Zoetermeer","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/d66.nl\/zoetermeer\/themes-or-point-of-view\/point-of-view\/","url":"https:\/\/d66.nl\/zoetermeer\/themes-or-point-of-view\/point-of-view\/","name":"Point of view Archives &#8212; D66 Zoetermeer","isPartOf":{"@id":"https:\/\/d66.nl\/zoetermeer\/#website"},"breadcrumb":{"@id":"https:\/\/d66.nl\/zoetermeer\/themes-or-point-of-view\/point-of-view\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/zoetermeer\/themes-or-point-of-view\/point-of-view\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/zoetermeer\/"},{"@type":"ListItem","position":2,"name":"Point of view"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/zoetermeer\/#website","url":"https:\/\/d66.nl\/zoetermeer\/","name":"D66 Zoetermeer","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/zoetermeer\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/zoetermeer\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/zoetermeer\/#organization","name":"D66","url":"https:\/\/d66.nl\/zoetermeer\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/zoetermeer\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/zoetermeer\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/zoetermeer\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/zoetermeer\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/zoetermeer\/wp-json\/wp\/v2\/themes-or-point-of-view\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/zoetermeer\/wp-json\/wp\/v2\/themes-or-point-of-view"}],"about":[{"href":"https:\/\/d66.nl\/zoetermeer\/wp-json\/wp\/v2\/taxonomies\/themes-or-point-of-view"}],"wp:post_type":[{"href":"https:\/\/d66.nl\/zoetermeer\/wp-json\/wp\/v2\/pages?themes-or-point-of-view=25"},{"href":"https:\/\/d66.nl\/zoetermeer\/wp-json\/wp\/v2\/verkiezingsprogramma?themes-or-point-of-view=25"},{"href":"https:\/\/d66.nl\/zoetermeer\/wp-json\/wp\/v2\/standpunten?themes-or-point-of-view=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}