{"id":26,"count":12,"description":"","link":"https:\/\/d66.nl\/westerveld\/search-tags\/lokaal\/","name":"Lokaal","slug":"lokaal","taxonomy":"search-tags","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lokaal Archives &#8212; D66 Westerveld<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/westerveld\/search-tags\/lokaal\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lokaal Archives &#8212; D66 Westerveld\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/westerveld\/search-tags\/lokaal\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Westerveld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/search-tags\\\/lokaal\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/search-tags\\\/lokaal\\\/\",\"name\":\"Lokaal Archives &#8212; D66 Westerveld\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/search-tags\\\/lokaal\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/search-tags\\\/lokaal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lokaal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/\",\"name\":\"D66 Westerveld\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/westerveld\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lokaal Archives &#8212; D66 Westerveld","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/westerveld\/search-tags\/lokaal\/","og_locale":"nl_NL","og_type":"article","og_title":"Lokaal Archives &#8212; D66 Westerveld","og_url":"https:\/\/d66.nl\/westerveld\/search-tags\/lokaal\/","og_site_name":"D66 Westerveld","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/d66.nl\/westerveld\/search-tags\/lokaal\/","url":"https:\/\/d66.nl\/westerveld\/search-tags\/lokaal\/","name":"Lokaal Archives &#8212; D66 Westerveld","isPartOf":{"@id":"https:\/\/d66.nl\/westerveld\/#website"},"breadcrumb":{"@id":"https:\/\/d66.nl\/westerveld\/search-tags\/lokaal\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/westerveld\/search-tags\/lokaal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/westerveld\/"},{"@type":"ListItem","position":2,"name":"Lokaal"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/westerveld\/#website","url":"https:\/\/d66.nl\/westerveld\/","name":"D66 Westerveld","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/westerveld\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/westerveld\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/westerveld\/#organization","name":"D66","url":"https:\/\/d66.nl\/westerveld\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/westerveld\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/westerveld\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/westerveld\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/westerveld\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/westerveld\/wp-json\/wp\/v2\/search-tags\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/westerveld\/wp-json\/wp\/v2\/search-tags"}],"about":[{"href":"https:\/\/d66.nl\/westerveld\/wp-json\/wp\/v2\/taxonomies\/search-tags"}],"wp:post_type":[{"href":"https:\/\/d66.nl\/westerveld\/wp-json\/wp\/v2\/posts?search-tags=26"},{"href":"https:\/\/d66.nl\/westerveld\/wp-json\/wp\/v2\/pages?search-tags=26"},{"href":"https:\/\/d66.nl\/westerveld\/wp-json\/wp\/v2\/people-type?search-tags=26"},{"href":"https:\/\/d66.nl\/westerveld\/wp-json\/wp\/v2\/events?search-tags=26"},{"href":"https:\/\/d66.nl\/westerveld\/wp-json\/wp\/v2\/vacatures?search-tags=26"},{"href":"https:\/\/d66.nl\/westerveld\/wp-json\/wp\/v2\/publications?search-tags=26"},{"href":"https:\/\/d66.nl\/westerveld\/wp-json\/wp\/v2\/initiatieven?search-tags=26"},{"href":"https:\/\/d66.nl\/westerveld\/wp-json\/wp\/v2\/verkiezingsprogramma?search-tags=26"},{"href":"https:\/\/d66.nl\/westerveld\/wp-json\/wp\/v2\/standpunten?search-tags=26"},{"href":"https:\/\/d66.nl\/westerveld\/wp-json\/wp\/v2\/liveblog?search-tags=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}