{"id":307,"date":"2021-10-27T12:12:52","date_gmt":"2021-10-27T12:12:52","guid":{"rendered":"https:\/\/d66.nl\/westerkwartier\/?page_id=307"},"modified":"2026-01-21T20:29:14","modified_gmt":"2026-01-21T20:29:14","slug":"zorg-gezondheid-en-sport","status":"publish","type":"topics","link":"https:\/\/d66.nl\/westerkwartier\/standpunten\/zorg-gezondheid-en-sport\/","title":{"rendered":"Natuur \u00e9n boeren, het kan w\u00e9l in Westerkwartier"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--100 wrapper__spacing-bottom-desktop--140 wrapper__spacing-bottom-mobile--110  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--0 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section\n  class=\"block-small-hero\"\n  data-video-url=\"\"\n>\n  <div class=\"block-small-hero__wrapper\">\n\t<div class=\"block-small-hero__heading\">\n\t  <div class=\"block-small-hero__title\">\n\t\t<h1 class=\"heading heading__align--left heading__color--black heading__size--giant  heading__weight--normal\" id=\"nav-introductie5406\" data-nav-heading-mobile=\"Introductie\">\n\t<strong>Natuur \u00e9n boeren, het kan w\u00e9l in Westerkwartier<\/strong><\/h1>\t  <\/div>\n\t  \t<\/div>\n\n\t\n\t\t  <div class=\"block-small-hero__image\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/d66.nl\/westerkwartier\/wp-content\/uploads\/sites\/43\/2022\/01\/grasland-middag-1024x683.jpeg\" class=\"image block-small-hero__img\" alt=\"\" \/>\n\t\t\t<div class=\"image__caption-wrapper block-small-hero__caption-wrapper\">\n\t\t\t<div class=\"image__caption block-small-hero__caption\">\n\t\t\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--small paragraph__weight--medium\">\n\t\tBloemrijk grasland in Middag (Westerkwartier) <i>&#x2022;<\/i> Beeld: Anne de Groot\t<\/p>\t\t\t<\/div>\n\t\t<\/div>\t  <\/div>\n\t\t<div class=\"block-small-hero__columns block-small-hero__columns--one\" data-accordion-active=\"0\">\n\t  <div class=\"block-small-hero__column\">\n\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default\">\n\t\tWesterkwartier heeft een uniek landschap van open en besloten gebieden met houtwallen,<br>voedselhagen, wierden en kleinschalige akkers en weilanden. Deze mix versterkt de biodiversiteit, trekt toeristen aan en geeft het gebied zijn eigen identiteit. Het is goed om te bedenken dat ons cultuurlandschap is ontstaan \u00e9n blijft bestaan met boeren. Zij zorgen daarmee niet alleen voor voedsel, maar ook voor een levend cultuurlandschap.<br><br>Boeren verdienen waardering \u00e9n ruimte om te ondernemen, vernieuwen en verduurzamen,<br>bijvoorbeeld via kleinschalige mestvergisting en natuurbeheer op hun eigen land. D66 Westerkwartier pleit ervoor dat we nog meer doen om een natuurinclusieve en duurzamere landbouw en veeteelt te bevorderen. Dat betekent dat innovatie ervoor moet zorgen dat er minder mest en schadelijke bestrijdingsmiddelen op het land en in het water terechtkomen. Dit houdt ook in dat de ketens van onze voedselproductie korter worden. En dat alles op een manier waardoor landbouw \u00e9n natuur elkaar in de toekomst versterken.<br><br>Samen met onze inwoners willen we scherpe keuzes maken. Waar is meer landbouw mogelijk en waar liever niet? Welke gebieden bieden andere kansen? Zo kunnen gebieden die minder geschikt zijn voor landbouw natter worden gemaakt en zo bijdragen aan natuurontwikkeling, waterberging en de opslag van broeikasgassen. Door samen met boeren te investeren in natuurbeheer en landschapskwaliteit, behouden we wat ons gebied uniek maakt. Wij kiezen voor landbouw \u00e9n natuur.<br><br>Verder zijn wij van mening dat het probleem met PAS-melders en \u2018interimmerspgelost moet worden. Immers, zij zijn slachtoffer geworden van een overheid die in het verleden onbetrouwbaar gehandeld heeft.<br><br><em><strong>Wat wil D66 Westerkwartier?<\/strong><\/em><br>&#8211; Ondersteun boeren die een ander bedrijfsmodel nastreven, met minder mestgebruik, meer<br>   biodiversiteit, aandacht voor het landschap en een beter dierenwelzijn<br>&#8211; Kijk samen met organisaties gericht naar welke activiteiten het beste passen bij een gebied\t<\/p>\t  <\/div>\n\t  \t  \t<\/div>\n  <\/div>\n<\/section>\n\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"author":6,"featured_media":594,"parent":0,"menu_order":0,"template":"with-navigation.php","meta":{"_acf_changed":false},"search-tags":[6],"topic-subtopics":[],"themes-or-point-of-view":[24],"class_list":["post-307","topics","type-topics","status-publish","has-post-thumbnail","hentry","search-tags-zorg-gezondheid-sport","themes-or-point-of-view-theme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D66 Westerkwartier &#8212; Natuur \u00e9n boeren, het kan w\u00e9l in Westerkwartier | Standpunten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/westerkwartier\/standpunten\/zorg-gezondheid-en-sport\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D66 Westerkwartier &#8212; Natuur \u00e9n boeren, het kan w\u00e9l in Westerkwartier | Standpunten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/westerkwartier\/standpunten\/zorg-gezondheid-en-sport\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Westerkwartier\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T20:29:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d66.nl\/westerkwartier\/wp-content\/uploads\/sites\/43\/2022\/01\/grasland-middag-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/\",\"name\":\"D66 Westerkwartier &#8212; Natuur \u00e9n boeren, het kan w\u00e9l in Westerkwartier | Standpunten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/wp-content\\\/uploads\\\/sites\\\/43\\\/2022\\\/01\\\/grasland-middag-scaled.jpeg\",\"datePublished\":\"2021-10-27T12:12:52+00:00\",\"dateModified\":\"2026-01-21T20:29:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/wp-content\\\/uploads\\\/sites\\\/43\\\/2022\\\/01\\\/grasland-middag-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/wp-content\\\/uploads\\\/sites\\\/43\\\/2022\\\/01\\\/grasland-middag-scaled.jpeg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/standpunten\\\/zorg-gezondheid-en-sport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Natuur \u00e9n boeren, het kan w\u00e9l in Westerkwartier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/\",\"name\":\"D66 Westerkwartier\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/westerkwartier\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D66 Westerkwartier &#8212; Natuur \u00e9n boeren, het kan w\u00e9l in Westerkwartier | Standpunten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/westerkwartier\/standpunten\/zorg-gezondheid-en-sport\/","og_locale":"nl_NL","og_type":"article","og_title":"D66 Westerkwartier &#8212; Natuur \u00e9n boeren, het kan w\u00e9l in Westerkwartier | Standpunten","og_url":"https:\/\/d66.nl\/westerkwartier\/standpunten\/zorg-gezondheid-en-sport\/","og_site_name":"D66 Westerkwartier","article_modified_time":"2026-01-21T20:29:14+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/d66.nl\/westerkwartier\/wp-content\/uploads\/sites\/43\/2022\/01\/grasland-middag-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/westerkwartier\/standpunten\/zorg-gezondheid-en-sport\/","url":"https:\/\/d66.nl\/westerkwartier\/standpunten\/zorg-gezondheid-en-sport\/","name":"D66 Westerkwartier &#8212; Natuur \u00e9n boeren, het kan w\u00e9l in Westerkwartier | Standpunten","isPartOf":{"@id":"https:\/\/d66.nl\/westerkwartier\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d66.nl\/westerkwartier\/standpunten\/zorg-gezondheid-en-sport\/#primaryimage"},"image":{"@id":"https:\/\/d66.nl\/westerkwartier\/standpunten\/zorg-gezondheid-en-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/d66.nl\/westerkwartier\/wp-content\/uploads\/sites\/43\/2022\/01\/grasland-middag-scaled.jpeg","datePublished":"2021-10-27T12:12:52+00:00","dateModified":"2026-01-21T20:29:14+00:00","breadcrumb":{"@id":"https:\/\/d66.nl\/westerkwartier\/standpunten\/zorg-gezondheid-en-sport\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/westerkwartier\/standpunten\/zorg-gezondheid-en-sport\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/westerkwartier\/standpunten\/zorg-gezondheid-en-sport\/#primaryimage","url":"https:\/\/d66.nl\/westerkwartier\/wp-content\/uploads\/sites\/43\/2022\/01\/grasland-middag-scaled.jpeg","contentUrl":"https:\/\/d66.nl\/westerkwartier\/wp-content\/uploads\/sites\/43\/2022\/01\/grasland-middag-scaled.jpeg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/westerkwartier\/standpunten\/zorg-gezondheid-en-sport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/westerkwartier\/"},{"@type":"ListItem","position":2,"name":"Natuur \u00e9n boeren, het kan w\u00e9l in Westerkwartier"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/westerkwartier\/#website","url":"https:\/\/d66.nl\/westerkwartier\/","name":"D66 Westerkwartier","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/westerkwartier\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/westerkwartier\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/westerkwartier\/#organization","name":"D66","url":"https:\/\/d66.nl\/westerkwartier\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/westerkwartier\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/westerkwartier\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/westerkwartier\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/westerkwartier\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/westerkwartier\/wp-json\/wp\/v2\/standpunten\/307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/westerkwartier\/wp-json\/wp\/v2\/standpunten"}],"about":[{"href":"https:\/\/d66.nl\/westerkwartier\/wp-json\/wp\/v2\/types\/topics"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/westerkwartier\/wp-json\/wp\/v2\/users\/6"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d66.nl\/westerkwartier\/wp-json\/wp\/v2\/media\/594"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/westerkwartier\/wp-json\/wp\/v2\/media?parent=307"}],"wp:term":[{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/westerkwartier\/wp-json\/wp\/v2\/search-tags?post=307"},{"taxonomy":"topic-sub-topics","embeddable":true,"href":"https:\/\/d66.nl\/westerkwartier\/wp-json\/wp\/v2\/topic-subtopics?post=307"},{"taxonomy":"themes-or-point-of-view","embeddable":true,"href":"https:\/\/d66.nl\/westerkwartier\/wp-json\/wp\/v2\/themes-or-point-of-view?post=307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}