{"id":6,"count":14,"description":"","link":"https:\/\/d66.nl\/waalre\/search-tags\/wonen-in-waalre\/","name":"Wonen in Waalre","slug":"wonen-in-waalre","taxonomy":"search-tags","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wonen in Waalre Archives &#8212; D66 Waalre<\/title>\n<meta name=\"description\" content=\"Hier vind u een overzicht van alle onderwerpen en artikelen van D66 Waalre gerelateerd aan zorg, gezondheid en welzijn in Waalre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/waalre\/search-tags\/wonen-in-waalre\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wonen in Waalre Archives &#8212; D66 Waalre\" \/>\n<meta property=\"og:description\" content=\"Hier vind u een overzicht van alle onderwerpen en artikelen van D66 Waalre gerelateerd aan zorg, gezondheid en welzijn in Waalre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/waalre\/search-tags\/wonen-in-waalre\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Waalre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/search-tags\\\/wonen-in-waalre\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/search-tags\\\/wonen-in-waalre\\\/\",\"name\":\"Wonen in Waalre Archives &#8212; D66 Waalre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/#website\"},\"description\":\"Hier vind u een overzicht van alle onderwerpen en artikelen van D66 Waalre gerelateerd aan zorg, gezondheid en welzijn in Waalre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/search-tags\\\/wonen-in-waalre\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/search-tags\\\/wonen-in-waalre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wonen in Waalre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/\",\"name\":\"D66 Waalre\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/waalre\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wonen in Waalre Archives &#8212; D66 Waalre","description":"Hier vind u een overzicht van alle onderwerpen en artikelen van D66 Waalre gerelateerd aan zorg, gezondheid en welzijn in Waalre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/waalre\/search-tags\/wonen-in-waalre\/","og_locale":"nl_NL","og_type":"article","og_title":"Wonen in Waalre Archives &#8212; D66 Waalre","og_description":"Hier vind u een overzicht van alle onderwerpen en artikelen van D66 Waalre gerelateerd aan zorg, gezondheid en welzijn in Waalre.","og_url":"https:\/\/d66.nl\/waalre\/search-tags\/wonen-in-waalre\/","og_site_name":"D66 Waalre","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/d66.nl\/waalre\/search-tags\/wonen-in-waalre\/","url":"https:\/\/d66.nl\/waalre\/search-tags\/wonen-in-waalre\/","name":"Wonen in Waalre Archives &#8212; D66 Waalre","isPartOf":{"@id":"https:\/\/d66.nl\/waalre\/#website"},"description":"Hier vind u een overzicht van alle onderwerpen en artikelen van D66 Waalre gerelateerd aan zorg, gezondheid en welzijn in Waalre.","breadcrumb":{"@id":"https:\/\/d66.nl\/waalre\/search-tags\/wonen-in-waalre\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/waalre\/search-tags\/wonen-in-waalre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/waalre\/"},{"@type":"ListItem","position":2,"name":"Wonen in Waalre"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/waalre\/#website","url":"https:\/\/d66.nl\/waalre\/","name":"D66 Waalre","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/waalre\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/waalre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/waalre\/#organization","name":"D66","url":"https:\/\/d66.nl\/waalre\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/waalre\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/waalre\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/waalre\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/waalre\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/waalre\/wp-json\/wp\/v2\/search-tags\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/waalre\/wp-json\/wp\/v2\/search-tags"}],"about":[{"href":"https:\/\/d66.nl\/waalre\/wp-json\/wp\/v2\/taxonomies\/search-tags"}],"wp:post_type":[{"href":"https:\/\/d66.nl\/waalre\/wp-json\/wp\/v2\/posts?search-tags=6"},{"href":"https:\/\/d66.nl\/waalre\/wp-json\/wp\/v2\/pages?search-tags=6"},{"href":"https:\/\/d66.nl\/waalre\/wp-json\/wp\/v2\/people-type?search-tags=6"},{"href":"https:\/\/d66.nl\/waalre\/wp-json\/wp\/v2\/events?search-tags=6"},{"href":"https:\/\/d66.nl\/waalre\/wp-json\/wp\/v2\/vacatures?search-tags=6"},{"href":"https:\/\/d66.nl\/waalre\/wp-json\/wp\/v2\/publications?search-tags=6"},{"href":"https:\/\/d66.nl\/waalre\/wp-json\/wp\/v2\/initiatieven?search-tags=6"},{"href":"https:\/\/d66.nl\/waalre\/wp-json\/wp\/v2\/verkiezingsprogramma?search-tags=6"},{"href":"https:\/\/d66.nl\/waalre\/wp-json\/wp\/v2\/standpunten?search-tags=6"},{"href":"https:\/\/d66.nl\/waalre\/wp-json\/wp\/v2\/liveblog?search-tags=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}