{"id":1746,"date":"2025-10-10T12:59:37","date_gmt":"2025-10-10T12:59:37","guid":{"rendered":"https:\/\/d66.nl\/vught\/nieuws\/"},"modified":"2025-12-12T01:35:28","modified_gmt":"2025-12-12T01:35:28","slug":"d66-verhoogt-duurzaamheidsambitie-vught","status":"publish","type":"post","link":"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught","title":{"rendered":"D66 verhoogt ambitie op duurzaamheid in Vught"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--66 wrapper__spacing-bottom-mobile--76  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading   heading__size--giant heading__font--serif heading__weight--regular  block-heading__heading\" id=\"nav--strong-d66-verhoogt-duurzaamheidsambitie-vught--strong-7995\"  data-nav-heading-mobile=\"D66 verhoogt duurzaamheidsambitie Vught\" >\n\t<strong>D66 verhoogt duurzaamheidsambitie Vught<\/strong><\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-mobile--40  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--13 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<p\n\t\tclass=\"paragraph   paragraph__size--big   block-paragraph__paragraph\"\n\t\t\t>\n\t\tTijdens de raadsvergadering van 9 oktober 2025 heeft D66 samen met de fracties van PvdA-GL, SP en PLV twee amendementen ingediend om gemeentelijke gebouwen alsnog te verduurzamen. Het betrof het buurthuis aan de Astorias in het voormalig woonoord Lunetten en de kinderopvang Partou aan de Theresialaan. Het college stelde voor deze gebouwen niet of maar beperkt te verduurzamen hoewel deze wel op de planning stonden. Het gebouw aan de Astorias zal nu alsnog w\u00e9l worden verduurzaamd. \t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20 wrapper__spacing-bottom-mobile--10  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--24 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-related-post-metadata js-block-related-post-metadata\">\n\t<div class=\"block-related-post-metadata__content-wrapper\">\n\t\t<div class=\"block-related-post-metadata__persons\">\n\t\t\t\t\t<\/div>\n\t\t<div class=\"block-related-post-metadata__meta\">\n\t\t\t<div class=\"block-related-post-metadata__date\">\n\t\t\t\t10.10.2025<div class=\"post-share js-post-share rs_skip_always\">\n\t<button class=\"post-share__share-button js-post-share-share-button\">\n\t\tShare\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='100px' height='100px' viewBox='0 0 24 24' fill='none'><path d='m8.684 10.658 6.629-3.314m.003 9.314-6.622-3.311M21 6a3 3 0 1 1-6 0 3 3 0 0 1 6 0ZM9 12a3 3 0 1 1-6 0 3 3 0 0 1 6 0Zm12 6a3 3 0 1 1-6 0 3 3 0 0 1 6 0Z' stroke='currentColor' stroke-width='1.5' fill='none'\/><\/svg>\t<\/button>\n\t<dialog class=\"post-share__dialog js-post-share-dialog\" aria-hidden=\"true\">\n\t\t<div class=\"post-share__dialog-header\">\n\t\t\tShare this post\t\t\t<button class=\"post-share__dialog-close js-post-share-dialog-close\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='150' height='150' viewBox='0 0 150 150' fill='none'><path d='M44.103 105.897 75 75m30.898-30.898L75 75m0 0L44.103 44.102M75 75l30.898 30.897' stroke='currentColor' stroke-width='5' fill='none'\/><\/svg>\t\t\t<\/button>\n\t\t<\/div>\n\t\t<div class=\"post-share__dialog-socials\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"#\" target=\"_blank\" data-copy=&quot;true&quot;>\n\t\t\t\t\tKopier link<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='150' height='150' viewBox='0 0 150 150' fill='none'><path d='M67.468 108.679c-8.533-.512-14.164-3.583-17.407-9.983-3.242-6.314-2.815-12.713 1.195-18.6 1.706-2.56 3.584-5.035 5.46-7.594 1.537-2.048 3.584-2.475 5.462-1.195 2.047 1.45 2.389 3.498.938 5.632-1.706 2.474-3.584 4.948-5.29 7.423-3.242 4.778-2.304 11.092 2.133 14.334 4.864 3.584 11.092 2.731 14.761-1.962 1.963-2.475 3.754-5.12 5.632-7.68 1.194-1.535 2.645-2.218 4.607-1.28 1.792.854 2.645 2.39 2.304 4.267 0 .17 0 .427-.17.597-3.67 5.12-6.4 11.178-12.544 13.993-2.56 1.195-5.46 1.707-6.996 2.219l-.085-.171Z' fill='currentColor'\/><path d='M86.921 44.6c6.144.257 11.605 3.328 14.932 9.728 3.328 6.399 2.816 12.798-1.109 18.856-1.621 2.56-3.498 4.95-5.29 7.424-1.707 2.303-3.754 2.815-5.717 1.45-2.048-1.45-2.304-3.669-.597-6.058 1.621-2.304 3.328-4.608 4.949-6.911 3.498-4.95 2.56-11.348-2.133-14.761-4.779-3.499-11.178-2.475-14.847 2.56-1.792 2.388-3.498 4.863-5.205 7.252-1.62 2.218-3.583 2.56-5.546 1.11-1.877-1.366-2.218-3.414-.768-5.462 2.048-2.986 4.01-5.972 6.314-8.703 3.67-4.351 8.448-6.399 15.103-6.399l-.086-.085Z' fill='currentColor'\/><path d='M71.478 88.457c-3.498-.341-5.46-3.413-3.754-6.143 3.327-5.29 6.825-10.495 10.324-15.7 1.45-2.133 3.413-2.389 5.46-1.109 1.878 1.28 2.219 3.413.854 5.546-3.328 5.034-6.57 9.983-9.983 14.932-.683 1.024-1.963 1.621-2.901 2.389v.085Z' fill='currentColor'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"mailto:?to=%20&amp;body=https%3A%2F%2Fd66.nl%2Fvught%2Fnieuws%2Fd66-verhoogt-duurzaamheidsambitie-vught\" target=\"_blank\" >\n\t\t\t\t\tMail<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fd66.nl%2Fvught%2Fnieuws%2Fd66-verhoogt-duurzaamheidsambitie-vught\" target=\"_blank\" >\n\t\t\t\t\tLinkedIn<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fd66.nl%2Fvught%2Fnieuws%2Fd66-verhoogt-duurzaamheidsambitie-vught\" target=\"_blank\" >\n\t\t\t\t\tFacebook<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"whatsapp:\/\/send?text=https%3A%2F%2Fd66.nl%2Fvught%2Fnieuws%2Fd66-verhoogt-duurzaamheidsambitie-vught\" target=\"_blank\" >\n\t\t\t\t\tWhatsApp<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"https:\/\/x.com\/intent\/post?url=https%3A%2F%2Fd66.nl%2Fvught%2Fnieuws%2Fd66-verhoogt-duurzaamheidsambitie-vught\" target=\"_blank\" >\n\t\t\t\t\tTwitter (X)<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/dialog>\n<\/div>\t\t\t<\/div>\n\t\t\t<div class=\"block-related-post-metadata__categories\">\n\t\t\t\t<div class=\"category-link__wrapper\">\n\t\t\t<div class=\"category-link__item\">\n\t\t\t<a href=\"https:\/\/d66.nl\/vught\/category\/d66\/\">\n\t\t\t\tD66 Vught\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--bold  block-post-content__heading\" id=\"nav-voorhoede6006\" data-nav-heading-mobile=\"Voorhoede\">\n\tVoorhoede<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tIn 2024 heeft het college van de gemeente Vught eindelijk de eerste stappen gezet in het verduurzamen van gemeentelijke gebouwen. Elk jaar worden vier gebouwen aangepakt. In een eerste ronde is ervaring opgedaan met het aanpakken van gebouwen aan de Ketting en de Lidwinastraat. In deze ronde stonden de kinderopvang Partou (Theresialaan), de Martinihal, de brandweerkazerne en het buurthuis Lunetten op de planning. <br><br>In het voorstel van het college van B&amp;W werd gekozen voor uitstel bij de brandweerkazerne, alleen de meest economisch rendabele aanpassingen aan de kinderopvang Theresialaan en de Martinihal, en g\u00e9\u00e9n verduurzaming bij het buurthuis Lunetten. <br><br>Uiteindelijk moeten alle gemeentelijke gebouwen onder de loep worden genomen. Hiervoor is een reserve gevormd van 1 miljoen euro. Hiermee wil de gemeente in de voorhoede opereren, zodat ook particulieren en bedrijven sneller overgaan tot verduurzaming van gebouwen als dit nog niet is gebeurd.\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--bold  block-post-content__heading\" id=\"nav-vage-doelstellingen2659\" data-nav-heading-mobile=\"Vage doelstellingen\">\n\tVage doelstellingen<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tEchter, volgens D66 blijkt hieruit ook een vage doelstelling van het college. Hierin staat dat het college Nul-op-de-Meter (NOM) wil realiseren voor zowel gas als elektra bij alle gemeentelijke gebouwen. Het feit dat dit voor geen van de gebouwen nu gebeurt, laat zien dat de doelstelling van het college moet worden aangepast. &#8220;D66 staat voor eerlijk bestuur en verzoekt het college dan ook duidelijk te zijn in haar ambities&#8221; aldus raadslid Pieter van de Meerakker. &#8220;Bij verduurzaming lijkt nu alleen de vraag of het economisch rendabel is belangrijk, en niet welke impact verduurzaming kan hebben op Vught als geheel. Terwijl dit ook een van de uitgangspunten is.&#8221;\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<div class=\"image__caption-wrapper block-image__caption-wrapper\">\n\t\t\t<div class=\"image__caption block-image__caption\">\n\t\t\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--small paragraph__weight--medium\">\n\t\t<span style=\"color: red\">LET OP: auteursrechten ontbreken<\/span>. <a href=\"https:\/\/d66.nl\/vught\/wp-admin\/upload.php?item=1745\">S.v.p. de auteursrechten invullen voor deze afbeelding<\/a> before using it.\t<\/p>\t\t\t<\/div>\n\t\t<\/div>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--bold  block-post-content__heading\" id=\"nav-ambitie-omhoog7369\" data-nav-heading-mobile=\"Ambitie omhoog\">\n\tAmbitie omhoog<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tVoor D66 was dit reden om het voorstel te amenderen en de ambitie te verhogen. Het voorstel om bij kinderopvang Partou Theresialaan te kiezen voor NOM voor zowel elektra als gas werd door de coalitie van Gemeentebelangen (GB), VVD en CDA niet gesteund en weggestemd. Het voorstel om het buurthuis Lunetten elektrisch zelfvoorzienend te maken, haalde w\u00e9l een meerderheid door steun van de indieners van het amendement en het CDA. Deze verhoogde ambitie bleek voor GB en VVD te hoog, waarna zij tegen het aangepaste voorstel van hun eigen college stemden &#8211; dus in feite geen enkel gebouw meer wilden verduurzamen.<br><br>D66 zal zich blijven inzetten voor verhoogde ambities en versnelling op dit thema en voor de gebouwen die nog op de planning staan. Van de Meerakker: &#8220;De gemeente vervult een belangrijke voorbeeldfunctie op dit gebied, maar heeft tot nu toe te weinig laten zien. NOM moet het uitgangspunt zijn en blijven; niet alleen een economische afweging kan tot een besluit leiden. De acht gebouwen die de gemeente nog moet verduurzamen, zullen wat D66 betreft dan ook volgens dat principe worden aangepakt \u2014 waarbij snelheid vereist is.&#8221;\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--bold  block-post-content__heading\" id=\"nav-4704\" data-nav-heading-mobile=\"\">\n\t<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t\t<div class=\"block-lists  block-lists__color--black\">\n\t\t<p class=\"paragraph  paragraph__color--black paragraph__size--default\">\n\t\t\t<\/p><ul class=\"block-lists lists__lists lists__weight--medium lists__color--black lists__type--default\">\n\t<li><a href=\"https:\/\/vught.bestuurlijkeinformatie.nl\/Agenda\/Index\/b7d19bad-6f28-4038-9b6e-839e0a74641d\">Link<\/a> naar raadsvergadering 9-10-2025<\/li><\/ul>\t<\/div>\n\t\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1317,"featured_media":2076,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"search-tags":[],"labels":[],"class_list":["post-1746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-d66"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D66 Vught &#8212; D66 verhoogt ambitie op duurzaamheid in Vught<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D66 Vught &#8212; D66 verhoogt ambitie op duurzaamheid in Vught\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Vught\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-10T12:59:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-12T01:35:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d66.nl\/vught\/wp-content\/uploads\/sites\/66\/2025\/12\/IMG_6768-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"dion-meuwissen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"dion-meuwissen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/nieuws\\\/d66-verhoogt-duurzaamheidsambitie-vught\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/nieuws\\\/d66-verhoogt-duurzaamheidsambitie-vught\\\/\"},\"author\":{\"name\":\"dion-meuwissen\",\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/#\\\/schema\\\/person\\\/690a74c958b1b82549559331f6ed4cd1\"},\"headline\":\"D66 verhoogt ambitie op duurzaamheid in Vught\",\"datePublished\":\"2025-10-10T12:59:37+00:00\",\"dateModified\":\"2025-12-12T01:35:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/nieuws\\\/d66-verhoogt-duurzaamheidsambitie-vught\\\/\"},\"wordCount\":7,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/nieuws\\\/d66-verhoogt-duurzaamheidsambitie-vught\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d66.nl\\\/vught\\\/wp-content\\\/uploads\\\/sites\\\/66\\\/2025\\\/12\\\/IMG_6768-scaled.jpg\",\"articleSection\":[\"D66 Vught\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/d66.nl\\\/vught\\\/nieuws\\\/d66-verhoogt-duurzaamheidsambitie-vught\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/nieuws\\\/d66-verhoogt-duurzaamheidsambitie-vught\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/vught\\\/nieuws\\\/d66-verhoogt-duurzaamheidsambitie-vught\\\/\",\"name\":\"D66 Vught &#8212; D66 verhoogt ambitie op duurzaamheid in Vught\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/nieuws\\\/d66-verhoogt-duurzaamheidsambitie-vught\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/nieuws\\\/d66-verhoogt-duurzaamheidsambitie-vught\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d66.nl\\\/vught\\\/wp-content\\\/uploads\\\/sites\\\/66\\\/2025\\\/12\\\/IMG_6768-scaled.jpg\",\"datePublished\":\"2025-10-10T12:59:37+00:00\",\"dateModified\":\"2025-12-12T01:35:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/nieuws\\\/d66-verhoogt-duurzaamheidsambitie-vught\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/vught\\\/nieuws\\\/d66-verhoogt-duurzaamheidsambitie-vught\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/nieuws\\\/d66-verhoogt-duurzaamheidsambitie-vught\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d66.nl\\\/vught\\\/wp-content\\\/uploads\\\/sites\\\/66\\\/2025\\\/12\\\/IMG_6768-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/vught\\\/wp-content\\\/uploads\\\/sites\\\/66\\\/2025\\\/12\\\/IMG_6768-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/nieuws\\\/d66-verhoogt-duurzaamheidsambitie-vught\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/vught\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nieuws\",\"item\":\"https:\\\/\\\/d66.nl\\\/vught\\\/nieuws\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D66 verhoogt ambitie op duurzaamheid in Vught\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/vught\\\/\",\"name\":\"D66 Vught\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/vught\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/vught\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/vught\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/vught\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/d66.nl\\\/vught\\\/#\\\/schema\\\/person\\\/690a74c958b1b82549559331f6ed4cd1\",\"name\":\"dion-meuwissen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/250754865a54803dc3e5b0df05da2f3bca368da577058391b22d583fed9e609e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/250754865a54803dc3e5b0df05da2f3bca368da577058391b22d583fed9e609e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/250754865a54803dc3e5b0df05da2f3bca368da577058391b22d583fed9e609e?s=96&d=mm&r=g\",\"caption\":\"dion-meuwissen\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D66 Vught &#8212; D66 verhoogt ambitie op duurzaamheid in Vught","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught","og_locale":"nl_NL","og_type":"article","og_title":"D66 Vught &#8212; D66 verhoogt ambitie op duurzaamheid in Vught","og_url":"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/","og_site_name":"D66 Vught","article_published_time":"2025-10-10T12:59:37+00:00","article_modified_time":"2025-12-12T01:35:28+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/d66.nl\/vught\/wp-content\/uploads\/sites\/66\/2025\/12\/IMG_6768-scaled.jpg","type":"image\/jpeg"}],"author":"dion-meuwissen","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"dion-meuwissen","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/#article","isPartOf":{"@id":"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/"},"author":{"name":"dion-meuwissen","@id":"https:\/\/d66.nl\/vught\/#\/schema\/person\/690a74c958b1b82549559331f6ed4cd1"},"headline":"D66 verhoogt ambitie op duurzaamheid in Vught","datePublished":"2025-10-10T12:59:37+00:00","dateModified":"2025-12-12T01:35:28+00:00","mainEntityOfPage":{"@id":"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/"},"wordCount":7,"commentCount":0,"publisher":{"@id":"https:\/\/d66.nl\/vught\/#organization"},"image":{"@id":"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/#primaryimage"},"thumbnailUrl":"https:\/\/d66.nl\/vught\/wp-content\/uploads\/sites\/66\/2025\/12\/IMG_6768-scaled.jpg","articleSection":["D66 Vught"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/","url":"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/","name":"D66 Vught &#8212; D66 verhoogt ambitie op duurzaamheid in Vught","isPartOf":{"@id":"https:\/\/d66.nl\/vught\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/#primaryimage"},"image":{"@id":"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/#primaryimage"},"thumbnailUrl":"https:\/\/d66.nl\/vught\/wp-content\/uploads\/sites\/66\/2025\/12\/IMG_6768-scaled.jpg","datePublished":"2025-10-10T12:59:37+00:00","dateModified":"2025-12-12T01:35:28+00:00","breadcrumb":{"@id":"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/#primaryimage","url":"https:\/\/d66.nl\/vught\/wp-content\/uploads\/sites\/66\/2025\/12\/IMG_6768-scaled.jpg","contentUrl":"https:\/\/d66.nl\/vught\/wp-content\/uploads\/sites\/66\/2025\/12\/IMG_6768-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/vught\/nieuws\/d66-verhoogt-duurzaamheidsambitie-vught\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/vught\/"},{"@type":"ListItem","position":2,"name":"Nieuws","item":"https:\/\/d66.nl\/vught\/nieuws\/"},{"@type":"ListItem","position":3,"name":"D66 verhoogt ambitie op duurzaamheid in Vught"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/vught\/#website","url":"https:\/\/d66.nl\/vught\/","name":"D66 Vught","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/vught\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/vught\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/vught\/#organization","name":"D66","url":"https:\/\/d66.nl\/vught\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/vught\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/vught\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/vught\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/vught\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/d66.nl\/vught\/#\/schema\/person\/690a74c958b1b82549559331f6ed4cd1","name":"dion-meuwissen","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/250754865a54803dc3e5b0df05da2f3bca368da577058391b22d583fed9e609e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/250754865a54803dc3e5b0df05da2f3bca368da577058391b22d583fed9e609e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/250754865a54803dc3e5b0df05da2f3bca368da577058391b22d583fed9e609e?s=96&d=mm&r=g","caption":"dion-meuwissen"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/vught\/wp-json\/wp\/v2\/posts\/1746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/vught\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/d66.nl\/vught\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/vught\/wp-json\/wp\/v2\/users\/1317"}],"replies":[{"embeddable":true,"href":"https:\/\/d66.nl\/vught\/wp-json\/wp\/v2\/comments?post=1746"}],"version-history":[{"count":10,"href":"https:\/\/d66.nl\/vught\/wp-json\/wp\/v2\/posts\/1746\/revisions"}],"predecessor-version":[{"id":2160,"href":"https:\/\/d66.nl\/vught\/wp-json\/wp\/v2\/posts\/1746\/revisions\/2160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d66.nl\/vught\/wp-json\/wp\/v2\/media\/2076"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/vught\/wp-json\/wp\/v2\/media?parent=1746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/d66.nl\/vught\/wp-json\/wp\/v2\/categories?post=1746"},{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/vught\/wp-json\/wp\/v2\/search-tags?post=1746"},{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/vught\/wp-json\/wp\/v2\/labels?post=1746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}