{"id":74,"count":1,"description":"","link":"https:\/\/d66.nl\/venray\/search-tags\/cultuur\/laagdrempeling-en-financieel-bereikbaar\/","name":"Laagdrempeling en financieel bereikbaar","slug":"laagdrempeling-en-financieel-bereikbaar","taxonomy":"search-tags","parent":72,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Laagdrempeling en financieel bereikbaar Archives &#8212; D66 Venray<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/venray\/search-tags\/cultuur\/laagdrempeling-en-financieel-bereikbaar\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laagdrempeling en financieel bereikbaar Archives &#8212; D66 Venray\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/venray\/search-tags\/cultuur\/laagdrempeling-en-financieel-bereikbaar\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Venray\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/venray\\\/search-tags\\\/cultuur\\\/laagdrempeling-en-financieel-bereikbaar\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/venray\\\/search-tags\\\/cultuur\\\/laagdrempeling-en-financieel-bereikbaar\\\/\",\"name\":\"Laagdrempeling en financieel bereikbaar Archives &#8212; D66 Venray\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/venray\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/venray\\\/search-tags\\\/cultuur\\\/laagdrempeling-en-financieel-bereikbaar\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/venray\\\/search-tags\\\/cultuur\\\/laagdrempeling-en-financieel-bereikbaar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/venray\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultuur\",\"item\":\"https:\\\/\\\/d66.nl\\\/venray\\\/search-tags\\\/cultuur\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Laagdrempeling en financieel bereikbaar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/venray\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/venray\\\/\",\"name\":\"D66 Venray\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/venray\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/venray\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/venray\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/venray\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/venray\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/venray\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/venray\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/venray\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laagdrempeling en financieel bereikbaar Archives &#8212; D66 Venray","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/venray\/search-tags\/cultuur\/laagdrempeling-en-financieel-bereikbaar\/","og_locale":"nl_NL","og_type":"article","og_title":"Laagdrempeling en financieel bereikbaar Archives &#8212; D66 Venray","og_url":"https:\/\/d66.nl\/venray\/search-tags\/cultuur\/laagdrempeling-en-financieel-bereikbaar\/","og_site_name":"D66 Venray","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/d66.nl\/venray\/search-tags\/cultuur\/laagdrempeling-en-financieel-bereikbaar\/","url":"https:\/\/d66.nl\/venray\/search-tags\/cultuur\/laagdrempeling-en-financieel-bereikbaar\/","name":"Laagdrempeling en financieel bereikbaar Archives &#8212; D66 Venray","isPartOf":{"@id":"https:\/\/d66.nl\/venray\/#website"},"breadcrumb":{"@id":"https:\/\/d66.nl\/venray\/search-tags\/cultuur\/laagdrempeling-en-financieel-bereikbaar\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/venray\/search-tags\/cultuur\/laagdrempeling-en-financieel-bereikbaar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/venray\/"},{"@type":"ListItem","position":2,"name":"Cultuur","item":"https:\/\/d66.nl\/venray\/search-tags\/cultuur\/"},{"@type":"ListItem","position":3,"name":"Laagdrempeling en financieel bereikbaar"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/venray\/#website","url":"https:\/\/d66.nl\/venray\/","name":"D66 Venray","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/venray\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/venray\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/venray\/#organization","name":"D66","url":"https:\/\/d66.nl\/venray\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/venray\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/venray\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/venray\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/venray\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/venray\/wp-json\/wp\/v2\/search-tags\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/venray\/wp-json\/wp\/v2\/search-tags"}],"about":[{"href":"https:\/\/d66.nl\/venray\/wp-json\/wp\/v2\/taxonomies\/search-tags"}],"up":[{"embeddable":true,"href":"https:\/\/d66.nl\/venray\/wp-json\/wp\/v2\/search-tags\/72"}],"wp:post_type":[{"href":"https:\/\/d66.nl\/venray\/wp-json\/wp\/v2\/posts?search-tags=74"},{"href":"https:\/\/d66.nl\/venray\/wp-json\/wp\/v2\/pages?search-tags=74"},{"href":"https:\/\/d66.nl\/venray\/wp-json\/wp\/v2\/people-type?search-tags=74"},{"href":"https:\/\/d66.nl\/venray\/wp-json\/wp\/v2\/events?search-tags=74"},{"href":"https:\/\/d66.nl\/venray\/wp-json\/wp\/v2\/vacatures?search-tags=74"},{"href":"https:\/\/d66.nl\/venray\/wp-json\/wp\/v2\/publications?search-tags=74"},{"href":"https:\/\/d66.nl\/venray\/wp-json\/wp\/v2\/initiatieven?search-tags=74"},{"href":"https:\/\/d66.nl\/venray\/wp-json\/wp\/v2\/verkiezingsprogramma?search-tags=74"},{"href":"https:\/\/d66.nl\/venray\/wp-json\/wp\/v2\/standpunten?search-tags=74"},{"href":"https:\/\/d66.nl\/venray\/wp-json\/wp\/v2\/liveblog?search-tags=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}