{"id":2340,"date":"2023-04-20T15:10:25","date_gmt":"2023-04-20T15:10:25","guid":{"rendered":"https:\/\/d66.nl\/utrecht\/nieuws\/"},"modified":"2023-04-20T15:10:26","modified_gmt":"2023-04-20T15:10:26","slug":"verplicht-openbare-scholen-niet-tot-gebedsruimtes","status":"publish","type":"post","link":"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes","title":{"rendered":"Verplicht openbare scholen niet tot gebedsruimtes"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--66 wrapper__spacing-bottom-mobile--76  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading   heading__size--giant heading__font--serif heading__weight--regular  block-heading__heading\" id=\"nav-verplicht-openbare-scholen-niet-tot-gebedsruimtes579\"  data-nav-heading-mobile=\"Verplicht openbare scholen niet tot gebedsruimtes\" >\n\tVerplicht openbare scholen niet tot gebedsruimtes<\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-mobile--40  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--13 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<p\n\t\tclass=\"paragraph   paragraph__size--big   block-paragraph__paragraph\"\n\t\t\t>\n\t\t<strong>Vandaag wordt er in de gemeenteraad gesproken over gebedsruimtes op <a>openbare<\/a> scholen. D66 Raadslid Berdien van der Wilt: \u201cIn Nederland moet je altijd en overal jezelf kunnen zijn. Ook op school. Bidden moet altijd kunnen, maar wat D66 betreft past een gebedsruimte voor \u00e9\u00e9n geloof niet bij het karakter van een openbare school. Een stilteruimte, waar alle leerlingen gebruik van kunnen maken, ongeacht hun overtuiging of geloof, is een betere oplossing.\u201d<\/strong>\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20 wrapper__spacing-bottom-mobile--10  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--24 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-related-post-metadata js-block-related-post-metadata\">\n\t<div class=\"block-related-post-metadata__content-wrapper\">\n\t\t<div class=\"block-related-post-metadata__persons\">\n\t\t\t<div class=\"related-person-info__wrapper\">\n\t\t\t<div class=\"related-person-info__item related-person-info__color--rosePink\">\n\t\t\t<a class=\"related-person-info__link\" href=\"https:\/\/d66.nl\/utrecht\/?post_type=people-type&#038;p=535\">\n\t\t\t\t<div class=\"related-person-info__image_container\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/d66.nl\/utrecht\/wp-content\/uploads\/sites\/85\/2022\/01\/5.-Berdien-Van-Der-Wilt-150x150.jpg\" class=\"related-person-info__image\" alt=\"\" \/>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"related-person-info__meta\">\n\t\t\t\t\t\t\t\t\t<header class=\"related-person-info__header\">\n\t\t\t\t\t\t<h3 class=\"heading   heading__size--small heading__font--sans heading__weight--bold\" id=\"nav-berdien-van-der-wilt1097\">\n\tBerdien van der Wilt<\/h3>\t\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"related-person-info__description\">\n\t\t\t\t\t\t<p class=\"paragraph   paragraph__size--small paragraph__weight--normal\">\n\t\tVicefractievoorzitter\t<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\t\t<\/div>\n\t\t<div class=\"block-related-post-metadata__meta\">\n\t\t\t<div class=\"block-related-post-metadata__date\">\n\t\t\t\t20.04.2023<div class=\"post-share js-post-share rs_skip_always\">\n\t<button class=\"post-share__share-button js-post-share-share-button\">\n\t\tShare\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='100px' height='100px' viewBox='0 0 24 24' fill='none'><path d='m8.684 10.658 6.629-3.314m.003 9.314-6.622-3.311M21 6a3 3 0 1 1-6 0 3 3 0 0 1 6 0ZM9 12a3 3 0 1 1-6 0 3 3 0 0 1 6 0Zm12 6a3 3 0 1 1-6 0 3 3 0 0 1 6 0Z' stroke='currentColor' stroke-width='1.5' fill='none'\/><\/svg>\t<\/button>\n\t<dialog class=\"post-share__dialog js-post-share-dialog\" aria-hidden=\"true\">\n\t\t<div class=\"post-share__dialog-header\">\n\t\t\tShare this post\t\t\t<button class=\"post-share__dialog-close js-post-share-dialog-close\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='150' height='150' viewBox='0 0 150 150' fill='none'><path d='M44.103 105.897 75 75m30.898-30.898L75 75m0 0L44.103 44.102M75 75l30.898 30.897' stroke='currentColor' stroke-width='5' fill='none'\/><\/svg>\t\t\t<\/button>\n\t\t<\/div>\n\t\t<div class=\"post-share__dialog-socials\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"#\" target=\"_blank\" data-copy=&quot;true&quot;>\n\t\t\t\t\tKopier link<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='150' height='150' viewBox='0 0 150 150' fill='none'><path d='M67.468 108.679c-8.533-.512-14.164-3.583-17.407-9.983-3.242-6.314-2.815-12.713 1.195-18.6 1.706-2.56 3.584-5.035 5.46-7.594 1.537-2.048 3.584-2.475 5.462-1.195 2.047 1.45 2.389 3.498.938 5.632-1.706 2.474-3.584 4.948-5.29 7.423-3.242 4.778-2.304 11.092 2.133 14.334 4.864 3.584 11.092 2.731 14.761-1.962 1.963-2.475 3.754-5.12 5.632-7.68 1.194-1.535 2.645-2.218 4.607-1.28 1.792.854 2.645 2.39 2.304 4.267 0 .17 0 .427-.17.597-3.67 5.12-6.4 11.178-12.544 13.993-2.56 1.195-5.46 1.707-6.996 2.219l-.085-.171Z' fill='currentColor'\/><path d='M86.921 44.6c6.144.257 11.605 3.328 14.932 9.728 3.328 6.399 2.816 12.798-1.109 18.856-1.621 2.56-3.498 4.95-5.29 7.424-1.707 2.303-3.754 2.815-5.717 1.45-2.048-1.45-2.304-3.669-.597-6.058 1.621-2.304 3.328-4.608 4.949-6.911 3.498-4.95 2.56-11.348-2.133-14.761-4.779-3.499-11.178-2.475-14.847 2.56-1.792 2.388-3.498 4.863-5.205 7.252-1.62 2.218-3.583 2.56-5.546 1.11-1.877-1.366-2.218-3.414-.768-5.462 2.048-2.986 4.01-5.972 6.314-8.703 3.67-4.351 8.448-6.399 15.103-6.399l-.086-.085Z' fill='currentColor'\/><path d='M71.478 88.457c-3.498-.341-5.46-3.413-3.754-6.143 3.327-5.29 6.825-10.495 10.324-15.7 1.45-2.133 3.413-2.389 5.46-1.109 1.878 1.28 2.219 3.413.854 5.546-3.328 5.034-6.57 9.983-9.983 14.932-.683 1.024-1.963 1.621-2.901 2.389v.085Z' fill='currentColor'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"mailto:?to=%20&amp;body=https%3A%2F%2Fd66.nl%2Futrecht%2Fnieuws%2Fverplicht-openbare-scholen-niet-tot-gebedsruimtes\" target=\"_blank\" >\n\t\t\t\t\tMail<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fd66.nl%2Futrecht%2Fnieuws%2Fverplicht-openbare-scholen-niet-tot-gebedsruimtes\" target=\"_blank\" >\n\t\t\t\t\tLinkedIn<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fd66.nl%2Futrecht%2Fnieuws%2Fverplicht-openbare-scholen-niet-tot-gebedsruimtes\" target=\"_blank\" >\n\t\t\t\t\tFacebook<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"whatsapp:\/\/send?text=https%3A%2F%2Fd66.nl%2Futrecht%2Fnieuws%2Fverplicht-openbare-scholen-niet-tot-gebedsruimtes\" target=\"_blank\" >\n\t\t\t\t\tWhatsApp<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"https:\/\/x.com\/intent\/post?url=https%3A%2F%2Fd66.nl%2Futrecht%2Fnieuws%2Fverplicht-openbare-scholen-niet-tot-gebedsruimtes\" target=\"_blank\" >\n\t\t\t\t\tTwitter (X)<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/dialog>\n<\/div>\t\t\t<\/div>\n\t\t\t<div class=\"block-related-post-metadata__categories\">\n\t\t\t\t<div class=\"category-link__wrapper\">\n\t\t\t<div class=\"category-link__item\">\n\t\t\t<a href=\"https:\/\/d66.nl\/utrecht\/category\/d66\/\">\n\t\t\t\tD66\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"category-link__item\">\n\t\t\t<a href=\"https:\/\/d66.nl\/utrecht\/search-tags\/onderwijs\/\">\n\t\t\t\tOnderwijs\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--semiBold  block-post-content__heading\" id=\"nav-altijd-overal-jezelf-kunnen-zijn3419\" data-nav-heading-mobile=\"Altijd overal jezelf kunnen zijn\">\n\tAltijd overal jezelf kunnen zijn<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tIn Nederland moet iedereen altijd en overal zichzelf kunnen zijn. Je vrij voelen om te kunnen zijn wie je bent is voor D66 een belangrijke waarde, ook als het gaat om uitdragen van je levensovertuiging. Het onderwijs is voor jongeren een van de belangrijkste plekken waar zij hun identiteit en blik op de wereld verder ontwikkelen. Hen verbieden om te bidden op school, of beperken in de expressie van hun geloofsovertuiging, beperkt hen in de vrijheid om zichzelf te zijn.\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--semiBold  block-post-content__heading\" id=\"nav-wel-of-geen-gebedsruimte5640\" data-nav-heading-mobile=\"Wel of geen gebedsruimte\">\n\tWel of geen gebedsruimte<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tDe discussie, over of scholen gebedsruimtes beschikbaar moeten maken voor hun leerlingen, laaide op in Utrecht nadat een directeur van een openbare school, het Leidsche Rijn College, weigerde zo\u2019n ruimte beschikbaar te stellen nadat leerlingen daarom hadden gevraagd. Wethouder Eerenberg gaf hierover aan dat hij gesproken heeft met de schoolleiding, dat het nooit zo mag zijn dat bidden verboden wordt op school, maar dat het college niet vindt dat de school een aparte gebedsruimte moet realiseren. Dit is in lijn met wat de Commissie gelijke behandeling eerder oordeelde: \u2018Een school mag leerlingen niet verbieden te bidden, maar heeft geen plicht om een speciale ruimte daarvoor ter beschikking te stellen.\u2019 Wel heeft de wethouder de school aangemoedigd het gesprek aan te gaan met ouders en leerlingen om te zoeken naar een oplossing die past bij de school, en de verschillende perspectieven van ouders en kinderen.\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--semiBold  block-post-content__heading\" id=\"nav-stilte-ruimte-i-p-v--gebedsruimte8801\" data-nav-heading-mobile=\"Stilte ruimte i.p.v. gebedsruimte\">\n\tStilte ruimte i.p.v. gebedsruimte<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tOpenbare Scholen zijn een plek waar ruimte moet zijn voor iedereen. Ze zijn per definitie niet antireligieus, maar juist een plek waar jongen in aanraking gebracht worden met alle levensbeschouwingen en geloofsovertuigingen, zonder dat er \u00e9\u00e9n meer of minder ruimte en aandacht krijgt. Van de Wilt: \u201cWat D66 betreft past het daarom niet bij het karakter van openbaar onderwijs om te eisen dat er een gebedsruimte voor \u00e9\u00e9n bepaalde geloofsovertuiging wordt ingericht. Wat D66 betreft zou het passender zijn om voor een algemene stilteruimte te kiezen, waar alle leerlingen gebruik van kunnen maken.\u201d\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-text-title\">\n\t<div class=\"block-text-title__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--semiBold  block-text-title__heading\" id=\"nav-scholen-in-gesprek-met-leerlingen4814\" data-nav-heading-mobile=\"Scholen in gesprek met leerlingen\">\n\tScholen in gesprek met leerlingen<\/h3>\t<\/div>\n\t<div class=\"block-text-title__content\">\n\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default\">\n\t\t\u201cHet is echter niet aan de D66, de raad of andere partijen om te eisen dat er een gebedsruimte komt, \u201d aldus van der Wilt. \u201cOp elke school zullen de omstandigheden anders zijn. Ik vind het belangrijk dat vooral op de scholen, en dus niet in de raad, het gesprek gevoerd wordt met leerlingen, ouders, docenten en medezeggenschapsraden om zo tot een passende keuze te komen die bij de school en het openbare karakter past.\u201d\t<\/p>\t<\/div>\n\n\t<div class=\"block-text-title__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":753,"featured_media":2341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"search-tags":[2],"labels":[],"class_list":["post-2340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-d66","search-tags-onderwijs"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D66 Utrecht &#8212; Verplicht openbare scholen niet tot gebedsruimtes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D66 Utrecht &#8212; Verplicht openbare scholen niet tot gebedsruimtes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Utrecht\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-20T15:10:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-20T15:10:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d66.nl\/utrecht\/wp-content\/uploads\/sites\/85\/2023\/04\/chris-nguyen-lbmrrNgq2lo-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"iris_de_jonge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"iris_de_jonge\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/nieuws\\\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/nieuws\\\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\\\/\"},\"author\":{\"name\":\"iris_de_jonge\",\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/#\\\/schema\\\/person\\\/83709dbb4635ea950290d515a4991b97\"},\"headline\":\"Verplicht openbare scholen niet tot gebedsruimtes\",\"datePublished\":\"2023-04-20T15:10:25+00:00\",\"dateModified\":\"2023-04-20T15:10:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/nieuws\\\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\\\/\"},\"wordCount\":6,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/nieuws\\\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/wp-content\\\/uploads\\\/sites\\\/85\\\/2023\\\/04\\\/chris-nguyen-lbmrrNgq2lo-unsplash-scaled.jpg\",\"articleSection\":[\"D66\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/d66.nl\\\/utrecht\\\/nieuws\\\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/nieuws\\\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/nieuws\\\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\\\/\",\"name\":\"D66 Utrecht &#8212; Verplicht openbare scholen niet tot gebedsruimtes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/nieuws\\\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/nieuws\\\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/wp-content\\\/uploads\\\/sites\\\/85\\\/2023\\\/04\\\/chris-nguyen-lbmrrNgq2lo-unsplash-scaled.jpg\",\"datePublished\":\"2023-04-20T15:10:25+00:00\",\"dateModified\":\"2023-04-20T15:10:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/nieuws\\\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/utrecht\\\/nieuws\\\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/nieuws\\\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/wp-content\\\/uploads\\\/sites\\\/85\\\/2023\\\/04\\\/chris-nguyen-lbmrrNgq2lo-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/wp-content\\\/uploads\\\/sites\\\/85\\\/2023\\\/04\\\/chris-nguyen-lbmrrNgq2lo-unsplash-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/nieuws\\\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nieuws\",\"item\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/nieuws\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Verplicht openbare scholen niet tot gebedsruimtes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/\",\"name\":\"D66 Utrecht\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/d66.nl\\\/utrecht\\\/#\\\/schema\\\/person\\\/83709dbb4635ea950290d515a4991b97\",\"name\":\"iris_de_jonge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9611a102bc93ea9924e582f95009786fa8b0555b7547fbc6734a17e1258121a1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9611a102bc93ea9924e582f95009786fa8b0555b7547fbc6734a17e1258121a1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9611a102bc93ea9924e582f95009786fa8b0555b7547fbc6734a17e1258121a1?s=96&d=mm&r=g\",\"caption\":\"iris_de_jonge\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D66 Utrecht &#8212; Verplicht openbare scholen niet tot gebedsruimtes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes","og_locale":"nl_NL","og_type":"article","og_title":"D66 Utrecht &#8212; Verplicht openbare scholen niet tot gebedsruimtes","og_url":"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/","og_site_name":"D66 Utrecht","article_published_time":"2023-04-20T15:10:25+00:00","article_modified_time":"2023-04-20T15:10:26+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/d66.nl\/utrecht\/wp-content\/uploads\/sites\/85\/2023\/04\/chris-nguyen-lbmrrNgq2lo-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"iris_de_jonge","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"iris_de_jonge"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/#article","isPartOf":{"@id":"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/"},"author":{"name":"iris_de_jonge","@id":"https:\/\/d66.nl\/utrecht\/#\/schema\/person\/83709dbb4635ea950290d515a4991b97"},"headline":"Verplicht openbare scholen niet tot gebedsruimtes","datePublished":"2023-04-20T15:10:25+00:00","dateModified":"2023-04-20T15:10:26+00:00","mainEntityOfPage":{"@id":"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/"},"wordCount":6,"commentCount":0,"publisher":{"@id":"https:\/\/d66.nl\/utrecht\/#organization"},"image":{"@id":"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/#primaryimage"},"thumbnailUrl":"https:\/\/d66.nl\/utrecht\/wp-content\/uploads\/sites\/85\/2023\/04\/chris-nguyen-lbmrrNgq2lo-unsplash-scaled.jpg","articleSection":["D66"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/","url":"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/","name":"D66 Utrecht &#8212; Verplicht openbare scholen niet tot gebedsruimtes","isPartOf":{"@id":"https:\/\/d66.nl\/utrecht\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/#primaryimage"},"image":{"@id":"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/#primaryimage"},"thumbnailUrl":"https:\/\/d66.nl\/utrecht\/wp-content\/uploads\/sites\/85\/2023\/04\/chris-nguyen-lbmrrNgq2lo-unsplash-scaled.jpg","datePublished":"2023-04-20T15:10:25+00:00","dateModified":"2023-04-20T15:10:26+00:00","breadcrumb":{"@id":"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/#primaryimage","url":"https:\/\/d66.nl\/utrecht\/wp-content\/uploads\/sites\/85\/2023\/04\/chris-nguyen-lbmrrNgq2lo-unsplash-scaled.jpg","contentUrl":"https:\/\/d66.nl\/utrecht\/wp-content\/uploads\/sites\/85\/2023\/04\/chris-nguyen-lbmrrNgq2lo-unsplash-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/utrecht\/nieuws\/verplicht-openbare-scholen-niet-tot-gebedsruimtes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/utrecht\/"},{"@type":"ListItem","position":2,"name":"Nieuws","item":"https:\/\/d66.nl\/utrecht\/nieuws\/"},{"@type":"ListItem","position":3,"name":"Verplicht openbare scholen niet tot gebedsruimtes"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/utrecht\/#website","url":"https:\/\/d66.nl\/utrecht\/","name":"D66 Utrecht","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/utrecht\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/utrecht\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/utrecht\/#organization","name":"D66","url":"https:\/\/d66.nl\/utrecht\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/utrecht\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/utrecht\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/utrecht\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/utrecht\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/d66.nl\/utrecht\/#\/schema\/person\/83709dbb4635ea950290d515a4991b97","name":"iris_de_jonge","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/9611a102bc93ea9924e582f95009786fa8b0555b7547fbc6734a17e1258121a1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9611a102bc93ea9924e582f95009786fa8b0555b7547fbc6734a17e1258121a1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9611a102bc93ea9924e582f95009786fa8b0555b7547fbc6734a17e1258121a1?s=96&d=mm&r=g","caption":"iris_de_jonge"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/utrecht\/wp-json\/wp\/v2\/posts\/2340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/utrecht\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/d66.nl\/utrecht\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/utrecht\/wp-json\/wp\/v2\/users\/753"}],"replies":[{"embeddable":true,"href":"https:\/\/d66.nl\/utrecht\/wp-json\/wp\/v2\/comments?post=2340"}],"version-history":[{"count":2,"href":"https:\/\/d66.nl\/utrecht\/wp-json\/wp\/v2\/posts\/2340\/revisions"}],"predecessor-version":[{"id":2343,"href":"https:\/\/d66.nl\/utrecht\/wp-json\/wp\/v2\/posts\/2340\/revisions\/2343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d66.nl\/utrecht\/wp-json\/wp\/v2\/media\/2341"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/utrecht\/wp-json\/wp\/v2\/media?parent=2340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/d66.nl\/utrecht\/wp-json\/wp\/v2\/categories?post=2340"},{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/utrecht\/wp-json\/wp\/v2\/search-tags?post=2340"},{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/utrecht\/wp-json\/wp\/v2\/labels?post=2340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}