{"id":177,"date":"2021-10-26T11:24:28","date_gmt":"2021-10-26T11:24:28","guid":{"rendered":"https:\/\/d66.nl\/template14okt1966\/?page_id=177"},"modified":"2025-06-15T15:32:20","modified_gmt":"2025-06-15T15:32:20","slug":"onze-mensen","status":"publish","type":"page","link":"https:\/\/d66.nl\/sociaalliberalisme\/onze-mensen\/","title":{"rendered":"Onze mensen"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--150 wrapper__spacing-bottom-desktop--140 wrapper__spacing-bottom-mobile--110  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--0 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section\n  class=\"block-small-hero\"\n  data-video-url=\"\"\n>\n  <div class=\"block-small-hero__wrapper\">\n\t<div class=\"block-small-hero__heading\">\n\t  <div class=\"block-small-hero__title\">\n\t\t<h1 class=\"heading heading__align--left heading__color--black heading__size--giant  heading__weight--normal\" id=\"nav-dit-is-ons-team3466\" data-nav-heading-mobile=\"Dit is ons team\">\n\tDit is ons team<\/h1>\t  <\/div>\n\t  \t<\/div>\n\n\t\n\t\t  <div class=\"block-small-hero__image\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/d66.nl\/sociaalliberalisme\/wp-content\/uploads\/sites\/3\/2021\/10\/d66\u2014klimaat-natuur-en-milieu_bos_heide_-veluwe_unsplash-1024x576.jpg\" class=\"image block-small-hero__img\" alt=\"\" \/>\n\t\t\t<div class=\"image__caption-wrapper block-small-hero__caption-wrapper\">\n\t\t\t<div class=\"image__caption block-small-hero__caption\">\n\t\t\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--small paragraph__weight--medium\">\n\t\tHeide op de Veluwe. <i>&#x2022;<\/i> Beeld: Unsplash\t<\/p>\t\t\t<\/div>\n\t\t<\/div>\t  <\/div>\n\t\t<div class=\"block-small-hero__columns block-small-hero__columns--two\" data-accordion-active=\"0\">\n\t  <div class=\"block-small-hero__column\">\n\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default\">\n\t\tHet bestuur van de thema-afdeling Sociaal-liberalisme is verantwoordelijk voor de dagelijkse gang van zaken. Zij bestaat uit zes leden.\t<\/p>\t  <\/div>\n\t  \t  <div class=\"block-small-hero__column\">\n\t\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default\">\n\t\tHieronder maak je kennis met ons bestuur.\t<\/p>\t  <\/div>\n\t  \t  \t<\/div>\n  <\/div>\n<\/section>\n\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--220 wrapper__spacing-bottom-tablet--190 wrapper__spacing-bottom-mobile--140  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t\n<section class=\"block-people-grid js-block-people-grid\">\n\t<aside\n  class=\"inside-page-navigation js-inside-page-navigation block-people-grid__inside-page-navigation\"\n  data-nav-items-number=\"5\"\n>\n  <div class=\"inside-page-navigation__wrapper\">\n\t<ol class=\"inside-page-navigation__list js-navigation-list lists__lists lists__weight--medium lists__color--black lists__type--decimal-leading-zero\">\n\tDe navigatie wordt geladen&#8230;<\/ol>  <\/div>\n<\/aside>\t<div class=\"block-people-grid__grid\">\n\t\t\t\t\t\t\t\t<div class=\"block-people-grid__item\">\n\t\t\t\t<article class=\"people-card js-people-card\">\n\t<a class=\"people-card__link\" href=\"https:\/\/d66.nl\/sociaalliberalisme\/?post_type=people-type&#038;p=599\" style=\"--people-card-background-color: var(--global-colors-yellow)\">\n\n\t\t<div class=\"people-card__featured-image-wrapper\" style=\"background-image: url('https:\/\/d66.nl\/sociaalliberalisme\/wp-content\/uploads\/sites\/422\/2023\/06\/image.jpeg')\">\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t<\/div>\n\n\t\t<div class=\"people-card__content-wrapper\">\n\t\t\t\t\t\t\t<header class=\"people-card__header\">\n\t\t\t\t\t<h2 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-emiel-althuis7674\">\n\tEmiel Althuis<\/h2>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t<div class=\"people-card__description\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--medium\">\n\t\tVoorzitter\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   people-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"block-people-grid__item\">\n\t\t\t\t<article class=\"people-card js-people-card\">\n\t<a class=\"people-card__link\" href=\"https:\/\/d66.nl\/sociaalliberalisme\/mensen\/898\/\" style=\"--people-card-background-color: var(--global-colors-rosePink)\">\n\n\t\t<div class=\"people-card__featured-image-wrapper\" style=\"background-image: url('https:\/\/media.d66.nl\/uploads\/sites\/422\/2024\/04\/hjk_landscape-768x614.jpeg')\">\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t<\/div>\n\n\t\t<div class=\"people-card__content-wrapper\">\n\t\t\t\t\t\t\t<header class=\"people-card__header\">\n\t\t\t\t\t<h2 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-hendrik-jan-knegt6138\">\n\tHendrik Jan Knegt<\/h2>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t<div class=\"people-card__description\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--medium\">\n\t\tSecretaris, penningmeester\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   people-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"block-people-grid__item\">\n\t\t\t\t<article class=\"people-card js-people-card\">\n\t<a class=\"people-card__link\" href=\"https:\/\/d66.nl\/sociaalliberalisme\/mensen\/897\/\" style=\"--people-card-background-color: var(--global-colors-tomato)\">\n\n\t\t<div class=\"people-card__featured-image-wrapper\" style=\"background-image: url('https:\/\/d66.nl\/sociaalliberalisme\/wp-content\/uploads\/sites\/422\/2023\/06\/image-2.jpeg')\">\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t<\/div>\n\n\t\t<div class=\"people-card__content-wrapper\">\n\t\t\t\t\t\t\t<header class=\"people-card__header\">\n\t\t\t\t\t<h2 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-art-van-bruggen3141\">\n\tArt van Bruggen<\/h2>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t<div class=\"people-card__description\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--medium\">\n\t\tAlgemeen bestuurslid\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   people-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"block-people-grid__item\">\n\t\t\t\t<article class=\"people-card js-people-card\">\n\t<a class=\"people-card__link\" href=\"https:\/\/d66.nl\/sociaalliberalisme\/mensen\/896\/\" style=\"--people-card-background-color: var(--global-colors-romanSilver)\">\n\n\t\t<div class=\"people-card__featured-image-wrapper\" style=\"background-image: url('https:\/\/d66.nl\/sociaalliberalisme\/wp-content\/uploads\/sites\/422\/2024\/04\/Lidwien.jpg')\">\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t<\/div>\n\n\t\t<div class=\"people-card__content-wrapper\">\n\t\t\t\t\t\t\t<header class=\"people-card__header\">\n\t\t\t\t\t<h2 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-lidwien-van-langen8617\">\n\tLidwien van Langen<\/h2>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t<div class=\"people-card__description\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--medium\">\n\t\tAlgemeen bestuurslid\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   people-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"block-people-grid__item\">\n\t\t\t\t<article class=\"people-card js-people-card\">\n\t<a class=\"people-card__link\" href=\"https:\/\/d66.nl\/sociaalliberalisme\/mensen\/roland-dorhout-mees\/\" style=\"--people-card-background-color: var(--global-colors-skyBlue)\">\n\n\t\t<div class=\"people-card__featured-image-wrapper\" style=\"background-image: url('https:\/\/d66.nl\/sociaalliberalisme\/wp-content\/uploads\/sites\/422\/2025\/06\/Roland-Dorhout-Mees-1-768x762.jpg')\">\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t<\/div>\n\n\t\t<div class=\"people-card__content-wrapper\">\n\t\t\t\t\t\t\t<header class=\"people-card__header\">\n\t\t\t\t\t<h2 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-roland-dorhout-mees8569\">\n\tRoland Dorhout Mees<\/h2>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t<div class=\"people-card__description\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--medium\">\n\t\tAlgemeen bestuurslid\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   people-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"block-people-grid__item\">\n\t\t\t\t<article class=\"people-card js-people-card\">\n\t<a class=\"people-card__link\" href=\"\" style=\"--people-card-background-color: var(--global-colors-yellow)\">\n\n\t\t<div class=\"people-card__featured-image-wrapper\">\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t<\/div>\n\n\t\t<div class=\"people-card__content-wrapper\">\n\t\t\t\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   people-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t<\/div>\n\t\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":979,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"with-navigation.php","meta":{"_acf_changed":false,"footnotes":""},"themes-or-point-of-view":[],"labels":[],"search-tags":[],"class_list":["post-177","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Thema-afdeling Sociaal Liberalisme &#8212; Onze mensen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/sociaalliberalisme\/onze-mensen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thema-afdeling Sociaal Liberalisme &#8212; Onze mensen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/sociaalliberalisme\/onze-mensen\/\" \/>\n<meta property=\"og:site_name\" content=\"Thema-afdeling Sociaal Liberalisme\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-15T15:32:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/onze-mensen\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/onze-mensen\\\/\",\"name\":\"Thema-afdeling Sociaal Liberalisme &#8212; Onze mensen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/#website\"},\"datePublished\":\"2021-10-26T11:24:28+00:00\",\"dateModified\":\"2025-06-15T15:32:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/onze-mensen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/onze-mensen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/onze-mensen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Onze mensen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/\",\"name\":\"Thema-afdeling Sociaal Liberalisme\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/template14okt1966\\\/wp-content\\\/uploads\\\/sites\\\/422\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/template14okt1966\\\/wp-content\\\/uploads\\\/sites\\\/422\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/sociaalliberalisme\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thema-afdeling Sociaal Liberalisme &#8212; Onze mensen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/sociaalliberalisme\/onze-mensen\/","og_locale":"nl_NL","og_type":"article","og_title":"Thema-afdeling Sociaal Liberalisme &#8212; Onze mensen","og_url":"https:\/\/d66.nl\/sociaalliberalisme\/onze-mensen\/","og_site_name":"Thema-afdeling Sociaal Liberalisme","article_modified_time":"2025-06-15T15:32:20+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/sociaalliberalisme\/onze-mensen\/","url":"https:\/\/d66.nl\/sociaalliberalisme\/onze-mensen\/","name":"Thema-afdeling Sociaal Liberalisme &#8212; Onze mensen","isPartOf":{"@id":"https:\/\/d66.nl\/sociaalliberalisme\/#website"},"datePublished":"2021-10-26T11:24:28+00:00","dateModified":"2025-06-15T15:32:20+00:00","breadcrumb":{"@id":"https:\/\/d66.nl\/sociaalliberalisme\/onze-mensen\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/sociaalliberalisme\/onze-mensen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/sociaalliberalisme\/onze-mensen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/sociaalliberalisme\/"},{"@type":"ListItem","position":2,"name":"Onze mensen"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/sociaalliberalisme\/#website","url":"https:\/\/d66.nl\/sociaalliberalisme\/","name":"Thema-afdeling Sociaal Liberalisme","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/sociaalliberalisme\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/sociaalliberalisme\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/sociaalliberalisme\/#organization","name":"D66","url":"https:\/\/d66.nl\/sociaalliberalisme\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/sociaalliberalisme\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/template14okt1966\/wp-content\/uploads\/sites\/422\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/template14okt1966\/wp-content\/uploads\/sites\/422\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/sociaalliberalisme\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/sociaalliberalisme\/wp-json\/wp\/v2\/pages\/177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/sociaalliberalisme\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/d66.nl\/sociaalliberalisme\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/sociaalliberalisme\/wp-json\/wp\/v2\/users\/979"}],"replies":[{"embeddable":true,"href":"https:\/\/d66.nl\/sociaalliberalisme\/wp-json\/wp\/v2\/comments?post=177"}],"version-history":[{"count":10,"href":"https:\/\/d66.nl\/sociaalliberalisme\/wp-json\/wp\/v2\/pages\/177\/revisions"}],"predecessor-version":[{"id":1010,"href":"https:\/\/d66.nl\/sociaalliberalisme\/wp-json\/wp\/v2\/pages\/177\/revisions\/1010"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/sociaalliberalisme\/wp-json\/wp\/v2\/media?parent=177"}],"wp:term":[{"taxonomy":"themes-or-point-of-view","embeddable":true,"href":"https:\/\/d66.nl\/sociaalliberalisme\/wp-json\/wp\/v2\/themes-or-point-of-view?post=177"},{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/sociaalliberalisme\/wp-json\/wp\/v2\/labels?post=177"},{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/sociaalliberalisme\/wp-json\/wp\/v2\/search-tags?post=177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}