{"id":694,"date":"2026-02-14T11:56:59","date_gmt":"2026-02-14T11:56:59","guid":{"rendered":"https:\/\/d66.nl\/sliedrecht\/?post_type=people-type&#038;p=694"},"modified":"2026-03-11T14:25:14","modified_gmt":"2026-03-11T14:25:14","slug":"ellen-koster","status":"publish","type":"people-type","link":"https:\/\/d66.nl\/sliedrecht\/mensen\/ellen-koster\/","title":{"rendered":"Ellen Koster"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--10 wrapper__spacing-bottom-mobile--10  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading heading__align--left heading__color--black heading__size--giant heading__font--serif heading__weight--regular  block-heading__heading\" id=\"nav-ellen-koster5442\"  data-nav-heading-mobile=\"Ellen Koster\" >\n\tEllen Koster<\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-people-introduction\">\n\t<div class=\"block-people-introduction__content\">\n\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--big\">\n\t\t\t<\/p><section class=\"people-bullet-point-card block-people-introduction__people-bullet-point-card\" style=\"--bg-color: var(--global-colors-yellow)\">\n\t<div class=\"people-bullet-point-card__wrapper\">\n\t\t<div class=\"people-bullet-point-card__title\">\n\t\t\t<h2 class=\"heading    heading__font--sans heading__weight--bold\" id=\"nav-over-ellen1044\" data-nav-heading-mobile=\"Over Ellen\">\n\tOver Ellen<\/h2>\t\t\t<div aria-hidden=\"true\" class=\"people-bullet-point-card__border\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"people-bullet-point-card__info\">\n\t\t\t<ul class=\"lists\">\n\t\t\t\t\t\t\t\t\t\t\t\t<li><label>Woonplaats<\/label><span>Sliedrecht<\/span><\/li>\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section><p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default\">\n\t\tIk sta op de kandidatenlijst voor D66 Sliedrecht omdat ik geloof in een eerlijke, open en constructieve lokale politiek. Al meer dan vijf jaar ben ik met plezier lid van D66 en inmiddels werken we ruim een jaar intensief aan de voorbereidingen voor deze gemeenteraadsverkiezingen. In die periode heb ik mij met grote toewijding ingezet voor het verkiezingsprogramma, waarin onze idealen en ambities voor Sliedrecht samenkomen.<br><br>Ik sta op plek 3, een bewuste lijstduwerplek. Realistisch gezien gaan we uit van \u00e9\u00e9n zetel en hopen we op twee, maar ik wil graag laten zien dat ik volledig achter ons team en onze koers sta. Later dit jaar verhuis ik, maar dat doet niets af aan mijn betrokkenheid bij deze campagne en mijn vertrouwen in de kandidaten op de verkiesbare plekken. Zij zullen zich met volle overtuiging inzetten voor het D66-gedachtengoed. Want ook in Sliedrecht kan politiek eerlijk, open en vooruitstrevend zijn.\t<\/p>\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"author":2000,"featured_media":725,"menu_order":0,"template":"","labels":[],"search-tags":[],"division-tags":[],"class_list":["post-694","people-type","type-people-type","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D66 Sliedrecht &#8212; Onze mensen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/sliedrecht\/mensen\/ellen-koster\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D66 Sliedrecht &#8212; Onze mensen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/sliedrecht\/mensen\/ellen-koster\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Sliedrecht\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-11T14:25:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.d66.nl\/uploads\/sites\/358\/2026\/02\/Screenshot-2026-03-11-at-15.24.47.png\" \/>\n\t<meta property=\"og:image:width\" content=\"776\" \/>\n\t<meta property=\"og:image:height\" content=\"884\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/mensen\\\/ellen-koster\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/mensen\\\/ellen-koster\\\/\",\"name\":\"D66 Sliedrecht &#8212; Onze mensen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/mensen\\\/ellen-koster\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/mensen\\\/ellen-koster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/358\\\/2026\\\/02\\\/Screenshot-2026-03-11-at-15.24.47.png\",\"datePublished\":\"2026-02-14T11:56:59+00:00\",\"dateModified\":\"2026-03-11T14:25:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/mensen\\\/ellen-koster\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/mensen\\\/ellen-koster\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/mensen\\\/ellen-koster\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/358\\\/2026\\\/02\\\/Screenshot-2026-03-11-at-15.24.47.png\",\"contentUrl\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/358\\\/2026\\\/02\\\/Screenshot-2026-03-11-at-15.24.47.png\",\"width\":776,\"height\":884},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/mensen\\\/ellen-koster\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mensen\",\"item\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/mensen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ellen Koster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/\",\"name\":\"D66 Sliedrecht\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/sliedrecht\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D66 Sliedrecht &#8212; Onze mensen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/sliedrecht\/mensen\/ellen-koster\/","og_locale":"nl_NL","og_type":"article","og_title":"D66 Sliedrecht &#8212; Onze mensen","og_url":"https:\/\/d66.nl\/sliedrecht\/mensen\/ellen-koster\/","og_site_name":"D66 Sliedrecht","article_modified_time":"2026-03-11T14:25:14+00:00","og_image":[{"width":776,"height":884,"url":"https:\/\/media.d66.nl\/uploads\/sites\/358\/2026\/02\/Screenshot-2026-03-11-at-15.24.47.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/sliedrecht\/mensen\/ellen-koster\/","url":"https:\/\/d66.nl\/sliedrecht\/mensen\/ellen-koster\/","name":"D66 Sliedrecht &#8212; Onze mensen","isPartOf":{"@id":"https:\/\/d66.nl\/sliedrecht\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d66.nl\/sliedrecht\/mensen\/ellen-koster\/#primaryimage"},"image":{"@id":"https:\/\/d66.nl\/sliedrecht\/mensen\/ellen-koster\/#primaryimage"},"thumbnailUrl":"https:\/\/media.d66.nl\/uploads\/sites\/358\/2026\/02\/Screenshot-2026-03-11-at-15.24.47.png","datePublished":"2026-02-14T11:56:59+00:00","dateModified":"2026-03-11T14:25:14+00:00","breadcrumb":{"@id":"https:\/\/d66.nl\/sliedrecht\/mensen\/ellen-koster\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/sliedrecht\/mensen\/ellen-koster\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/sliedrecht\/mensen\/ellen-koster\/#primaryimage","url":"https:\/\/media.d66.nl\/uploads\/sites\/358\/2026\/02\/Screenshot-2026-03-11-at-15.24.47.png","contentUrl":"https:\/\/media.d66.nl\/uploads\/sites\/358\/2026\/02\/Screenshot-2026-03-11-at-15.24.47.png","width":776,"height":884},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/sliedrecht\/mensen\/ellen-koster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/sliedrecht\/"},{"@type":"ListItem","position":2,"name":"Mensen","item":"https:\/\/d66.nl\/sliedrecht\/mensen\/"},{"@type":"ListItem","position":3,"name":"Ellen Koster"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/sliedrecht\/#website","url":"https:\/\/d66.nl\/sliedrecht\/","name":"D66 Sliedrecht","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/sliedrecht\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/sliedrecht\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/sliedrecht\/#organization","name":"D66","url":"https:\/\/d66.nl\/sliedrecht\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/sliedrecht\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/sliedrecht\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/sliedrecht\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/sliedrecht\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/sliedrecht\/wp-json\/wp\/v2\/people-type\/694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/sliedrecht\/wp-json\/wp\/v2\/people-type"}],"about":[{"href":"https:\/\/d66.nl\/sliedrecht\/wp-json\/wp\/v2\/types\/people-type"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/sliedrecht\/wp-json\/wp\/v2\/users\/2000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d66.nl\/sliedrecht\/wp-json\/wp\/v2\/media\/725"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/sliedrecht\/wp-json\/wp\/v2\/media?parent=694"}],"wp:term":[{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/sliedrecht\/wp-json\/wp\/v2\/labels?post=694"},{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/sliedrecht\/wp-json\/wp\/v2\/search-tags?post=694"},{"taxonomy":"division-tags","embeddable":true,"href":"https:\/\/d66.nl\/sliedrecht\/wp-json\/wp\/v2\/division-tags?post=694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}