{"id":1956,"date":"2026-02-04T18:21:43","date_gmt":"2026-02-04T18:21:43","guid":{"rendered":"https:\/\/d66.nl\/shertogenbosch\/?post_type=people-type&#038;p=1956"},"modified":"2026-04-22T19:05:05","modified_gmt":"2026-04-22T19:05:05","slug":"casper-soetekouw","status":"publish","type":"people-type","link":"https:\/\/d66.nl\/shertogenbosch\/mensen\/casper-soetekouw\/","title":{"rendered":"Casper Soetekouw"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--10 wrapper__spacing-bottom-mobile--10  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading heading__align--left heading__color--black heading__size--giant heading__font--serif heading__weight--regular  block-heading__heading\" id=\"nav-casper-soetekouw1898\"  data-nav-heading-mobile=\"Casper Soetekouw\" >\n\tCasper Soetekouw<\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/media.d66.nl\/uploads\/sites\/200\/2026\/01\/260110_D66-portretten_Noud-Otten-Photography_08-69791ed1dfb39-1024x683.jpg\" class=\"image block-image__img\" alt=\"\" srcset=\"https:\/\/media.d66.nl\/uploads\/sites\/200\/2026\/01\/260110_D66-portretten_Noud-Otten-Photography_08-69791ed1dfb39-1024x683.jpg 1024w, https:\/\/media.d66.nl\/uploads\/sites\/200\/2026\/01\/260110_D66-portretten_Noud-Otten-Photography_08-69791ed1dfb39-300x200.jpg 300w, https:\/\/media.d66.nl\/uploads\/sites\/200\/2026\/01\/260110_D66-portretten_Noud-Otten-Photography_08-69791ed1dfb39-768x512.jpg 768w, https:\/\/media.d66.nl\/uploads\/sites\/200\/2026\/01\/260110_D66-portretten_Noud-Otten-Photography_08-69791ed1dfb39-1536x1024.jpg 1536w, https:\/\/media.d66.nl\/uploads\/sites\/200\/2026\/01\/260110_D66-portretten_Noud-Otten-Photography_08-69791ed1dfb39-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<div class=\"image__caption-wrapper block-image__caption-wrapper\">\n\t\t\t<div class=\"image__caption block-image__caption\">\n\t\t\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--small paragraph__weight--medium\">\n\t\t<b>Casper Soetekouw<\/b> <i>&#045;<\/i> Beeld: Noud Otten\/D66 &#8216;s-Hertogenbosch\t<\/p>\t\t\t<\/div>\n\t\t<\/div>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-people-introduction\">\n\t<div class=\"block-people-introduction__content\">\n\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--big\">\n\t\tNa een aantal jaren buiten de stad ben ik teruggekeerd naar Den Bosch, waar ik nu samenwoon met mijn vriendin. Dit is de stad waar ik ben opgegroeid en die mijn thuis is. In mijn werk bij het ministerie van Buitenlandse Zaken houd ik me dagelijks bezig met wat er buiten Nederland gebeurt. Juist daardoor realiseer ik me hoe goed we het hier in Den Bosch voor elkaar hebben, maar ook waar het beter kan.\t<\/p><section class=\"people-bullet-point-card block-people-introduction__people-bullet-point-card\" style=\"--bg-color: var(--global-colors-yellow)\">\n\t<div class=\"people-bullet-point-card__wrapper\">\n\t\t<div class=\"people-bullet-point-card__title\">\n\t\t\t<h2 class=\"heading    heading__font--sans heading__weight--bold\" id=\"nav-over-casper8084\" data-nav-heading-mobile=\"Over Casper\">\n\tOver Casper<\/h2>\t\t\t<div aria-hidden=\"true\" class=\"people-bullet-point-card__border\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"people-bullet-point-card__info\">\n\t\t\t<ul class=\"lists\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section><p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default\">\n\t\tDie combinatie van een brede blik en lokale betrokkenheid wil ik inzetten in deze gemeente namens D66. Den Bosch heeft alles om een sterke, levendige stad te zijn en blijven, maar dat vraagt wel om ambitieuze keuzes voor de toekomst. Betaalbaar wonen is daarbij essentieel, zodat mensen die dat willen hier kunnen wonen en hun leven opbouwen. Daarnaast geloof ik dat een stad pas echt werkt als er ruimte is voor eigen initiatief, ontmoeting en groen. Als raadslid wil ik bijdragen aan een Den Bosch dat vooruit kijkt, openstaat voor nieuwe idee\u00ebn en zijn menselijke maat behoudt.\t<\/p><div class=\"content-accordion js-content-accordion\" data-accordion-opened=\"0\">\n\n\t\t\t<div aria-hidden=\"true\" class=\"content-accordion__border\"><\/div>\n\t\n\t<button id=\"content-accordion-trigger-1924210567\" class=\"content-accordion__trigger js-content-accordion-trigger\" aria-label=\"Expertises (portefeuilles)\" aria-controls>\n\t\t<div class=\"content-accordion__heading\">\n\t\t\t<h3 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-expertises--portefeuilles-2627\">\n\tExpertises (portefeuilles)<\/h3>\t\t<\/div>\n\t\t<div class=\"content-accordion__icon\" aria-hidden=\"true\"><\/div>\n\t<\/button>\n\n\t<section id=\"content-accordion-panel-1924210567\" class=\"content-accordion__panel js-content-accordion-panel\" aria-hidden=\"true\" aria-labelledby=\"content-accordion-trigger-1924210567\">\n\t\t<div class=\"content-accordion__content-wrapper\">\n\t\t\t<div class=\"content-accordion__description\">\n\t\t\t\tWonen<br \/>\r\nGrondbeleid\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n\t<div aria-hidden=\"true\" class=\"content-accordion__border\"><\/div>\n<\/div>\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--bold  block-post-content__heading\" id=\"nav-mijn-speerpunten8434\" data-nav-heading-mobile=\"Mijn speerpunten\">\n\tMijn speerpunten<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper wrapper__spacing-top-large--0 wrapper__spacing-bottom-large--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-desktop--default\">\n\t  <div class=\"wrapper__inner wrapper__width-mobile--24\">\n\t\t\t<div class=\"block-lists  block-lists__color--black\">\n\t\t<p class=\"paragraph  paragraph__color--black paragraph__size--default\">\n\t\t\t<\/p><ul class=\"block-lists lists__lists lists__weight--medium lists__color--black lists__type--default\">\n\t<li>Betaalbaar wonen, zodat mensen in Den Bosch kunnen komen en blijven wonen.<\/li><li>Ruimte voor bewonersinitiatieven en ontmoeting, omdat goede idee\u00ebn vaak uit de stad zelf komen.<\/li><li>Meer groen in en rondom wijken en dorpen, voor ontspanning, gezondheid en leefkwaliteit.<\/li><\/ul>\t<\/div>\n\t\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\t\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"author":1906,"featured_media":1958,"menu_order":0,"template":"","search-tags":[],"labels":[],"division-tags":[31,32],"class_list":["post-1956","people-type","type-people-type","status-publish","has-post-thumbnail","hentry","division-tags-fractie","division-tags-kandidaat-raadsleden-2026-2030"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D66 &#039;s-Hertogenbosch &#8212; Onze mensen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/shertogenbosch\/mensen\/casper-soetekouw\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D66 &#039;s-Hertogenbosch &#8212; Onze mensen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/shertogenbosch\/mensen\/casper-soetekouw\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 &#039;s-Hertogenbosch\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T19:05:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.d66.nl\/uploads\/sites\/200\/2026\/01\/260110_D66-portretten_Noud-Otten-Photography_08-69791ed1dfb39-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/mensen\\\/casper-soetekouw\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/mensen\\\/casper-soetekouw\\\/\",\"name\":\"D66 &#039;s-Hertogenbosch &#8212; Onze mensen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/mensen\\\/casper-soetekouw\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/mensen\\\/casper-soetekouw\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/200\\\/2026\\\/01\\\/260110_D66-portretten_Noud-Otten-Photography_08-69791ed1dfb39-scaled.jpg\",\"datePublished\":\"2026-02-04T18:21:43+00:00\",\"dateModified\":\"2026-04-22T19:05:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/mensen\\\/casper-soetekouw\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/mensen\\\/casper-soetekouw\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/mensen\\\/casper-soetekouw\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/200\\\/2026\\\/01\\\/260110_D66-portretten_Noud-Otten-Photography_08-69791ed1dfb39-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/200\\\/2026\\\/01\\\/260110_D66-portretten_Noud-Otten-Photography_08-69791ed1dfb39-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/mensen\\\/casper-soetekouw\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mensen\",\"item\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/mensen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Casper Soetekouw\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/\",\"name\":\"D66 &#039;s-Hertogenbosch\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/shertogenbosch\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D66 &#039;s-Hertogenbosch &#8212; Onze mensen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/shertogenbosch\/mensen\/casper-soetekouw\/","og_locale":"nl_NL","og_type":"article","og_title":"D66 &#039;s-Hertogenbosch &#8212; Onze mensen","og_url":"https:\/\/d66.nl\/shertogenbosch\/mensen\/casper-soetekouw\/","og_site_name":"D66 &#039;s-Hertogenbosch","article_modified_time":"2026-04-22T19:05:05+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/media.d66.nl\/uploads\/sites\/200\/2026\/01\/260110_D66-portretten_Noud-Otten-Photography_08-69791ed1dfb39-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/shertogenbosch\/mensen\/casper-soetekouw\/","url":"https:\/\/d66.nl\/shertogenbosch\/mensen\/casper-soetekouw\/","name":"D66 &#039;s-Hertogenbosch &#8212; Onze mensen","isPartOf":{"@id":"https:\/\/d66.nl\/shertogenbosch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d66.nl\/shertogenbosch\/mensen\/casper-soetekouw\/#primaryimage"},"image":{"@id":"https:\/\/d66.nl\/shertogenbosch\/mensen\/casper-soetekouw\/#primaryimage"},"thumbnailUrl":"https:\/\/media.d66.nl\/uploads\/sites\/200\/2026\/01\/260110_D66-portretten_Noud-Otten-Photography_08-69791ed1dfb39-scaled.jpg","datePublished":"2026-02-04T18:21:43+00:00","dateModified":"2026-04-22T19:05:05+00:00","breadcrumb":{"@id":"https:\/\/d66.nl\/shertogenbosch\/mensen\/casper-soetekouw\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/shertogenbosch\/mensen\/casper-soetekouw\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/shertogenbosch\/mensen\/casper-soetekouw\/#primaryimage","url":"https:\/\/media.d66.nl\/uploads\/sites\/200\/2026\/01\/260110_D66-portretten_Noud-Otten-Photography_08-69791ed1dfb39-scaled.jpg","contentUrl":"https:\/\/media.d66.nl\/uploads\/sites\/200\/2026\/01\/260110_D66-portretten_Noud-Otten-Photography_08-69791ed1dfb39-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/shertogenbosch\/mensen\/casper-soetekouw\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/shertogenbosch\/"},{"@type":"ListItem","position":2,"name":"Mensen","item":"https:\/\/d66.nl\/shertogenbosch\/mensen\/"},{"@type":"ListItem","position":3,"name":"Casper Soetekouw"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/shertogenbosch\/#website","url":"https:\/\/d66.nl\/shertogenbosch\/","name":"D66 &#039;s-Hertogenbosch","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/shertogenbosch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/shertogenbosch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/shertogenbosch\/#organization","name":"D66","url":"https:\/\/d66.nl\/shertogenbosch\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/shertogenbosch\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/shertogenbosch\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/shertogenbosch\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/shertogenbosch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/shertogenbosch\/wp-json\/wp\/v2\/people-type\/1956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/shertogenbosch\/wp-json\/wp\/v2\/people-type"}],"about":[{"href":"https:\/\/d66.nl\/shertogenbosch\/wp-json\/wp\/v2\/types\/people-type"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/shertogenbosch\/wp-json\/wp\/v2\/users\/1906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d66.nl\/shertogenbosch\/wp-json\/wp\/v2\/media\/1958"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/shertogenbosch\/wp-json\/wp\/v2\/media?parent=1956"}],"wp:term":[{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/shertogenbosch\/wp-json\/wp\/v2\/search-tags?post=1956"},{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/shertogenbosch\/wp-json\/wp\/v2\/labels?post=1956"},{"taxonomy":"division-tags","embeddable":true,"href":"https:\/\/d66.nl\/shertogenbosch\/wp-json\/wp\/v2\/division-tags?post=1956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}