{"id":665,"date":"2023-06-01T18:40:58","date_gmt":"2023-06-01T18:40:58","guid":{"rendered":"https:\/\/d66.nl\/ruimteenmobiliteit\/?page_id=665"},"modified":"2023-06-28T13:59:20","modified_gmt":"2023-06-28T13:59:20","slug":"slimme-duurzame-mobiliteit-voor-iedereen","status":"publish","type":"page","link":"https:\/\/d66.nl\/ruimteenmobiliteit\/slimme-duurzame-mobiliteit-voor-iedereen\/","title":{"rendered":"Slimme, duurzame mobiliteit voor iedereen"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--66 wrapper__spacing-bottom-mobile--76  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading   heading__size--giant heading__font--serif heading__weight--regular  block-heading__heading\" id=\"nav-slimme--duurzame-mobiliteit-voor-iedereen9070\"  data-nav-heading-mobile=\"Slimme, duurzame mobiliteit voor iedereen\" >\n\tSlimme, duurzame mobiliteit voor iedereen<\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-mobile--40  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--13 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<p\n\t\tclass=\"paragraph   paragraph__size--big   block-paragraph__paragraph\"\n\t\t\t>\n\t\tWij zijn continu in beweging. Nederlanders zijn gemiddeld 1,5 uur per dag onderweg. Naar verwachting zal onze mobiliteit de komende jaren drastisch veranderen. Gaan we van hebben naar delen? Praten verkeerslichten, auto\u2019s, treinen en bussen straks allemaal met elkaar? Wat regelen we straks collectief en hoeveel hebben we zelf nog? Deze ontwikkelingen hebben grote impact op onze fysieke omgeving.\u00a0Tegelijkertijd staan we nu voor grote uitdagingen. De files nemen in rap tempo toe en het OV in de Randstad zit vol. Door minder in te zetten op asfalt en meer te gaan voor slimme oplossingen, kunnen we problemen op de weg structureel aanpakken. En omdat we niet weten wat de toekomst brengt kunnen flexibele MIRT trajecten ervoor zorgen dat oplossingsrichtingen mee veranderen met de ontwikkelingen in de mobiliteit. In de drukke Randstad is het OV een belangrijke schakel in de stedelijke bereikbaarheid. In deze schakel moeten we blijven investeren.\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1081,"featured_media":735,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"search-tags":[],"labels":[],"themes-or-point-of-view":[],"class_list":["post-665","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ruimte en Mobiliteit &#8212; Slimme, duurzame mobiliteit voor iedereen<\/title>\n<meta name=\"description\" content=\"Wij zijn continu in beweging. Nederlanders zijn gemiddeld 1,5 ur per dag onderweg. Naar verwachting zal onze mobiliteit de komende jaren drastisch veranderen. Gaan we van hebben naar delen? Praten verkeerslichten, auto\u2019s, treinen en bussen straks allemaal met elkaar? Wat regelen we straks collectief en hoeveel hebben we zelf nog?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/ruimteenmobiliteit\/slimme-duurzame-mobiliteit-voor-iedereen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ruimte en Mobiliteit &#8212; Slimme, duurzame mobiliteit voor iedereen\" \/>\n<meta property=\"og:description\" content=\"Wij zijn continu in beweging. Nederlanders zijn gemiddeld 1,5 ur per dag onderweg. Naar verwachting zal onze mobiliteit de komende jaren drastisch veranderen. Gaan we van hebben naar delen? Praten verkeerslichten, auto\u2019s, treinen en bussen straks allemaal met elkaar? Wat regelen we straks collectief en hoeveel hebben we zelf nog?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/ruimteenmobiliteit\/slimme-duurzame-mobiliteit-voor-iedereen\/\" \/>\n<meta property=\"og:site_name\" content=\"Ruimte en Mobiliteit\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-28T13:59:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-content\/uploads\/sites\/418\/2023\/06\/liam-mcgarry-tR-f_6zYvIo-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/slimme-duurzame-mobiliteit-voor-iedereen\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/slimme-duurzame-mobiliteit-voor-iedereen\\\/\",\"name\":\"Ruimte en Mobiliteit &#8212; Slimme, duurzame mobiliteit voor iedereen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/slimme-duurzame-mobiliteit-voor-iedereen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/slimme-duurzame-mobiliteit-voor-iedereen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/wp-content\\\/uploads\\\/sites\\\/418\\\/2023\\\/06\\\/liam-mcgarry-tR-f_6zYvIo-unsplash-scaled.jpg\",\"datePublished\":\"2023-06-01T18:40:58+00:00\",\"dateModified\":\"2023-06-28T13:59:20+00:00\",\"description\":\"Wij zijn continu in beweging. Nederlanders zijn gemiddeld 1,5 ur per dag onderweg. Naar verwachting zal onze mobiliteit de komende jaren drastisch veranderen. Gaan we van hebben naar delen? Praten verkeerslichten, auto\u2019s, treinen en bussen straks allemaal met elkaar? Wat regelen we straks collectief en hoeveel hebben we zelf nog?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/slimme-duurzame-mobiliteit-voor-iedereen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/slimme-duurzame-mobiliteit-voor-iedereen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/slimme-duurzame-mobiliteit-voor-iedereen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/wp-content\\\/uploads\\\/sites\\\/418\\\/2023\\\/06\\\/liam-mcgarry-tR-f_6zYvIo-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/wp-content\\\/uploads\\\/sites\\\/418\\\/2023\\\/06\\\/liam-mcgarry-tR-f_6zYvIo-unsplash-scaled.jpg\",\"width\":2048,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/slimme-duurzame-mobiliteit-voor-iedereen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slimme, duurzame mobiliteit voor iedereen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/\",\"name\":\"Ruimte en Mobiliteit\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/template14okt1966\\\/wp-content\\\/uploads\\\/sites\\\/418\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/template14okt1966\\\/wp-content\\\/uploads\\\/sites\\\/418\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ruimte en Mobiliteit &#8212; Slimme, duurzame mobiliteit voor iedereen","description":"Wij zijn continu in beweging. Nederlanders zijn gemiddeld 1,5 ur per dag onderweg. Naar verwachting zal onze mobiliteit de komende jaren drastisch veranderen. Gaan we van hebben naar delen? Praten verkeerslichten, auto\u2019s, treinen en bussen straks allemaal met elkaar? Wat regelen we straks collectief en hoeveel hebben we zelf nog?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/ruimteenmobiliteit\/slimme-duurzame-mobiliteit-voor-iedereen\/","og_locale":"nl_NL","og_type":"article","og_title":"Ruimte en Mobiliteit &#8212; Slimme, duurzame mobiliteit voor iedereen","og_description":"Wij zijn continu in beweging. Nederlanders zijn gemiddeld 1,5 ur per dag onderweg. Naar verwachting zal onze mobiliteit de komende jaren drastisch veranderen. Gaan we van hebben naar delen? Praten verkeerslichten, auto\u2019s, treinen en bussen straks allemaal met elkaar? Wat regelen we straks collectief en hoeveel hebben we zelf nog?","og_url":"https:\/\/d66.nl\/ruimteenmobiliteit\/slimme-duurzame-mobiliteit-voor-iedereen\/","og_site_name":"Ruimte en Mobiliteit","article_modified_time":"2023-06-28T13:59:20+00:00","og_image":[{"width":2048,"height":2560,"url":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-content\/uploads\/sites\/418\/2023\/06\/liam-mcgarry-tR-f_6zYvIo-unsplash-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/slimme-duurzame-mobiliteit-voor-iedereen\/","url":"https:\/\/d66.nl\/ruimteenmobiliteit\/slimme-duurzame-mobiliteit-voor-iedereen\/","name":"Ruimte en Mobiliteit &#8212; Slimme, duurzame mobiliteit voor iedereen","isPartOf":{"@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/slimme-duurzame-mobiliteit-voor-iedereen\/#primaryimage"},"image":{"@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/slimme-duurzame-mobiliteit-voor-iedereen\/#primaryimage"},"thumbnailUrl":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-content\/uploads\/sites\/418\/2023\/06\/liam-mcgarry-tR-f_6zYvIo-unsplash-scaled.jpg","datePublished":"2023-06-01T18:40:58+00:00","dateModified":"2023-06-28T13:59:20+00:00","description":"Wij zijn continu in beweging. Nederlanders zijn gemiddeld 1,5 ur per dag onderweg. Naar verwachting zal onze mobiliteit de komende jaren drastisch veranderen. Gaan we van hebben naar delen? Praten verkeerslichten, auto\u2019s, treinen en bussen straks allemaal met elkaar? Wat regelen we straks collectief en hoeveel hebben we zelf nog?","breadcrumb":{"@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/slimme-duurzame-mobiliteit-voor-iedereen\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/ruimteenmobiliteit\/slimme-duurzame-mobiliteit-voor-iedereen\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/slimme-duurzame-mobiliteit-voor-iedereen\/#primaryimage","url":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-content\/uploads\/sites\/418\/2023\/06\/liam-mcgarry-tR-f_6zYvIo-unsplash-scaled.jpg","contentUrl":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-content\/uploads\/sites\/418\/2023\/06\/liam-mcgarry-tR-f_6zYvIo-unsplash-scaled.jpg","width":2048,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/slimme-duurzame-mobiliteit-voor-iedereen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/ruimteenmobiliteit\/"},{"@type":"ListItem","position":2,"name":"Slimme, duurzame mobiliteit voor iedereen"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/#website","url":"https:\/\/d66.nl\/ruimteenmobiliteit\/","name":"Ruimte en Mobiliteit","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/ruimteenmobiliteit\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/#organization","name":"D66","url":"https:\/\/d66.nl\/ruimteenmobiliteit\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/template14okt1966\/wp-content\/uploads\/sites\/418\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/template14okt1966\/wp-content\/uploads\/sites\/418\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/pages\/665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/users\/1081"}],"replies":[{"embeddable":true,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/comments?post=665"}],"version-history":[{"count":6,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/pages\/665\/revisions"}],"predecessor-version":[{"id":730,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/pages\/665\/revisions\/730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/media\/735"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/media?parent=665"}],"wp:term":[{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/search-tags?post=665"},{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/labels?post=665"},{"taxonomy":"themes-or-point-of-view","embeddable":true,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/themes-or-point-of-view?post=665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}