{"id":427,"date":"2021-11-26T12:12:58","date_gmt":"2021-11-26T12:12:58","guid":{"rendered":"https:\/\/d66.nl\/template14okt1966\/?page_id=427"},"modified":"2023-06-28T12:49:06","modified_gmt":"2023-06-28T12:49:06","slug":"contact","status":"publish","type":"page","link":"https:\/\/d66.nl\/ruimteenmobiliteit\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--66 wrapper__spacing-bottom-mobile--76  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading heading__align--left heading__color--black heading__size--giant heading__font--serif   block-heading__heading\" id=\"nav-contact-met-d666154\"  data-nav-heading-mobile=\"Contact met D66\" >\n\tContact met D66<\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--semiBold  block-post-content__heading\" id=\"nav-contact-met-onze--br-thema-afdeling6917\" data-nav-heading-mobile=\"Contact met onze thema afdeling\">\n\tContact met onze <br>thema afdeling<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\t<strong>Een e-mail sturen kan natuurlijk:<br><\/strong><a href=\"mailto:info@d66ruimteenmobiliteit.nl\">secretaris@d66ruimteenmobiliteit.nl<\/a><br>\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":35,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"themes-or-point-of-view":[],"labels":[],"search-tags":[],"class_list":["post-427","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ruimte en Mobiliteit &#8212; Contact<\/title>\n<meta name=\"description\" content=\"Benieuwd naar wat de thema-afdeling jouw te bieden heeft? Wil je een keer een bijeenkomst bijwonen of, nog beter, wil jij een interessante bijeenkomst organiseren? Heb jij interesse in een bestuursfuctie en wil je meer weten over het reilen en zeilen van de afdeling?Neem dan contact met ons op!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/ruimteenmobiliteit\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ruimte en Mobiliteit &#8212; Contact\" \/>\n<meta property=\"og:description\" content=\"Benieuwd naar wat de thema-afdeling jouw te bieden heeft? Wil je een keer een bijeenkomst bijwonen of, nog beter, wil jij een interessante bijeenkomst organiseren? Heb jij interesse in een bestuursfuctie en wil je meer weten over het reilen en zeilen van de afdeling?Neem dan contact met ons op!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/ruimteenmobiliteit\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Ruimte en Mobiliteit\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-28T12:49:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/contact\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/contact\\\/\",\"name\":\"Ruimte en Mobiliteit &#8212; Contact\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/#website\"},\"datePublished\":\"2021-11-26T12:12:58+00:00\",\"dateModified\":\"2023-06-28T12:49:06+00:00\",\"description\":\"Benieuwd naar wat de thema-afdeling jouw te bieden heeft? Wil je een keer een bijeenkomst bijwonen of, nog beter, wil jij een interessante bijeenkomst organiseren? Heb jij interesse in een bestuursfuctie en wil je meer weten over het reilen en zeilen van de afdeling?Neem dan contact met ons op!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/contact\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/\",\"name\":\"Ruimte en Mobiliteit\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/template14okt1966\\\/wp-content\\\/uploads\\\/sites\\\/418\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/template14okt1966\\\/wp-content\\\/uploads\\\/sites\\\/418\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/ruimteenmobiliteit\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ruimte en Mobiliteit &#8212; Contact","description":"Benieuwd naar wat de thema-afdeling jouw te bieden heeft? Wil je een keer een bijeenkomst bijwonen of, nog beter, wil jij een interessante bijeenkomst organiseren? Heb jij interesse in een bestuursfuctie en wil je meer weten over het reilen en zeilen van de afdeling?Neem dan contact met ons op!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/ruimteenmobiliteit\/contact\/","og_locale":"nl_NL","og_type":"article","og_title":"Ruimte en Mobiliteit &#8212; Contact","og_description":"Benieuwd naar wat de thema-afdeling jouw te bieden heeft? Wil je een keer een bijeenkomst bijwonen of, nog beter, wil jij een interessante bijeenkomst organiseren? Heb jij interesse in een bestuursfuctie en wil je meer weten over het reilen en zeilen van de afdeling?Neem dan contact met ons op!","og_url":"https:\/\/d66.nl\/ruimteenmobiliteit\/contact\/","og_site_name":"Ruimte en Mobiliteit","article_modified_time":"2023-06-28T12:49:06+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/contact\/","url":"https:\/\/d66.nl\/ruimteenmobiliteit\/contact\/","name":"Ruimte en Mobiliteit &#8212; Contact","isPartOf":{"@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/#website"},"datePublished":"2021-11-26T12:12:58+00:00","dateModified":"2023-06-28T12:49:06+00:00","description":"Benieuwd naar wat de thema-afdeling jouw te bieden heeft? Wil je een keer een bijeenkomst bijwonen of, nog beter, wil jij een interessante bijeenkomst organiseren? Heb jij interesse in een bestuursfuctie en wil je meer weten over het reilen en zeilen van de afdeling?Neem dan contact met ons op!","breadcrumb":{"@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/contact\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/ruimteenmobiliteit\/contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/ruimteenmobiliteit\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/#website","url":"https:\/\/d66.nl\/ruimteenmobiliteit\/","name":"Ruimte en Mobiliteit","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/ruimteenmobiliteit\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/#organization","name":"D66","url":"https:\/\/d66.nl\/ruimteenmobiliteit\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/template14okt1966\/wp-content\/uploads\/sites\/418\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/template14okt1966\/wp-content\/uploads\/sites\/418\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/ruimteenmobiliteit\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/pages\/427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/comments?post=427"}],"version-history":[{"count":6,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/pages\/427\/revisions"}],"predecessor-version":[{"id":692,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/pages\/427\/revisions\/692"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/media?parent=427"}],"wp:term":[{"taxonomy":"themes-or-point-of-view","embeddable":true,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/themes-or-point-of-view?post=427"},{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/labels?post=427"},{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/ruimteenmobiliteit\/wp-json\/wp\/v2\/search-tags?post=427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}