{"id":1302,"date":"2026-05-05T16:25:28","date_gmt":"2026-05-05T16:25:28","guid":{"rendered":"https:\/\/d66.nl\/route66\/?post_type=people-type&#038;p=1302"},"modified":"2026-05-06T10:49:48","modified_gmt":"2026-05-06T10:49:48","slug":"fien-van-solinge","status":"publish","type":"people-type","link":"https:\/\/d66.nl\/route66\/mensen\/fien-van-solinge\/","title":{"rendered":"Fien van Solinge"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--66 wrapper__spacing-bottom-mobile--76  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading heading__align--left heading__color--black heading__size--giant heading__font--serif heading__weight--regular  block-heading__heading\" id=\"nav-fien-van-solinge1149\"  data-nav-heading-mobile=\"Fien van Solinge\" >\n\tFien van Solinge<\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--110 wrapper__spacing-bottom-desktop--60 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<section class=\"block-video\">\n\t<div\n\t\tclass=\"block-video__video-wrapper\"\n\t\tstyle=\"background-image: url('https:\/\/media.d66.nl\/uploads\/sites\/400\/2026\/05\/fien.jpg')\"\n\t>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"block-video__caption-wrapper\">\n\t\t\t<div class=\"block-video__caption\">\n\t\t\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--small paragraph__weight--medium\">\n\t\tBeeld: Priv\u00e9foto\t<\/p>\t\t\t<\/div>\n\t\t<\/div>\n\t\n<\/section>\n\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-people-introduction\">\n\t<div class=\"block-people-introduction__content\">\n\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--big\">\n\t\t\t<\/p><section class=\"people-bullet-point-card block-people-introduction__people-bullet-point-card\" style=\"--bg-color: var(--global-colors-texasRose)\">\n\t<div class=\"people-bullet-point-card__wrapper\">\n\t\t<div class=\"people-bullet-point-card__title\">\n\t\t\t<h2 class=\"heading    heading__font--sans heading__weight--bold\" id=\"nav-over-fien5422\" data-nav-heading-mobile=\"Over Fien\">\n\tOver Fien<\/h2>\t\t\t<div aria-hidden=\"true\" class=\"people-bullet-point-card__border\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"people-bullet-point-card__info\">\n\t\t\t<ul class=\"lists\">\n\t\t\t\t\t\t\t\t\t\t\t\t<li><label>Woonplaats<\/label><span>Den Haag<\/span><\/li>\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section><p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default\">\n\t\t\t<\/p><div class=\"content-accordion js-content-accordion\" data-accordion-opened=\"0\">\n\n\t\n\t<button id=\"content-accordion-trigger-971475091\" class=\"content-accordion__trigger js-content-accordion-trigger\" aria-label=\"Functie historie\" aria-controls>\n\t\t<div class=\"content-accordion__heading\">\n\t\t\t<h3 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-functie-historie8533\">\n\tFunctie historie<\/h3>\t\t<\/div>\n\t\t<div class=\"content-accordion__icon\" aria-hidden=\"true\"><\/div>\n\t<\/button>\n\n\t<section id=\"content-accordion-panel-971475091\" class=\"content-accordion__panel js-content-accordion-panel\" aria-hidden=\"true\" aria-labelledby=\"content-accordion-trigger-971475091\">\n\t\t<div class=\"content-accordion__content-wrapper\">\n\t\t\t<div class=\"content-accordion__description\">\n\t\t\t\t<ul class=\"content-accordion lists content-accordion__lists lists__weight--medium lists__color--black lists__type--default\"><li><label><\/label><span>Bestuurlijk Adviseur bij het Ministerie van Financi\u00ebn<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n\t<div aria-hidden=\"true\" class=\"content-accordion__border\"><\/div>\n<\/div>\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"author":2201,"featured_media":1304,"menu_order":0,"template":"","search-tags":[],"labels":[],"division-tags":[],"class_list":["post-1302","people-type","type-people-type","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Route66 &#8212; Onze mensen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/route66\/mensen\/fien-van-solinge\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Route66 &#8212; Onze mensen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/route66\/mensen\/fien-van-solinge\/\" \/>\n<meta property=\"og:site_name\" content=\"Route66\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T10:49:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.d66.nl\/uploads\/sites\/400\/2026\/05\/fien.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"239\" \/>\n\t<meta property=\"og:image:height\" content=\"239\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/route66\\\/mensen\\\/fien-van-solinge\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/route66\\\/mensen\\\/fien-van-solinge\\\/\",\"name\":\"Route66 &#8212; Onze mensen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/route66\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/route66\\\/mensen\\\/fien-van-solinge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/route66\\\/mensen\\\/fien-van-solinge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/400\\\/2026\\\/05\\\/fien.jpg\",\"datePublished\":\"2026-05-05T16:25:28+00:00\",\"dateModified\":\"2026-05-06T10:49:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/route66\\\/mensen\\\/fien-van-solinge\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/route66\\\/mensen\\\/fien-van-solinge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/route66\\\/mensen\\\/fien-van-solinge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/400\\\/2026\\\/05\\\/fien.jpg\",\"contentUrl\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/400\\\/2026\\\/05\\\/fien.jpg\",\"width\":239,\"height\":239},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/route66\\\/mensen\\\/fien-van-solinge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/route66\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mensen\",\"item\":\"https:\\\/\\\/d66.nl\\\/route66\\\/mensen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fien van Solinge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/route66\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/route66\\\/\",\"name\":\"Route66\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/route66\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/route66\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/route66\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/route66\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/route66\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/route66\\\/wp-content\\\/uploads\\\/sites\\\/400\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/route66\\\/wp-content\\\/uploads\\\/sites\\\/400\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/route66\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Route66 &#8212; Onze mensen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/route66\/mensen\/fien-van-solinge\/","og_locale":"nl_NL","og_type":"article","og_title":"Route66 &#8212; Onze mensen","og_url":"https:\/\/d66.nl\/route66\/mensen\/fien-van-solinge\/","og_site_name":"Route66","article_modified_time":"2026-05-06T10:49:48+00:00","og_image":[{"width":239,"height":239,"url":"https:\/\/media.d66.nl\/uploads\/sites\/400\/2026\/05\/fien.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/route66\/mensen\/fien-van-solinge\/","url":"https:\/\/d66.nl\/route66\/mensen\/fien-van-solinge\/","name":"Route66 &#8212; Onze mensen","isPartOf":{"@id":"https:\/\/d66.nl\/route66\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d66.nl\/route66\/mensen\/fien-van-solinge\/#primaryimage"},"image":{"@id":"https:\/\/d66.nl\/route66\/mensen\/fien-van-solinge\/#primaryimage"},"thumbnailUrl":"https:\/\/media.d66.nl\/uploads\/sites\/400\/2026\/05\/fien.jpg","datePublished":"2026-05-05T16:25:28+00:00","dateModified":"2026-05-06T10:49:48+00:00","breadcrumb":{"@id":"https:\/\/d66.nl\/route66\/mensen\/fien-van-solinge\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/route66\/mensen\/fien-van-solinge\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/route66\/mensen\/fien-van-solinge\/#primaryimage","url":"https:\/\/media.d66.nl\/uploads\/sites\/400\/2026\/05\/fien.jpg","contentUrl":"https:\/\/media.d66.nl\/uploads\/sites\/400\/2026\/05\/fien.jpg","width":239,"height":239},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/route66\/mensen\/fien-van-solinge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/route66\/"},{"@type":"ListItem","position":2,"name":"Mensen","item":"https:\/\/d66.nl\/route66\/mensen\/"},{"@type":"ListItem","position":3,"name":"Fien van Solinge"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/route66\/#website","url":"https:\/\/d66.nl\/route66\/","name":"Route66","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/route66\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/route66\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/route66\/#organization","name":"D66","url":"https:\/\/d66.nl\/route66\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/route66\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/route66\/wp-content\/uploads\/sites\/400\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/route66\/wp-content\/uploads\/sites\/400\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/route66\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/route66\/wp-json\/wp\/v2\/people-type\/1302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/route66\/wp-json\/wp\/v2\/people-type"}],"about":[{"href":"https:\/\/d66.nl\/route66\/wp-json\/wp\/v2\/types\/people-type"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/route66\/wp-json\/wp\/v2\/users\/2201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d66.nl\/route66\/wp-json\/wp\/v2\/media\/1304"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/route66\/wp-json\/wp\/v2\/media?parent=1302"}],"wp:term":[{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/route66\/wp-json\/wp\/v2\/search-tags?post=1302"},{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/route66\/wp-json\/wp\/v2\/labels?post=1302"},{"taxonomy":"division-tags","embeddable":true,"href":"https:\/\/d66.nl\/route66\/wp-json\/wp\/v2\/division-tags?post=1302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}