{"id":947,"date":"2025-03-01T16:06:45","date_gmt":"2025-03-01T16:06:45","guid":{"rendered":"https:\/\/d66.nl\/pride66\/?post_type=people-type&#038;p=947"},"modified":"2025-03-01T16:08:37","modified_gmt":"2025-03-01T16:08:37","slug":"alexander-scholtes","status":"publish","type":"people-type","link":"https:\/\/d66.nl\/pride66\/mensen\/alexander-scholtes\/","title":{"rendered":"Alexander Scholtes"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--66 wrapper__spacing-bottom-mobile--76  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading heading__align--left heading__color--black heading__size--giant heading__font--serif heading__weight--regular  block-heading__heading\" id=\"nav-alexander-scholtes8476\"  data-nav-heading-mobile=\"Alexander Scholtes\" >\n\tAlexander Scholtes<\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--110 wrapper__spacing-bottom-desktop--60 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<section class=\"block-video\">\n\t<div\n\t\tclass=\"block-video__video-wrapper\"\n\t\tstyle=\"background-image: url('https:\/\/d66.nl\/pride66\/wp-content\/uploads\/sites\/435\/2025\/03\/HR-Alexander_9212-1-768x1250-1.jpg')\"\n\t>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"block-video__caption-wrapper\">\n\t\t\t<div class=\"block-video__caption\">\n\t\t\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--small paragraph__weight--medium\">\n\t\t<b>Alexander Scholtes<\/b> <i>&#045;<\/i> Beeld: D66 Amsterdam\t<\/p>\t\t\t<\/div>\n\t\t<\/div>\n\t\n<\/section>\n\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-people-introduction\">\n\t<div class=\"block-people-introduction__content\">\n\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--big\">\n\t\tAlexander Scholtes is wethouder van de gemeente Amsterdam, verantwoordelijk voor onder andere zorg, volksgezondheid, de digitale stad, deelnemingen en monumenten.\t<\/p><section class=\"people-bullet-point-card block-people-introduction__people-bullet-point-card\" style=\"--bg-color: var(--global-colors-texasRose)\">\n\t<div class=\"people-bullet-point-card__wrapper\">\n\t\t<div class=\"people-bullet-point-card__title\">\n\t\t\t<h2 class=\"heading    heading__font--sans heading__weight--bold\" id=\"nav-over-alexander5996\" data-nav-heading-mobile=\"Over Alexander\">\n\tOver Alexander<\/h2>\t\t\t<div aria-hidden=\"true\" class=\"people-bullet-point-card__border\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"people-bullet-point-card__info\">\n\t\t\t<ul class=\"lists\">\n\t\t\t\t<li><label>Leeftijd<\/label><span>43 jaar<\/span><\/li>\t\t\t\t<li><label>Geboorteplaats<\/label><span>Nijmegen<\/span><\/li>\t\t\t\t<li><label>Woonplaats<\/label><span>Amsterdam<\/span><\/li>\t\t\t\t<li><label>Voornaamwoorden<\/label><span>Hij\/hem<\/span><\/li>\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div aria-hidden=\"true\" class=\"people-bullet-point-card__border\"><\/div>\n\t\t\t<div class=\"people-bullet-point-card__socialmedia\">\n\t\t\t\t<ul class=\"people-bullet-point-card__sm_panel\"><li><a href=\"https:\/\/www.instagram.com\/alexanderscholtes\/\" target=\"_blank\">Ig<\/a><\/li><li><a href=\"https:\/\/www.linkedin.com\/in\/alexanderscholtes\/\" target=\"_blank\">Li<\/a><\/li><\/ul>\t\t\t<\/div>\n\t\t\n\t\t\t<\/div>\n<\/section><p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default\">\n\t\tAls middelbare scholier had Alexander al een mening over de gemeentepolitiek. Zijn lokale D66 gaf hem toen de kans verantwoordelijkheid te nemen en sindsdien is hij altijd bij de partij gebleven.<br><br>Delen van de regenbooggemeenschap komen vaak terug in zijn werk, bijvoorbeeld in de portefeuille volksgezondheid. De gemeente doet investeringen in PrEP en seksuele gezondheid, werkt aan de ambitie voor nul nieuwe hiv-infecties in 2026 en voor een transkliniek bij de GGD. <br><br>Als het gaat om mentale gezondheid werkt Amsterdam samen met allerlei gemeenschappen die het belangrijk vinden dit onderwerp beter bespreekbaar te maken. Dat betreft dus ook delen van de regenbooggemeenschap die daar behoefte aan hebben.<br><br><strong>Wat zie je als grootste uitdaging voor onze gemeenschap op dit moment?<\/strong><br><br>Conservatieve gedachten onder (een deel van de) jongere generaties ten aanzien van seksuele- en genderdiversiteit. Dit wordt ook aangewakkerd door rechts-conservatieve politici en influencers op social media. Mensen krijgen van hen het gevoel dat er iets van hen wordt afgepakt als de regenbooggemeenschap pleit voor gelijke rechten en waardigheid. Daar maak ik me echt zorgen over.<br><br><strong>Waarom moeten mensen lid worden van PRIDE66 volgens jou?<\/strong><br><br>Omdat we elkaar nodig hebben en we elkaar scherp moeten houden.\t<\/p><div class=\"content-accordion js-content-accordion\" data-accordion-opened=\"0\">\n\n\t\n\t<button id=\"content-accordion-trigger-1279035414\" class=\"content-accordion__trigger js-content-accordion-trigger\" aria-label=\"Functie historie\" aria-controls>\n\t\t<div class=\"content-accordion__heading\">\n\t\t\t<h3 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-functie-historie7560\">\n\tFunctie historie<\/h3>\t\t<\/div>\n\t\t<div class=\"content-accordion__icon\" aria-hidden=\"true\"><\/div>\n\t<\/button>\n\n\t<section id=\"content-accordion-panel-1279035414\" class=\"content-accordion__panel js-content-accordion-panel\" aria-hidden=\"true\" aria-labelledby=\"content-accordion-trigger-1279035414\">\n\t\t<div class=\"content-accordion__content-wrapper\">\n\t\t\t<div class=\"content-accordion__description\">\n\t\t\t\t<ul class=\"content-accordion lists content-accordion__lists lists__weight--medium lists__color--black lists__type--default\"><li><label>2023\u2013heden<\/label><span>gemeenteraadslid D66 Amsterdam<\/span><\/li><li><label>2022\u20132023<\/label><span>voorzitter dagelijks bestuur, stadsdeel Amsterdam Centrum<\/span><\/li><li><label>2014\u20132018<\/label><span>politiek adviseur wethouder gemeente Amsterdam Kajsa Ollongren<\/span><\/li><li><label>2006\u20132014<\/label><span>deelraadslid D66 Amsterdam<\/span><\/li><li><label>2007\u20132009<\/label><span>beleidsmedewerker en voorlichter gemeenteraadsfractie D66 Amsterdam<\/span><\/li><li><label>2006\u20132007<\/label><span>persoonlijk medewerker, Tweede Kamerfractie D66<\/span><\/li><li><label>2004\u20132005<\/label><span>landelijk bestuur, Jonge Democraten<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n\t<div aria-hidden=\"true\" class=\"content-accordion__border\"><\/div>\n<\/div>\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"author":1522,"featured_media":948,"menu_order":0,"template":"","search-tags":[],"labels":[],"division-tags":[33],"class_list":["post-947","people-type","type-people-type","status-publish","has-post-thumbnail","hentry","division-tags-ambassadeurs"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRIDE66 &#8212; Onze mensen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/pride66\/mensen\/alexander-scholtes\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRIDE66 &#8212; Onze mensen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/pride66\/mensen\/alexander-scholtes\/\" \/>\n<meta property=\"og:site_name\" content=\"PRIDE66\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-01T16:08:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d66.nl\/pride66\/wp-content\/uploads\/sites\/435\/2025\/03\/HR-Alexander_9212-1-768x1250-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/mensen\\\/alexander-scholtes\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/mensen\\\/alexander-scholtes\\\/\",\"name\":\"PRIDE66 &#8212; Onze mensen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/mensen\\\/alexander-scholtes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/mensen\\\/alexander-scholtes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/wp-content\\\/uploads\\\/sites\\\/435\\\/2025\\\/03\\\/HR-Alexander_9212-1-768x1250-1.jpg\",\"datePublished\":\"2025-03-01T16:06:45+00:00\",\"dateModified\":\"2025-03-01T16:08:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/mensen\\\/alexander-scholtes\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/pride66\\\/mensen\\\/alexander-scholtes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/mensen\\\/alexander-scholtes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/wp-content\\\/uploads\\\/sites\\\/435\\\/2025\\\/03\\\/HR-Alexander_9212-1-768x1250-1.jpg\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/wp-content\\\/uploads\\\/sites\\\/435\\\/2025\\\/03\\\/HR-Alexander_9212-1-768x1250-1.jpg\",\"width\":768,\"height\":1250,\"caption\":\"Alexander Scholtes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/mensen\\\/alexander-scholtes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mensen\",\"item\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/mensen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alexander Scholtes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/\",\"name\":\"PRIDE66\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/wp-content\\\/uploads\\\/sites\\\/435\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/wp-content\\\/uploads\\\/sites\\\/435\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/pride66\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRIDE66 &#8212; Onze mensen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/pride66\/mensen\/alexander-scholtes\/","og_locale":"nl_NL","og_type":"article","og_title":"PRIDE66 &#8212; Onze mensen","og_url":"https:\/\/d66.nl\/pride66\/mensen\/alexander-scholtes\/","og_site_name":"PRIDE66","article_modified_time":"2025-03-01T16:08:37+00:00","og_image":[{"width":768,"height":1250,"url":"https:\/\/d66.nl\/pride66\/wp-content\/uploads\/sites\/435\/2025\/03\/HR-Alexander_9212-1-768x1250-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/pride66\/mensen\/alexander-scholtes\/","url":"https:\/\/d66.nl\/pride66\/mensen\/alexander-scholtes\/","name":"PRIDE66 &#8212; Onze mensen","isPartOf":{"@id":"https:\/\/d66.nl\/pride66\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d66.nl\/pride66\/mensen\/alexander-scholtes\/#primaryimage"},"image":{"@id":"https:\/\/d66.nl\/pride66\/mensen\/alexander-scholtes\/#primaryimage"},"thumbnailUrl":"https:\/\/d66.nl\/pride66\/wp-content\/uploads\/sites\/435\/2025\/03\/HR-Alexander_9212-1-768x1250-1.jpg","datePublished":"2025-03-01T16:06:45+00:00","dateModified":"2025-03-01T16:08:37+00:00","breadcrumb":{"@id":"https:\/\/d66.nl\/pride66\/mensen\/alexander-scholtes\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/pride66\/mensen\/alexander-scholtes\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/pride66\/mensen\/alexander-scholtes\/#primaryimage","url":"https:\/\/d66.nl\/pride66\/wp-content\/uploads\/sites\/435\/2025\/03\/HR-Alexander_9212-1-768x1250-1.jpg","contentUrl":"https:\/\/d66.nl\/pride66\/wp-content\/uploads\/sites\/435\/2025\/03\/HR-Alexander_9212-1-768x1250-1.jpg","width":768,"height":1250,"caption":"Alexander Scholtes"},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/pride66\/mensen\/alexander-scholtes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/pride66\/"},{"@type":"ListItem","position":2,"name":"Mensen","item":"https:\/\/d66.nl\/pride66\/mensen\/"},{"@type":"ListItem","position":3,"name":"Alexander Scholtes"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/pride66\/#website","url":"https:\/\/d66.nl\/pride66\/","name":"PRIDE66","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/pride66\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/pride66\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/pride66\/#organization","name":"D66","url":"https:\/\/d66.nl\/pride66\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/pride66\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/pride66\/wp-content\/uploads\/sites\/435\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/pride66\/wp-content\/uploads\/sites\/435\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/pride66\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/pride66\/wp-json\/wp\/v2\/people-type\/947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/pride66\/wp-json\/wp\/v2\/people-type"}],"about":[{"href":"https:\/\/d66.nl\/pride66\/wp-json\/wp\/v2\/types\/people-type"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/pride66\/wp-json\/wp\/v2\/users\/1522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d66.nl\/pride66\/wp-json\/wp\/v2\/media\/948"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/pride66\/wp-json\/wp\/v2\/media?parent=947"}],"wp:term":[{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/pride66\/wp-json\/wp\/v2\/search-tags?post=947"},{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/pride66\/wp-json\/wp\/v2\/labels?post=947"},{"taxonomy":"division-tags","embeddable":true,"href":"https:\/\/d66.nl\/pride66\/wp-json\/wp\/v2\/division-tags?post=947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}