{"id":3049,"date":"2023-10-16T19:10:34","date_gmt":"2023-10-16T19:10:34","guid":{"rendered":"https:\/\/d66.nl\/noordholland\/?post_type=people-type&#038;p=3049"},"modified":"2025-06-03T14:49:12","modified_gmt":"2025-06-03T14:49:12","slug":"friso-le-poole","status":"publish","type":"people-type","link":"https:\/\/d66.nl\/noordholland\/mensen\/friso-le-poole\/","title":{"rendered":"Friso Le Poole"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--66 wrapper__spacing-bottom-mobile--76  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading   heading__size--giant heading__font--serif heading__weight--regular  block-heading__heading\" id=\"nav-friso-le-poole3242\"  data-nav-heading-mobile=\"Friso Le Poole\" >\n\tFriso Le Poole<\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--110 wrapper__spacing-bottom-desktop--60 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<section class=\"block-video\">\n\t<div\n\t\tclass=\"block-video__video-wrapper\"\n\t\tstyle=\"background-image: url('https:\/\/d66.nl\/noordholland\/wp-content\/uploads\/sites\/340\/2024\/05\/20240715_221802-scaled.jpg')\"\n\t>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"block-video__caption-wrapper\">\n\t\t\t<div class=\"block-video__caption\">\n\t\t\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--small paragraph__weight--medium\">\n\t\t<b>Friso Le Poole<\/b> <i>&#045;<\/i> Beeld: Dennis Drenth\t<\/p>\t\t\t<\/div>\n\t\t<\/div>\n\t\n<\/section>\n\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-people-introduction\">\n\t<div class=\"block-people-introduction__content\">\n\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--big\">\n\t\tIn augustus 2023 is Friso Le Poole door de leden gekozen als regiobestuurslid campagne voor D66 Noord-Holland. <br>\t<\/p><section class=\"people-bullet-point-card block-people-introduction__people-bullet-point-card\" style=\"--bg-color: var(--global-colors-texasRose)\">\n\t<div class=\"people-bullet-point-card__wrapper\">\n\t\t<div class=\"people-bullet-point-card__title\">\n\t\t\t<h2 class=\"heading    heading__font--sans heading__weight--bold\" id=\"nav-over-friso5141\" data-nav-heading-mobile=\"Over Friso\">\n\tOver Friso<\/h2>\t\t\t<div aria-hidden=\"true\" class=\"people-bullet-point-card__border\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"people-bullet-point-card__info\">\n\t\t\t<ul class=\"lists\">\n\t\t\t\t<li><label>Leeftijd<\/label><span>19 jaar<\/span><\/li>\t\t\t\t<li><label>Geboorteplaats<\/label><span>Haarlem<\/span><\/li>\t\t\t\t<li><label>Woonplaats<\/label><span>Bloemendaal<\/span><\/li>\t\t\t\t<li><label>Voornaamwoorden<\/label><span>Hij\/hem<\/span><\/li>\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"people-bullet-point-card__email\">\n\t\t\t\t<span>\n\t\t\t\t\tStuur Friso een <a href=\"mailto:friso.lepoole@gmail.com\">e-mail<\/a>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div aria-hidden=\"true\" class=\"people-bullet-point-card__border\"><\/div>\n\t\t\t<div class=\"people-bullet-point-card__socialmedia\">\n\t\t\t\t<ul class=\"people-bullet-point-card__sm_panel\"><li><a href=\"https:\/\/www.linkedin.com\/in\/friso-le-poole-b538b8231\/\" target=\"_blank\">Li<\/a><\/li><li><a href=\"https:\/\/www.instagram.com\/frisolepoole\/\" target=\"_blank\">Ig<\/a><\/li><\/ul>\t\t\t<\/div>\n\t\t\n\t\t\t<\/div>\n<\/section><p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default\">\n\t\t\t<\/p><div class=\"content-accordion js-content-accordion\" data-accordion-opened=\"0\">\n\n\t\t\t<div aria-hidden=\"true\" class=\"content-accordion__border\"><\/div>\n\t\n\t<button id=\"content-accordion-trigger-4187555906\" class=\"content-accordion__trigger js-content-accordion-trigger\" aria-label=\"Expertises (portefeuilles)\" aria-controls>\n\t\t<div class=\"content-accordion__heading\">\n\t\t\t<h3 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-expertises--portefeuilles-2938\">\n\tExpertises (portefeuilles)<\/h3>\t\t<\/div>\n\t\t<div class=\"content-accordion__icon\" aria-hidden=\"true\"><\/div>\n\t<\/button>\n\n\t<section id=\"content-accordion-panel-4187555906\" class=\"content-accordion__panel js-content-accordion-panel\" aria-hidden=\"true\" aria-labelledby=\"content-accordion-trigger-4187555906\">\n\t\t<div class=\"content-accordion__content-wrapper\">\n\t\t\t<div class=\"content-accordion__description\">\n\t\t\t\tCampagne\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n\t<div aria-hidden=\"true\" class=\"content-accordion__border\"><\/div>\n<\/div><div class=\"content-accordion js-content-accordion\" data-accordion-opened=\"0\">\n\n\t\n\t<button id=\"content-accordion-trigger-3298895740\" class=\"content-accordion__trigger js-content-accordion-trigger\" aria-label=\"Functie historie\" aria-controls>\n\t\t<div class=\"content-accordion__heading\">\n\t\t\t<h3 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-functie-historie16\">\n\tFunctie historie<\/h3>\t\t<\/div>\n\t\t<div class=\"content-accordion__icon\" aria-hidden=\"true\"><\/div>\n\t<\/button>\n\n\t<section id=\"content-accordion-panel-3298895740\" class=\"content-accordion__panel js-content-accordion-panel\" aria-hidden=\"true\" aria-labelledby=\"content-accordion-trigger-3298895740\">\n\t\t<div class=\"content-accordion__content-wrapper\">\n\t\t\t<div class=\"content-accordion__description\">\n\t\t\t\t<ul class=\"content-accordion lists content-accordion__lists lists__weight--medium lists__color--black lists__type--default\"><li><label>2022 &#8211; 2024<\/label><span>Fractieondersteuner D66 Bloemendaal<\/span><\/li><li><label>2022 &#8211; 2023<\/label><span>Bestuurslid Pers en Politiek Jonge Democraten Amsterdam<\/span><\/li><li><label>2023 &#8211; heden<\/label><span>Bestuurslid Campagne D66 Noord-Holland<\/span><\/li><li><label>2023 <\/label><span>Regioco\u00f6rdinator Landelijk Bureau D66<\/span><\/li><li><label>2025 &#8211; heden<\/label><span>International Officer JD<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n\t<div aria-hidden=\"true\" class=\"content-accordion__border\"><\/div>\n<\/div>\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--20  wrapper__gutter--default\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--10 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t\n<div class=\"block-infographics block-infographics--with-wrapper\">\n\t\t\t\t\t<div class=\"block-infographics__wrapper\" style=\"--bg-color: var(--global-colors-international);\">\n\t\t\t<div class=\"block-infographics__media\">\n\t\t\t\t\t\t\t\t<span class=\"block-infographics__media-icon\">\n\t\t\t\t\t<i class=\"icon\">\n\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='507' height='365.069' viewBox='0 0 507 365.069'><g data-name='Group 843'><g data-name='Group 87' transform='translate(591.229 175.884)' fill='none' stroke='#000' stroke-linecap='round' stroke-linejoin='round' stroke-width='7'><path data-name='Path 65' d='m-451.737 64.092-1.765-.546a105.2 105.2 0 0 0-14.412-3.37 143.93 143.93 0 0 0-21.823-1.646 126.65 126.65 0 0 0-35.992 4.935c-21.488 6.458-40.045 20.058-50.91 37.309-7.67 12.195-11.089 26.015-11.089 44.805v40.1' fill='none'\/><path data-name='Path 66' d='m-223.719 64.092 1.765-.546a105.151 105.151 0 0 1 14.412-3.37 143.931 143.931 0 0 1 21.823-1.646 126.641 126.641 0 0 1 35.99 4.935c21.49 6.458 40.049 20.058 50.912 37.309 7.67 12.195 11.089 26.015 11.089 44.805v40.1' fill='none'\/><path data-name='Path 67' d='M-212.122 185.538v-36c0-3.074.056-6.189.114-9.323.181-9.946.369-20.233-1.264-30.018-6.238-37.162-36.541-69.631-77.2-82.724-16.963-5.563-34-6.7-54.37-6.7-21.771 0-41.781 4.178-59.474 12.417-38.777 18.373-63.108 53.482-63.509 91.615-.095 13.563-.062 27.287-.031 40.564q.023 10.141.031 20.308' fill='none'\/><circle data-name='Ellipse 2' cx='80.47' cy='80.47' r='80.47' transform='translate(-417.72 -172.384)' fill='none'\/><circle data-name='Ellipse 3' cx='52.666' cy='52.666' r='52.666' transform='translate(-231.951 -78.639)' fill='none'\/><circle data-name='Ellipse 4' cx='52.666' cy='52.666' r='52.666' transform='translate(-547.906 -78.639)' fill='none'\/><\/g><\/g><\/svg><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"block-infographics__content\">\n\t\t\t\t<span class=\"block-infographics__content-title\">\n\t\t\t\t\tAfdeling\t\t\t\t<\/span>\n\t\t\t\t<span class=\"block-infographics__content-text\">\n\t\t\t\t\tBij het bestuurslid campagne kan je als afdeling langskomen met vragen over de campagne of om een campagnetraining voor jou of je afdeling te regelen.  \t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"block-infographics__wrapper\" style=\"--bg-color: var(--global-colors-pixieGreen);\">\n\t\t\t<div class=\"block-infographics__media\">\n\t\t\t\t\t\t\t\t<span class=\"block-infographics__media-icon\">\n\t\t\t\t\t<i class=\"icon\">\n\t<svg data-name='Group 1090' xmlns='http:\/\/www.w3.org\/2000\/svg' width='574.824' height='613.145' viewBox='0 0 574.824 613.145'><defs><clipPath id='e60cea2a-cf71-4dca-a621-9c4216892f36'><path data-name='Rectangle 338' fill='none' stroke='#000' stroke-width='7' d='M0 0h574.824v613.145H0z'\/><\/clipPath><\/defs><g data-name='Group 1089' clip-path='url(#e60cea2a-cf71-4dca-a621-9c4216892f36)' fill='none' stroke='#000' stroke-linecap='round' stroke-linejoin='round' stroke-width='7'><path data-name='Path 2939' d='M533.656 184.61v-24.861a15.907 15.907 0 1 0-31.813 0v-20.652a15.907 15.907 0 1 0-31.814 0v20.652a15.905 15.905 0 1 0-31.809 0v56.332h-.167l.148 21.129.051-4.113.12 32.68s-13.533-5.312-14.7-5.845c-1.584-.727-12.357-14.1-18.693-22.958a16.017 16.017 0 0 0-28.345 14.923l23.6 33.013 54.748 60.149-13.96 187.643' fill='none'\/><path data-name='Path 2940' d='m562.898 532.701-13.894-187.834 16.56-26.315V215.544h-.153v-30.818a15.856 15.856 0 1 0-31.712 0' fill='none'\/><path data-name='Line 488' d='M470.032 159.749v61.807' fill='none'\/><path data-name='Line 489' d='M501.769 159.749v65.484' fill='none'\/><path data-name='Path 2941' d='M437.979 265.688a64.772 64.772 0 0 1 38.436 35' fill='none'\/><path data-name='Line 490' d='M533.709 185.45v46.18' fill='none'\/><path data-name='Path 2942' d='M41.169 184.61v-24.861a15.907 15.907 0 1 1 31.813 0v-20.652a15.907 15.907 0 1 1 31.813 0v20.652a15.905 15.905 0 1 1 31.809 0v56.332h.167l-.148 21.129-.051-4.113-.12 32.68s13.533-5.312 14.7-5.845c1.584-.727 12.357-14.1 18.693-22.958a16.016 16.016 0 0 1 28.335 14.922l-23.6 33.013-54.75 60.149 13.973 187.644' fill='none'\/><path data-name='Path 2943' d='M11.926 532.701 25.82 344.867 9.263 318.552V215.544h.153v-30.818a15.856 15.856 0 1 1 31.712 0' fill='none'\/><path data-name='Line 491' d='M104.792 159.749v61.807' fill='none'\/><path data-name='Line 492' d='M73.055 159.749v65.484' fill='none'\/><path data-name='Path 2944' d='M136.845 265.688a64.772 64.772 0 0 0-38.436 35' fill='none'\/><path data-name='Line 493' d='M41.115 185.45v46.18' fill='none'\/><path data-name='Path 2945' d='M256.319 57.643v-19.58a12.528 12.528 0 1 1 25.056 0V21.791a12.53 12.53 0 0 1 25.061 0v16.272a12.528 12.528 0 1 1 25.056 0v44.368h.13l-.116 16.641-.042-3.237-.1 25.742s10.662-4.187 11.579-4.608c1.246-.57 9.731-11.106 14.723-18.077a12.616 12.616 0 1 1 22.328 11.75l-18.6 26-43.118 47.38 9.11 137.906' fill='none'\/><path data-name='Path 2946' d='m234.134 321.923 10.1-138.059-13.041-20.725V82h.12V57.726a12.489 12.489 0 1 1 24.977 0' fill='none'\/><path data-name='Line 494' d='M306.435 38.058v48.681' fill='none'\/><path data-name='Line 495' d='M281.437 38.058v51.581' fill='none'\/><path data-name='Path 2947' d='M331.682 121.502a51.014 51.014 0 0 0-30.276 27.566' fill='none'\/><path data-name='Line 496' d='M256.279 58.301v36.375' fill='none'\/><path data-name='Path 2948' d='M336.031 399.713v-24.864a15.907 15.907 0 1 0-31.814 0V354.2a15.907 15.907 0 1 0-31.813 0v20.649a15.905 15.905 0 1 0-31.809 0v56.332h-.167l.148 21.129.051-4.117.12 32.684s-13.533-5.312-14.7-5.845c-1.584-.727-12.357-14.1-18.693-22.958a16.016 16.016 0 0 0-28.34 14.925l23.6 33.008 54.753 60.153-3.253 43.722' fill='none'\/><path data-name='Path 2949' d='m354.381 600.543-3-40.576 16.557-26.311V430.642h-.158v-30.816a15.854 15.854 0 1 0-31.707 0' fill='none'\/><path data-name='Line 497' d='M272.406 374.85v61.807' fill='none'\/><path data-name='Line 498' d='M304.144 374.85v65.484' fill='none'\/><path data-name='Path 2950' d='M240.358 480.792a64.777 64.777 0 0 1 38.432 35' fill='none'\/><path data-name='Line 499' d='M336.083 400.551v46.18' fill='none'\/><\/g><\/svg><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"block-infographics__content\">\n\t\t\t\t<span class=\"block-infographics__content-title\">\n\t\t\t\t\tIndividueel Lid\t\t\t\t<\/span>\n\t\t\t\t<span class=\"block-infographics__content-text\">\n\t\t\t\t\tLeden met interesse in campagne kunnen het bestuurslid campagne benaderen en gekoppeld worden aan een afdeling. Leden kunnen zich ook altijd aanmelden via team.d66.nl\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"block-infographics__wrapper\" style=\"--bg-color: var(--global-colors-illusion);\">\n\t\t\t<div class=\"block-infographics__media\">\n\t\t\t\t\t\t\t\t<span class=\"block-infographics__media-icon\">\n\t\t\t\t\t<i class=\"icon\">\n\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='412.639' height='340.548' viewBox='0 0 412.639 340.548'><g data-name='Group 217' fill='none' stroke='#000' stroke-miterlimit='10' stroke-width='7'><path data-name='Path 176' d='M333.097 3.5a75.609 75.609 0 0 0-53.757 22.26l-98.205 98.205a76.146 76.146 0 0 0-19.432 74.363 14.502 14.502 0 0 0 27.915-7.874 47.147 47.147 0 0 1 12.022-45.984l98.205-98.191a47.021 47.021 0 0 1 66.5 66.49l-98.205 98.205a46.874 46.874 0 0 1-23.521 12.746 14.5 14.5 0 0 0 3 28.7 14.344 14.344 0 0 0 3.016-.319 75.808 75.808 0 0 0 38.009-20.621l98.2-98.191A76.017 76.017 0 0 0 333.097 3.5z' fill='none'\/><path data-name='Path 177' d='M250.511 142.613a14.502 14.502 0 1 0-27.915 7.874 47.147 47.147 0 0 1-12.022 45.985l-98.205 98.2a47.02 47.02 0 0 1-66.5-66.489l98.205-98.219a46.79 46.79 0 0 1 23.493-12.746 14.502 14.502 0 0 0-5.688-28.44l-.287.06a75.912 75.912 0 0 0-38.022 20.621l-98.205 98.2a76.032 76.032 0 0 0 107.509 107.534l98.205-98.219a76.148 76.148 0 0 0 19.432-74.364z' fill='none'\/><\/g><\/svg><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"block-infographics__content\">\n\t\t\t\t<span class=\"block-infographics__content-title\">\n\t\t\t\t\tContact\t\t\t\t<\/span>\n\t\t\t\t<span class=\"block-infographics__content-text\">\n\t\t\t\t\tJe kan altijd mailen naar friso.lepoole@gmail.com of bellen\/appen naar +31683654168\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\n<\/div>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"author":1174,"featured_media":4032,"menu_order":0,"template":"","search-tags":[],"labels":[],"division-tags":[28],"class_list":["post-3049","people-type","type-people-type","status-publish","has-post-thumbnail","hentry","division-tags-regiobestuur"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D66 Noord-Holland &#8212; Friso Le Poole<\/title>\n<meta name=\"description\" content=\"Friso Le Poole is het regio-bestuurslid verantwoordelijk voor het co\u00f6rdineren van de campagne binnen Noord-Holland.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/noordholland\/mensen\/friso-le-poole\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D66 Noord-Holland &#8212; Friso Le Poole\" \/>\n<meta property=\"og:description\" content=\"Friso Le Poole is het regio-bestuurslid verantwoordelijk voor het co\u00f6rdineren van de campagne binnen Noord-Holland.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/noordholland\/mensen\/friso-le-poole\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Noord-Holland\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-03T14:49:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d66.nl\/noordholland\/wp-content\/uploads\/sites\/340\/2024\/05\/20240715_221802-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/mensen\\\/friso-le-poole\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/mensen\\\/friso-le-poole\\\/\",\"name\":\"D66 Noord-Holland &#8212; Friso Le Poole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/mensen\\\/friso-le-poole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/mensen\\\/friso-le-poole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/wp-content\\\/uploads\\\/sites\\\/340\\\/2024\\\/05\\\/20240715_221802-scaled.jpg\",\"datePublished\":\"2023-10-16T19:10:34+00:00\",\"dateModified\":\"2025-06-03T14:49:12+00:00\",\"description\":\"Friso Le Poole is het regio-bestuurslid verantwoordelijk voor het co\u00f6rdineren van de campagne binnen Noord-Holland.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/mensen\\\/friso-le-poole\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/noordholland\\\/mensen\\\/friso-le-poole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/mensen\\\/friso-le-poole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/wp-content\\\/uploads\\\/sites\\\/340\\\/2024\\\/05\\\/20240715_221802-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/wp-content\\\/uploads\\\/sites\\\/340\\\/2024\\\/05\\\/20240715_221802-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/mensen\\\/friso-le-poole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mensen\",\"item\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/mensen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Friso Le Poole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/\",\"name\":\"D66 Noord-Holland\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D66 Noord-Holland &#8212; Friso Le Poole","description":"Friso Le Poole is het regio-bestuurslid verantwoordelijk voor het co\u00f6rdineren van de campagne binnen Noord-Holland.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/noordholland\/mensen\/friso-le-poole\/","og_locale":"nl_NL","og_type":"article","og_title":"D66 Noord-Holland &#8212; Friso Le Poole","og_description":"Friso Le Poole is het regio-bestuurslid verantwoordelijk voor het co\u00f6rdineren van de campagne binnen Noord-Holland.","og_url":"https:\/\/d66.nl\/noordholland\/mensen\/friso-le-poole\/","og_site_name":"D66 Noord-Holland","article_modified_time":"2025-06-03T14:49:12+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/d66.nl\/noordholland\/wp-content\/uploads\/sites\/340\/2024\/05\/20240715_221802-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/noordholland\/mensen\/friso-le-poole\/","url":"https:\/\/d66.nl\/noordholland\/mensen\/friso-le-poole\/","name":"D66 Noord-Holland &#8212; Friso Le Poole","isPartOf":{"@id":"https:\/\/d66.nl\/noordholland\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d66.nl\/noordholland\/mensen\/friso-le-poole\/#primaryimage"},"image":{"@id":"https:\/\/d66.nl\/noordholland\/mensen\/friso-le-poole\/#primaryimage"},"thumbnailUrl":"https:\/\/d66.nl\/noordholland\/wp-content\/uploads\/sites\/340\/2024\/05\/20240715_221802-scaled.jpg","datePublished":"2023-10-16T19:10:34+00:00","dateModified":"2025-06-03T14:49:12+00:00","description":"Friso Le Poole is het regio-bestuurslid verantwoordelijk voor het co\u00f6rdineren van de campagne binnen Noord-Holland.","breadcrumb":{"@id":"https:\/\/d66.nl\/noordholland\/mensen\/friso-le-poole\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/noordholland\/mensen\/friso-le-poole\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/noordholland\/mensen\/friso-le-poole\/#primaryimage","url":"https:\/\/d66.nl\/noordholland\/wp-content\/uploads\/sites\/340\/2024\/05\/20240715_221802-scaled.jpg","contentUrl":"https:\/\/d66.nl\/noordholland\/wp-content\/uploads\/sites\/340\/2024\/05\/20240715_221802-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/noordholland\/mensen\/friso-le-poole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/noordholland\/"},{"@type":"ListItem","position":2,"name":"Mensen","item":"https:\/\/d66.nl\/noordholland\/mensen\/"},{"@type":"ListItem","position":3,"name":"Friso Le Poole"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/noordholland\/#website","url":"https:\/\/d66.nl\/noordholland\/","name":"D66 Noord-Holland","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/noordholland\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/noordholland\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/noordholland\/#organization","name":"D66","url":"https:\/\/d66.nl\/noordholland\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/noordholland\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/noordholland\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/noordholland\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/noordholland\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/noordholland\/wp-json\/wp\/v2\/people-type\/3049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/noordholland\/wp-json\/wp\/v2\/people-type"}],"about":[{"href":"https:\/\/d66.nl\/noordholland\/wp-json\/wp\/v2\/types\/people-type"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/noordholland\/wp-json\/wp\/v2\/users\/1174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d66.nl\/noordholland\/wp-json\/wp\/v2\/media\/4032"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/noordholland\/wp-json\/wp\/v2\/media?parent=3049"}],"wp:term":[{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/noordholland\/wp-json\/wp\/v2\/search-tags?post=3049"},{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/noordholland\/wp-json\/wp\/v2\/labels?post=3049"},{"taxonomy":"division-tags","embeddable":true,"href":"https:\/\/d66.nl\/noordholland\/wp-json\/wp\/v2\/division-tags?post=3049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}