{"id":50,"count":22,"description":"Gemeenten Bloemendaal, Haarlem, Heemstede en Zandvoort zijn Zuid-Kennemerland. De IJmondgemeenten zijn Beverwijk, Heemskerk en Velsen.","link":"https:\/\/d66.nl\/noordholland\/category\/regio\/zuid-kennemerland-ijmond\/","name":"Zuid Kennemerland \/ IJmond","slug":"zuid-kennemerland-ijmond","taxonomy":"category","parent":43,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zuid Kennemerland \/ IJmond Archives &#8212; D66 Noord-Holland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/noordholland\/category\/regio\/zuid-kennemerland-ijmond\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zuid Kennemerland \/ IJmond Archives &#8212; D66 Noord-Holland\" \/>\n<meta property=\"og:description\" content=\"Gemeenten Bloemendaal, Haarlem, Heemstede en Zandvoort zijn Zuid-Kennemerland. De IJmondgemeenten zijn Beverwijk, Heemskerk en Velsen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/noordholland\/category\/regio\/zuid-kennemerland-ijmond\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Noord-Holland\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/category\\\/regio\\\/zuid-kennemerland-ijmond\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/category\\\/regio\\\/zuid-kennemerland-ijmond\\\/\",\"name\":\"Zuid Kennemerland \\\/ IJmond Archives &#8212; D66 Noord-Holland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/category\\\/regio\\\/zuid-kennemerland-ijmond\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/category\\\/regio\\\/zuid-kennemerland-ijmond\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bestuurlijke regio's\",\"item\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/category\\\/regio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zuid Kennemerland \\\/ IJmond\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/\",\"name\":\"D66 Noord-Holland\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/noordholland\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zuid Kennemerland \/ IJmond Archives &#8212; D66 Noord-Holland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/noordholland\/category\/regio\/zuid-kennemerland-ijmond\/","og_locale":"nl_NL","og_type":"article","og_title":"Zuid Kennemerland \/ IJmond Archives &#8212; D66 Noord-Holland","og_description":"Gemeenten Bloemendaal, Haarlem, Heemstede en Zandvoort zijn Zuid-Kennemerland. De IJmondgemeenten zijn Beverwijk, Heemskerk en Velsen.","og_url":"https:\/\/d66.nl\/noordholland\/category\/regio\/zuid-kennemerland-ijmond\/","og_site_name":"D66 Noord-Holland","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/d66.nl\/noordholland\/category\/regio\/zuid-kennemerland-ijmond\/","url":"https:\/\/d66.nl\/noordholland\/category\/regio\/zuid-kennemerland-ijmond\/","name":"Zuid Kennemerland \/ IJmond Archives &#8212; D66 Noord-Holland","isPartOf":{"@id":"https:\/\/d66.nl\/noordholland\/#website"},"breadcrumb":{"@id":"https:\/\/d66.nl\/noordholland\/category\/regio\/zuid-kennemerland-ijmond\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/noordholland\/category\/regio\/zuid-kennemerland-ijmond\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/noordholland\/"},{"@type":"ListItem","position":2,"name":"Bestuurlijke regio's","item":"https:\/\/d66.nl\/noordholland\/category\/regio\/"},{"@type":"ListItem","position":3,"name":"Zuid Kennemerland \/ IJmond"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/noordholland\/#website","url":"https:\/\/d66.nl\/noordholland\/","name":"D66 Noord-Holland","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/noordholland\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/noordholland\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/noordholland\/#organization","name":"D66","url":"https:\/\/d66.nl\/noordholland\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/noordholland\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/noordholland\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/noordholland\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/noordholland\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/noordholland\/wp-json\/wp\/v2\/categories\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/noordholland\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/d66.nl\/noordholland\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/d66.nl\/noordholland\/wp-json\/wp\/v2\/categories\/43"}],"wp:post_type":[{"href":"https:\/\/d66.nl\/noordholland\/wp-json\/wp\/v2\/posts?categories=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}