{"id":427,"date":"2021-11-26T12:12:58","date_gmt":"2021-11-26T12:12:58","guid":{"rendered":"https:\/\/d66.nl\/template14okt1966\/?page_id=427"},"modified":"2021-11-26T12:20:34","modified_gmt":"2021-11-26T12:20:34","slug":"contact","status":"publish","type":"page","link":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--66 wrapper__spacing-bottom-mobile--76  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading heading__align--left heading__color--black heading__size--giant heading__font--serif   block-heading__heading\" id=\"nav-contact-met-d661675\"  data-nav-heading-mobile=\"Contact met D66\" >\n\tContact met D66<\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--semiBold  block-post-content__heading\" id=\"nav-contact-met-d66-in-jouw-gemeente3154\" data-nav-heading-mobile=\"Contact met D66 in jouw gemeente\">\n\tContact met D66 in jouw gemeente<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tContactdetails.\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--semiBold  block-post-content__heading\" id=\"nav-landelijk-bureau-d662204\" data-nav-heading-mobile=\"Landelijk Bureau D66\">\n\tLandelijk Bureau D66<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tHet Landelijk Bureau is verantwoordelijk voor de organisatorische kant van de partij en voert vele taken uit die noodzakelijk zijn voor het functioneren van D66. Zij treedt dienstverlenend op voor de leden, afdelingen en regio\u2019s en is verantwoordelijk voor alle verenigingszaken. Op het Landelijk Bureau werken ongeveer 30 mensen die bij de partij in dienst zijn. In campagnetijd worden extra medewerkers ingezet.<br><br><strong>Bezoek- en postadres<\/strong><br>Landelijk Bureau D66<br>Lange Houtstraat 11<br>2511 CV Den Haag<br><br><strong>Telefoonnummer<\/strong><br>070-3566066\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<a\n\thref=\"mailto:info@d66.nl\"\n\tclass=\"arrow-link arrow-link__size--default arrow-link__color--black block-arrow-link__arrow_link\"\n\tid=\"\"\n\ttitle=\"Stuur een algemene vraag\"\n\n\t\n\t>\n\t<span class=\"arrow-link__arrow\"><\/span>\n\t<span class=\"arrow-link__title\">Stuur een algemene vraag<\/span>\n<\/a>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":35,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"search-tags":[],"labels":[],"themes-or-point-of-view":[],"class_list":["post-427","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Thema afdeling Internationale Veiligheid en Defensie &#8212; Contact<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/internationale-veiligheid-defensie\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thema afdeling Internationale Veiligheid en Defensie &#8212; Contact\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/internationale-veiligheid-defensie\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Thema afdeling Internationale Veiligheid en Defensie\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-26T12:20:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/contact\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/contact\\\/\",\"name\":\"Thema afdeling Internationale Veiligheid en Defensie &#8212; Contact\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/#website\"},\"datePublished\":\"2021-11-26T12:12:58+00:00\",\"dateModified\":\"2021-11-26T12:20:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/contact\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/\",\"name\":\"Thema afdeling Internationale Veiligheid en Defensie\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/template14okt1966\\\/wp-content\\\/uploads\\\/sites\\\/411\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/template14okt1966\\\/wp-content\\\/uploads\\\/sites\\\/411\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/internationale-veiligheid-defensie\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thema afdeling Internationale Veiligheid en Defensie &#8212; Contact","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/contact\/","og_locale":"nl_NL","og_type":"article","og_title":"Thema afdeling Internationale Veiligheid en Defensie &#8212; Contact","og_url":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/contact\/","og_site_name":"Thema afdeling Internationale Veiligheid en Defensie","article_modified_time":"2021-11-26T12:20:34+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/contact\/","url":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/contact\/","name":"Thema afdeling Internationale Veiligheid en Defensie &#8212; Contact","isPartOf":{"@id":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/#website"},"datePublished":"2021-11-26T12:12:58+00:00","dateModified":"2021-11-26T12:20:34+00:00","breadcrumb":{"@id":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/contact\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/internationale-veiligheid-defensie\/contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/#website","url":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/","name":"Thema afdeling Internationale Veiligheid en Defensie","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/#organization","name":"D66","url":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/template14okt1966\/wp-content\/uploads\/sites\/411\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/template14okt1966\/wp-content\/uploads\/sites\/411\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/wp-json\/wp\/v2\/pages\/427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/wp-json\/wp\/v2\/comments?post=427"}],"version-history":[{"count":2,"href":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/wp-json\/wp\/v2\/pages\/427\/revisions"}],"predecessor-version":[{"id":429,"href":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/wp-json\/wp\/v2\/pages\/427\/revisions\/429"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/wp-json\/wp\/v2\/media?parent=427"}],"wp:term":[{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/wp-json\/wp\/v2\/search-tags?post=427"},{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/wp-json\/wp\/v2\/labels?post=427"},{"taxonomy":"themes-or-point-of-view","embeddable":true,"href":"https:\/\/d66.nl\/internationale-veiligheid-defensie\/wp-json\/wp\/v2\/themes-or-point-of-view?post=427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}