{"id":1438,"date":"2022-12-23T16:23:01","date_gmt":"2022-12-23T16:23:01","guid":{"rendered":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/"},"modified":"2022-12-24T11:58:34","modified_gmt":"2022-12-24T11:58:34","slug":"motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer","status":"publish","type":"post","link":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer","title":{"rendered":"Motie D66 en VW: college voorkom verschraling scholierenvervoer"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--66 wrapper__spacing-bottom-mobile--76  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading   heading__size--giant heading__font--serif heading__weight--regular  block-heading__heading\" id=\"nav-motie-d66-en-vw--college-voorkom-verschraling-scholierenvervoer2000\"  data-nav-heading-mobile=\"Motie D66 en VW: college voorkom verschraling scholierenvervoer\" >\n\tMotie D66 en VW: college voorkom verschraling scholierenvervoer<\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-mobile--40  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--13 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<p\n\t\tclass=\"paragraph   paragraph__size--big   block-paragraph__paragraph\"\n\t\t\t>\n\t\tEen brief aan leerlingen van het voortgezet onderwijs in Oud Beijerland veroorzaakte grote onrust deze week. Leerlingen van onder andere het Hoeksch Lyceum kregen te horen dat er na de kerstvakantie minder bussen worden ingezet in de drukken uren \u2019s ochtends. Scholen in de Hoeksche Waard gaan hun lesrooster aanpassen omdat extra bussen door de nieuwe dienstregeling komen te vervallen. Het is daardoor goed mogelijk dat sommige leerlingen niet mee kunnen met de bus en dus te laat komen.\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20 wrapper__spacing-bottom-mobile--10  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--24 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-related-post-metadata js-block-related-post-metadata\">\n\t<div class=\"block-related-post-metadata__content-wrapper\">\n\t\t<div class=\"block-related-post-metadata__persons\">\n\t\t\t<div class=\"related-person-info__wrapper\">\n\t\t\t<div class=\"related-person-info__item related-person-info__color--yellow\">\n\t\t\t<a class=\"related-person-info__link\" href=\"https:\/\/d66.nl\/hoeksche-waard\/mensen\/coenraijer\/\">\n\t\t\t\t<div class=\"related-person-info__image_container\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/media.d66.nl\/uploads\/sites\/189\/2021\/10\/Coen-Raijer-D66HW-150x150.jpg\" class=\"related-person-info__image\" alt=\"\" \/>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"related-person-info__meta\">\n\t\t\t\t\t\t\t\t\t<header class=\"related-person-info__header\">\n\t\t\t\t\t\t<h3 class=\"heading   heading__size--small heading__font--sans heading__weight--bold\" id=\"nav-coen-raijer8454\">\n\tCoen Raijer<\/h3>\t\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"related-person-info__description\">\n\t\t\t\t\t\t<p class=\"paragraph   paragraph__size--small paragraph__weight--normal\">\n\t\tFractievoorzitter en partijleider\t<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\t\t<\/div>\n\t\t<div class=\"block-related-post-metadata__meta\">\n\t\t\t<div class=\"block-related-post-metadata__date\">\n\t\t\t\t23.12.2022<div class=\"post-share js-post-share rs_skip_always\">\n\t<button class=\"post-share__share-button js-post-share-share-button\">\n\t\tShare\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='100px' height='100px' viewBox='0 0 24 24' fill='none'><path d='m8.684 10.658 6.629-3.314m.003 9.314-6.622-3.311M21 6a3 3 0 1 1-6 0 3 3 0 0 1 6 0ZM9 12a3 3 0 1 1-6 0 3 3 0 0 1 6 0Zm12 6a3 3 0 1 1-6 0 3 3 0 0 1 6 0Z' stroke='currentColor' stroke-width='1.5' fill='none'\/><\/svg>\t<\/button>\n\t<dialog class=\"post-share__dialog js-post-share-dialog\" aria-hidden=\"true\">\n\t\t<div class=\"post-share__dialog-header\">\n\t\t\tShare this post\t\t\t<button class=\"post-share__dialog-close js-post-share-dialog-close\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='150' height='150' viewBox='0 0 150 150' fill='none'><path d='M44.103 105.897 75 75m30.898-30.898L75 75m0 0L44.103 44.102M75 75l30.898 30.897' stroke='currentColor' stroke-width='5' fill='none'\/><\/svg>\t\t\t<\/button>\n\t\t<\/div>\n\t\t<div class=\"post-share__dialog-socials\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"#\" target=\"_blank\" data-copy=&quot;true&quot;>\n\t\t\t\t\tKopier link<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='150' height='150' viewBox='0 0 150 150' fill='none'><path d='M67.468 108.679c-8.533-.512-14.164-3.583-17.407-9.983-3.242-6.314-2.815-12.713 1.195-18.6 1.706-2.56 3.584-5.035 5.46-7.594 1.537-2.048 3.584-2.475 5.462-1.195 2.047 1.45 2.389 3.498.938 5.632-1.706 2.474-3.584 4.948-5.29 7.423-3.242 4.778-2.304 11.092 2.133 14.334 4.864 3.584 11.092 2.731 14.761-1.962 1.963-2.475 3.754-5.12 5.632-7.68 1.194-1.535 2.645-2.218 4.607-1.28 1.792.854 2.645 2.39 2.304 4.267 0 .17 0 .427-.17.597-3.67 5.12-6.4 11.178-12.544 13.993-2.56 1.195-5.46 1.707-6.996 2.219l-.085-.171Z' fill='currentColor'\/><path d='M86.921 44.6c6.144.257 11.605 3.328 14.932 9.728 3.328 6.399 2.816 12.798-1.109 18.856-1.621 2.56-3.498 4.95-5.29 7.424-1.707 2.303-3.754 2.815-5.717 1.45-2.048-1.45-2.304-3.669-.597-6.058 1.621-2.304 3.328-4.608 4.949-6.911 3.498-4.95 2.56-11.348-2.133-14.761-4.779-3.499-11.178-2.475-14.847 2.56-1.792 2.388-3.498 4.863-5.205 7.252-1.62 2.218-3.583 2.56-5.546 1.11-1.877-1.366-2.218-3.414-.768-5.462 2.048-2.986 4.01-5.972 6.314-8.703 3.67-4.351 8.448-6.399 15.103-6.399l-.086-.085Z' fill='currentColor'\/><path d='M71.478 88.457c-3.498-.341-5.46-3.413-3.754-6.143 3.327-5.29 6.825-10.495 10.324-15.7 1.45-2.133 3.413-2.389 5.46-1.109 1.878 1.28 2.219 3.413.854 5.546-3.328 5.034-6.57 9.983-9.983 14.932-.683 1.024-1.963 1.621-2.901 2.389v.085Z' fill='currentColor'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"mailto:?to=%20&amp;body=https%3A%2F%2Fd66.nl%2Fhoeksche-waard%2Fnieuws%2Fmotie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\" target=\"_blank\" >\n\t\t\t\t\tMail<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fd66.nl%2Fhoeksche-waard%2Fnieuws%2Fmotie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\" target=\"_blank\" >\n\t\t\t\t\tLinkedIn<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fd66.nl%2Fhoeksche-waard%2Fnieuws%2Fmotie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\" target=\"_blank\" >\n\t\t\t\t\tFacebook<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"whatsapp:\/\/send?text=https%3A%2F%2Fd66.nl%2Fhoeksche-waard%2Fnieuws%2Fmotie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\" target=\"_blank\" >\n\t\t\t\t\tWhatsApp<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"post-share__dialog-item js-post-share-dialog-item\" href=\"https:\/\/x.com\/intent\/post?url=https%3A%2F%2Fd66.nl%2Fhoeksche-waard%2Fnieuws%2Fmotie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\" target=\"_blank\" >\n\t\t\t\t\tTwitter (X)<svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='40' height='40' viewBox='0 0 40 40' fill='none'><path d='M24.107 15.865a1 1 0 0 1 1.266 1.265l-1.686 5.052a1 1 0 0 1-1.654.392l-3.37-3.37a1.001 1.001 0 0 1 .392-1.654l5.052-1.685Z' fill='currentColor'\/><path d='m21.763 19.475-5.657 5.657' stroke='currentColor' stroke-width='2' stroke-linecap='round' fill='none'\/><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/dialog>\n<\/div>\t\t\t<\/div>\n\t\t\t<div class=\"block-related-post-metadata__categories\">\n\t\t\t\t<div class=\"category-link__wrapper\">\n\t\t\t<div class=\"category-link__item\">\n\t\t\t<a href=\"https:\/\/d66.nl\/hoeksche-waard\/category\/d66-hoeksche-waard\/\">\n\t\t\t\tNieuws uit de gemeenteraad\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--semiBold  block-post-content__heading\" id=\"nav-hoge-brandstofprijzen-en-personeelstekort1547\" data-nav-heading-mobile=\"Hoge brandstofprijzen en personeelstekort\">\n\tHoge brandstofprijzen en personeelstekort<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tAls oorzaak werden hoge brandstofprijzen en personeelstekort genoemd bij Connexxion, die de buslijnen verzorgt. Het gevolg van deze maatregel is dat verschillende scholen hun roosters aanpassen. Voor het Hoeksch Lyceum betekent dat bijvoorbeeld dat vakken als tekenen en mentoruren naar het eerste uur verhuizen. Op die manier wordt minder lesstof gemist als leerlingen door uitvallende of overvolle bussen niet op tijd op school kunnen komen, zo is de gedachte.\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--semiBold  block-post-content__heading\" id=\"nav-vragen-aan-het-college4087\" data-nav-heading-mobile=\"Vragen aan het college\">\n\tVragen aan het college<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tOnze fractie heeft tijdens de raadsvergadering afgelopen dinsdag direct vragen aan het college van B&amp;W gesteld hierover. \u201cOok al gaat de gemeente hier niet rechtstreeks over: dit kunnen we echt niet laten lopen,\u201d aldus Coen Raijer. \u201cWe geven echt een verkeerd signaal aan onze jonge inwoners als we het laten gebeuren dat ze niet op een normale manier met de bus op tijd op school kunnen komen. Dit is een moment waarop we als gemeenteraad moeten laten zien dat we hier niet mee akkoord gaan.&#8221;\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--semiBold  block-post-content__heading\" id=\"nav-niet-tevreden-met-antwoorden-van-de-wethouder3738\" data-nav-heading-mobile=\"Niet tevreden met antwoorden van de wethouder\">\n\tNiet tevreden met antwoorden van de wethouder<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tWethouder van Waveren, die verantwoordelijk is voor Openbaar Vervoer was niet aanwezig bij de raadsvergadering. Zijn plaatsvervanger, Wethouder van der Wulp, kon niet direct garanderen dat er een oplossing zou komen en liet ook in het midden of de gemeente hier een rol in zou moeten spelen. Wij hebben daarop samen met VoorWaards Hoeksche Waard een motie gemaakt die het college oproept initiatief te nemen om tot een oplossing te komen en verschraling van het scholierenvervoer tegen te gaan. De motie van Raijer roept het college op om leiderschap te tonen in deze en samen met scholen, provincie, en vervoersbedrijven tot een oplossing te komen.\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--semiBold  block-post-content__heading\" id=\"nav-motie-aangenomen4072\" data-nav-heading-mobile=\"Motie aangenomen\">\n\tMotie aangenomen<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tOnze motie is met ruime meerderheid aangenomen. Coen Raijer: \u201cWe zijn blij dat de raad met zo\u2019n grote meerderheid achter onze motie staat. We zullen het college kritisch volgen bij het komen tot een oplossing. Verdere verschraling van het openbaar vervoer, zeker voor scholieren gaat er bij ons niet in!\u201d\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":428,"featured_media":1439,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"labels":[],"search-tags":[],"class_list":["post-1438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-d66-hoeksche-waard"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D66 Hoeksche Waard &#8212; Motie D66 en VW: college voorkom verschraling scholierenvervoer<\/title>\n<meta name=\"description\" content=\"D66 Hoeksche Waard heeft samen met VoorWaards Hoeksche Waard een motie ingediend. De motie roept het college op om initiatief te nemen om tot een oplossing te komen en verschraling van het scholierenvervoer tegen te gaan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D66 Hoeksche Waard &#8212; Motie D66 en VW: college voorkom verschraling scholierenvervoer\" \/>\n<meta property=\"og:description\" content=\"D66 Hoeksche Waard heeft samen met VoorWaards Hoeksche Waard een motie ingediend. De motie roept het college op om initiatief te nemen om tot een oplossing te komen en verschraling van het scholierenvervoer tegen te gaan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Hoeksche Waard\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-23T16:23:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-24T11:58:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d66.nl\/hoeksche-waard\/wp-content\/uploads\/sites\/189\/2022\/12\/Fractievoorzitter-D66-Hoeksche-Waard-Coen-Raijer-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Menno van Diest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Menno van Diest\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/nieuws\\\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/nieuws\\\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\\\/\"},\"author\":{\"name\":\"Menno van Diest\",\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/#\\\/schema\\\/person\\\/58afe0ca8de624132e3cd60e31a467f4\"},\"headline\":\"Motie D66 en VW: college voorkom verschraling scholierenvervoer\",\"datePublished\":\"2022-12-23T16:23:01+00:00\",\"dateModified\":\"2022-12-24T11:58:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/nieuws\\\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\\\/\"},\"wordCount\":8,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/nieuws\\\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/wp-content\\\/uploads\\\/sites\\\/189\\\/2022\\\/12\\\/Fractievoorzitter-D66-Hoeksche-Waard-Coen-Raijer-scaled.jpeg\",\"articleSection\":[\"Nieuws uit de gemeenteraad\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/nieuws\\\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/nieuws\\\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/nieuws\\\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\\\/\",\"name\":\"D66 Hoeksche Waard &#8212; Motie D66 en VW: college voorkom verschraling scholierenvervoer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/nieuws\\\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/nieuws\\\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/wp-content\\\/uploads\\\/sites\\\/189\\\/2022\\\/12\\\/Fractievoorzitter-D66-Hoeksche-Waard-Coen-Raijer-scaled.jpeg\",\"datePublished\":\"2022-12-23T16:23:01+00:00\",\"dateModified\":\"2022-12-24T11:58:34+00:00\",\"description\":\"D66 Hoeksche Waard heeft samen met VoorWaards Hoeksche Waard een motie ingediend. De motie roept het college op om initiatief te nemen om tot een oplossing te komen en verschraling van het scholierenvervoer tegen te gaan.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/nieuws\\\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/nieuws\\\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/nieuws\\\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/wp-content\\\/uploads\\\/sites\\\/189\\\/2022\\\/12\\\/Fractievoorzitter-D66-Hoeksche-Waard-Coen-Raijer-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/wp-content\\\/uploads\\\/sites\\\/189\\\/2022\\\/12\\\/Fractievoorzitter-D66-Hoeksche-Waard-Coen-Raijer-scaled.jpeg\",\"width\":1707,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/nieuws\\\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nieuws\",\"item\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/nieuws\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Motie D66 en VW: college voorkom verschraling scholierenvervoer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/\",\"name\":\"D66 Hoeksche Waard\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/#organization\",\"name\":\"D66 Hoeksche Waard\",\"url\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/wp-content\\\/uploads\\\/sites\\\/189\\\/2021\\\/12\\\/Logo-D66-HW.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/wp-content\\\/uploads\\\/sites\\\/189\\\/2021\\\/12\\\/Logo-D66-HW.png\",\"width\":2250,\"height\":2250,\"caption\":\"D66 Hoeksche Waard\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/d66.nl\\\/hoeksche-waard\\\/#\\\/schema\\\/person\\\/58afe0ca8de624132e3cd60e31a467f4\",\"name\":\"Menno van Diest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b4f74a4266e9edc6547e75bd440b19b76f9f28995626ee140a9bc35c8e5fe37?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b4f74a4266e9edc6547e75bd440b19b76f9f28995626ee140a9bc35c8e5fe37?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b4f74a4266e9edc6547e75bd440b19b76f9f28995626ee140a9bc35c8e5fe37?s=96&d=mm&r=g\",\"caption\":\"Menno van Diest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D66 Hoeksche Waard &#8212; Motie D66 en VW: college voorkom verschraling scholierenvervoer","description":"D66 Hoeksche Waard heeft samen met VoorWaards Hoeksche Waard een motie ingediend. De motie roept het college op om initiatief te nemen om tot een oplossing te komen en verschraling van het scholierenvervoer tegen te gaan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer","og_locale":"nl_NL","og_type":"article","og_title":"D66 Hoeksche Waard &#8212; Motie D66 en VW: college voorkom verschraling scholierenvervoer","og_description":"D66 Hoeksche Waard heeft samen met VoorWaards Hoeksche Waard een motie ingediend. De motie roept het college op om initiatief te nemen om tot een oplossing te komen en verschraling van het scholierenvervoer tegen te gaan.","og_url":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/","og_site_name":"D66 Hoeksche Waard","article_published_time":"2022-12-23T16:23:01+00:00","article_modified_time":"2022-12-24T11:58:34+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/d66.nl\/hoeksche-waard\/wp-content\/uploads\/sites\/189\/2022\/12\/Fractievoorzitter-D66-Hoeksche-Waard-Coen-Raijer-scaled.jpeg","type":"image\/jpeg"}],"author":"Menno van Diest","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"Menno van Diest"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/#article","isPartOf":{"@id":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/"},"author":{"name":"Menno van Diest","@id":"https:\/\/d66.nl\/hoeksche-waard\/#\/schema\/person\/58afe0ca8de624132e3cd60e31a467f4"},"headline":"Motie D66 en VW: college voorkom verschraling scholierenvervoer","datePublished":"2022-12-23T16:23:01+00:00","dateModified":"2022-12-24T11:58:34+00:00","mainEntityOfPage":{"@id":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/"},"wordCount":8,"commentCount":0,"publisher":{"@id":"https:\/\/d66.nl\/hoeksche-waard\/#organization"},"image":{"@id":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/#primaryimage"},"thumbnailUrl":"https:\/\/d66.nl\/hoeksche-waard\/wp-content\/uploads\/sites\/189\/2022\/12\/Fractievoorzitter-D66-Hoeksche-Waard-Coen-Raijer-scaled.jpeg","articleSection":["Nieuws uit de gemeenteraad"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/","url":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/","name":"D66 Hoeksche Waard &#8212; Motie D66 en VW: college voorkom verschraling scholierenvervoer","isPartOf":{"@id":"https:\/\/d66.nl\/hoeksche-waard\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/#primaryimage"},"image":{"@id":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/#primaryimage"},"thumbnailUrl":"https:\/\/d66.nl\/hoeksche-waard\/wp-content\/uploads\/sites\/189\/2022\/12\/Fractievoorzitter-D66-Hoeksche-Waard-Coen-Raijer-scaled.jpeg","datePublished":"2022-12-23T16:23:01+00:00","dateModified":"2022-12-24T11:58:34+00:00","description":"D66 Hoeksche Waard heeft samen met VoorWaards Hoeksche Waard een motie ingediend. De motie roept het college op om initiatief te nemen om tot een oplossing te komen en verschraling van het scholierenvervoer tegen te gaan.","breadcrumb":{"@id":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/#primaryimage","url":"https:\/\/d66.nl\/hoeksche-waard\/wp-content\/uploads\/sites\/189\/2022\/12\/Fractievoorzitter-D66-Hoeksche-Waard-Coen-Raijer-scaled.jpeg","contentUrl":"https:\/\/d66.nl\/hoeksche-waard\/wp-content\/uploads\/sites\/189\/2022\/12\/Fractievoorzitter-D66-Hoeksche-Waard-Coen-Raijer-scaled.jpeg","width":1707,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/motie-d66-en-vw-college-voorkom-verschraling-scholierenvervoer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/hoeksche-waard\/"},{"@type":"ListItem","position":2,"name":"Nieuws","item":"https:\/\/d66.nl\/hoeksche-waard\/nieuws\/"},{"@type":"ListItem","position":3,"name":"Motie D66 en VW: college voorkom verschraling scholierenvervoer"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/hoeksche-waard\/#website","url":"https:\/\/d66.nl\/hoeksche-waard\/","name":"D66 Hoeksche Waard","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/hoeksche-waard\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/hoeksche-waard\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/hoeksche-waard\/#organization","name":"D66 Hoeksche Waard","url":"https:\/\/d66.nl\/hoeksche-waard\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/hoeksche-waard\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/hoeksche-waard\/wp-content\/uploads\/sites\/189\/2021\/12\/Logo-D66-HW.png","contentUrl":"https:\/\/d66.nl\/hoeksche-waard\/wp-content\/uploads\/sites\/189\/2021\/12\/Logo-D66-HW.png","width":2250,"height":2250,"caption":"D66 Hoeksche Waard"},"image":{"@id":"https:\/\/d66.nl\/hoeksche-waard\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/d66.nl\/hoeksche-waard\/#\/schema\/person\/58afe0ca8de624132e3cd60e31a467f4","name":"Menno van Diest","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/9b4f74a4266e9edc6547e75bd440b19b76f9f28995626ee140a9bc35c8e5fe37?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9b4f74a4266e9edc6547e75bd440b19b76f9f28995626ee140a9bc35c8e5fe37?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9b4f74a4266e9edc6547e75bd440b19b76f9f28995626ee140a9bc35c8e5fe37?s=96&d=mm&r=g","caption":"Menno van Diest"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/hoeksche-waard\/wp-json\/wp\/v2\/posts\/1438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/hoeksche-waard\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/d66.nl\/hoeksche-waard\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/hoeksche-waard\/wp-json\/wp\/v2\/users\/428"}],"replies":[{"embeddable":true,"href":"https:\/\/d66.nl\/hoeksche-waard\/wp-json\/wp\/v2\/comments?post=1438"}],"version-history":[{"count":6,"href":"https:\/\/d66.nl\/hoeksche-waard\/wp-json\/wp\/v2\/posts\/1438\/revisions"}],"predecessor-version":[{"id":1447,"href":"https:\/\/d66.nl\/hoeksche-waard\/wp-json\/wp\/v2\/posts\/1438\/revisions\/1447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d66.nl\/hoeksche-waard\/wp-json\/wp\/v2\/media\/1439"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/hoeksche-waard\/wp-json\/wp\/v2\/media?parent=1438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/d66.nl\/hoeksche-waard\/wp-json\/wp\/v2\/categories?post=1438"},{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/hoeksche-waard\/wp-json\/wp\/v2\/labels?post=1438"},{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/hoeksche-waard\/wp-json\/wp\/v2\/search-tags?post=1438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}