{"id":721,"date":"2022-09-07T13:34:46","date_gmt":"2022-09-07T13:34:46","guid":{"rendered":"https:\/\/d66.nl\/gelderland\/nieuws\/"},"modified":"2022-09-07T13:34:47","modified_gmt":"2022-09-07T13:34:47","slug":"d66-zet-in-op-digitale-veiligheid-en-de-fiets","status":"publish","type":"post","link":"https:\/\/d66.nl\/gelderland\/nieuws\/d66-zet-in-op-digitale-veiligheid-en-de-fiets","title":{"rendered":"D66 zet in op digitale veiligheid en de fiets"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--66 wrapper__spacing-bottom-mobile--76  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading   heading__size--giant heading__font--serif heading__weight--regular  block-heading__heading\" id=\"nav-d66-zet-in-op-digitale-veiligheid-en-de-fiets2453\"  data-nav-heading-mobile=\"D66 zet in op digitale veiligheid en de fiets\" >\n\tD66 zet in op digitale veiligheid en de fiets<\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-mobile--40  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--13 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<p\n\t\tclass=\"paragraph   paragraph__size--big   block-paragraph__paragraph\"\n\t\t\t>\n\t\t\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--bold  block-post-content__heading\" id=\"nav-7528\" data-nav-heading-mobile=\"\">\n\t<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tAfgelopen Statenvergadering in de provincie Gelderland stond de kadernota ter discussie. C\u00e9line Blom die namens D66 Gelderland het woord voerde had een duidelijke boodschap. \u201cHet is essentieel voor Gelderland om een Centrum voor Veiligheid en Digitalisering te laten starten. Digitale veiligheid raakt inmiddels alle haarvaten van onze samenleving en de ontwikkelingen gaan snel. Wij willen dat hier op tijd in wordt ge\u00efnvesteerd, ook door de provincie\u201d, aldus Blom. Blom diende namens D66 een motie in om het kenniscentrum voor Veiligheid en Digitalisering in Apeldoorn goed te laten starten. Deze motie werd met een ruime meerderheid aangenomen.<br><br>Naast de digitale uitdagingen in onze samenleving zitten we ook nog steeds met een gezondheidscrisis en klimaatcrisis. Mobiliteit is een groot onderdeel van zowel de gezondheidscrisis als de klimaatcrisis. Zo draagt mobiliteit in onze provincie voor bijna een derde bij aan de huidige CO2-uitstoot. D66 wil dat er verkenningskomt om nieuwe potenti\u00eble snelle fietsroutes op te nemen in de kadernota. De fiets draagt bij aan meer beweging en gezondheid en levert een grote bijdrage tot het terugdringen van de CO2 uitstoot van onze mobiliteit.<br>Beide moties werden uiteindelijk aangenomen.<br><br><a href=\"https:\/\/gelderland.stateninformatie.nl\/document\/10073865\/1\/Motie%2021M27%20D66%20e_a_,%20Centrum%20voor%20Veiligheid%20&amp;%20Digitalisering\">Lees hier motie kenniscentrum veiligheid en digitalisering.\u00a0<\/a><br><a href=\"https:\/\/gelderland.stateninformatie.nl\/document\/10073866\/1\/Motie%2021M28%20D66%20e_a_,%20Start%20verkenningen%20vier%20nieuwe%20snelfietsroutes\">Lees hier motie snelle fietsroutes.\u00a0<\/a>\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":458,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"search-tags":[10,9],"labels":[],"class_list":["post-721","post","type-post","status-publish","format-standard","hentry","category-d66","search-tags-ruimte-verkeer-bereikbaarheid","search-tags-veiligheid-criminaliteit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D66 Gelderland &#8212; D66 zet in op digitale veiligheid en de fiets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/gelderland\/nieuws\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D66 Gelderland &#8212; D66 zet in op digitale veiligheid en de fiets\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/gelderland\/nieuws\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Gelderland\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-07T13:34:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-07T13:34:47+00:00\" \/>\n<meta name=\"author\" content=\"loestendolle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"loestendolle\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/nieuws\\\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/nieuws\\\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\\\/\"},\"author\":{\"name\":\"loestendolle\",\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/#\\\/schema\\\/person\\\/7b553693aec6a255a5c18f163027928d\"},\"headline\":\"D66 zet in op digitale veiligheid en de fiets\",\"datePublished\":\"2022-09-07T13:34:46+00:00\",\"dateModified\":\"2022-09-07T13:34:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/nieuws\\\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\\\/\"},\"wordCount\":9,\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/#organization\"},\"articleSection\":[\"D66\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/nieuws\\\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/nieuws\\\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\\\/\",\"name\":\"D66 Gelderland &#8212; D66 zet in op digitale veiligheid en de fiets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/#website\"},\"datePublished\":\"2022-09-07T13:34:46+00:00\",\"dateModified\":\"2022-09-07T13:34:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/nieuws\\\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/gelderland\\\/nieuws\\\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/nieuws\\\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nieuws\",\"item\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/nieuws\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D66 zet in op digitale veiligheid en de fiets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/\",\"name\":\"D66 Gelderland\",\"description\":\"Website van D66 Gelderland\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/d66.nl\\\/gelderland\\\/#\\\/schema\\\/person\\\/7b553693aec6a255a5c18f163027928d\",\"name\":\"loestendolle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab4bec5787de3fe7453997d73f8605504a377f29845cbf6ec1512adafa3419c4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab4bec5787de3fe7453997d73f8605504a377f29845cbf6ec1512adafa3419c4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab4bec5787de3fe7453997d73f8605504a377f29845cbf6ec1512adafa3419c4?s=96&d=mm&r=g\",\"caption\":\"loestendolle\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D66 Gelderland &#8212; D66 zet in op digitale veiligheid en de fiets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/gelderland\/nieuws\/d66-zet-in-op-digitale-veiligheid-en-de-fiets","og_locale":"nl_NL","og_type":"article","og_title":"D66 Gelderland &#8212; D66 zet in op digitale veiligheid en de fiets","og_url":"https:\/\/d66.nl\/gelderland\/nieuws\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\/","og_site_name":"D66 Gelderland","article_published_time":"2022-09-07T13:34:46+00:00","article_modified_time":"2022-09-07T13:34:47+00:00","author":"loestendolle","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"loestendolle"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/d66.nl\/gelderland\/nieuws\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\/#article","isPartOf":{"@id":"https:\/\/d66.nl\/gelderland\/nieuws\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\/"},"author":{"name":"loestendolle","@id":"https:\/\/d66.nl\/gelderland\/#\/schema\/person\/7b553693aec6a255a5c18f163027928d"},"headline":"D66 zet in op digitale veiligheid en de fiets","datePublished":"2022-09-07T13:34:46+00:00","dateModified":"2022-09-07T13:34:47+00:00","mainEntityOfPage":{"@id":"https:\/\/d66.nl\/gelderland\/nieuws\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\/"},"wordCount":9,"publisher":{"@id":"https:\/\/d66.nl\/gelderland\/#organization"},"articleSection":["D66"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/d66.nl\/gelderland\/nieuws\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\/","url":"https:\/\/d66.nl\/gelderland\/nieuws\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\/","name":"D66 Gelderland &#8212; D66 zet in op digitale veiligheid en de fiets","isPartOf":{"@id":"https:\/\/d66.nl\/gelderland\/#website"},"datePublished":"2022-09-07T13:34:46+00:00","dateModified":"2022-09-07T13:34:47+00:00","breadcrumb":{"@id":"https:\/\/d66.nl\/gelderland\/nieuws\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/gelderland\/nieuws\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/gelderland\/nieuws\/d66-zet-in-op-digitale-veiligheid-en-de-fiets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/gelderland\/"},{"@type":"ListItem","position":2,"name":"Nieuws","item":"https:\/\/d66.nl\/gelderland\/nieuws\/"},{"@type":"ListItem","position":3,"name":"D66 zet in op digitale veiligheid en de fiets"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/gelderland\/#website","url":"https:\/\/d66.nl\/gelderland\/","name":"D66 Gelderland","description":"Website van D66 Gelderland","publisher":{"@id":"https:\/\/d66.nl\/gelderland\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/gelderland\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/gelderland\/#organization","name":"D66","url":"https:\/\/d66.nl\/gelderland\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/gelderland\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/gelderland\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/gelderland\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/gelderland\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/d66.nl\/gelderland\/#\/schema\/person\/7b553693aec6a255a5c18f163027928d","name":"loestendolle","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/ab4bec5787de3fe7453997d73f8605504a377f29845cbf6ec1512adafa3419c4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ab4bec5787de3fe7453997d73f8605504a377f29845cbf6ec1512adafa3419c4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab4bec5787de3fe7453997d73f8605504a377f29845cbf6ec1512adafa3419c4?s=96&d=mm&r=g","caption":"loestendolle"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/gelderland\/wp-json\/wp\/v2\/posts\/721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/gelderland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/d66.nl\/gelderland\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/gelderland\/wp-json\/wp\/v2\/users\/458"}],"replies":[{"embeddable":true,"href":"https:\/\/d66.nl\/gelderland\/wp-json\/wp\/v2\/comments?post=721"}],"version-history":[{"count":2,"href":"https:\/\/d66.nl\/gelderland\/wp-json\/wp\/v2\/posts\/721\/revisions"}],"predecessor-version":[{"id":723,"href":"https:\/\/d66.nl\/gelderland\/wp-json\/wp\/v2\/posts\/721\/revisions\/723"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/gelderland\/wp-json\/wp\/v2\/media?parent=721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/d66.nl\/gelderland\/wp-json\/wp\/v2\/categories?post=721"},{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/gelderland\/wp-json\/wp\/v2\/search-tags?post=721"},{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/gelderland\/wp-json\/wp\/v2\/labels?post=721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}