{"id":177,"date":"2021-10-26T11:24:28","date_gmt":"2021-10-26T11:24:28","guid":{"rendered":"https:\/\/d66.nl\/elsborstnetwerk\/?page_id=177"},"modified":"2026-06-22T20:49:35","modified_gmt":"2026-06-22T20:49:35","slug":"onze-mensen","status":"publish","type":"page","link":"https:\/\/d66.nl\/elsborstnetwerk\/onze-mensen\/","title":{"rendered":"Het bestuur"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--66 wrapper__spacing-bottom-mobile--76  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading   heading__size--giant heading__font--serif heading__weight--regular  block-heading__heading\" id=\"nav-het-bestuur701\"  data-nav-heading-mobile=\"Het bestuur\" >\n\tHet bestuur<\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--220 wrapper__spacing-bottom-tablet--190 wrapper__spacing-bottom-mobile--140  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t\n<section class=\"block-people-grid js-block-people-grid\">\n\t<aside\n  class=\"inside-page-navigation js-inside-page-navigation block-people-grid__inside-page-navigation\"\n  data-nav-items-number=\"5\"\n>\n  <div class=\"inside-page-navigation__wrapper\">\n\t<ol class=\"inside-page-navigation__list js-navigation-list lists__lists lists__weight--medium lists__color--black lists__type--decimal-leading-zero\">\n\tDe navigatie wordt geladen&#8230;<\/ol>  <\/div>\n<\/aside>\t<div class=\"block-people-grid__grid\">\n\t\t\t\t\t\t\t\t<div class=\"block-people-grid__item\">\n\t\t\t\t<article class=\"people-card js-people-card\">\n\t<a class=\"people-card__link\" href=\"https:\/\/d66.nl\/elsborstnetwerk\/mensen\/jorien-migchielsen\/\" style=\"--people-card-background-color: var(--global-colors-romanSilver)\">\n\n\t\t<div class=\"people-card__featured-image-wrapper\" style=\"background-image: url('https:\/\/media.d66.nl\/uploads\/sites\/377\/2026\/06\/Profielfoto-Jorien-Migchielsen.jpg')\">\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t<\/div>\n\n\t\t<div class=\"people-card__content-wrapper\">\n\t\t\t\t\t\t\t<header class=\"people-card__header\">\n\t\t\t\t\t<h2 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-jorien-migchielsen1503\">\n\tJorien Migchielsen<\/h2>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t<div class=\"people-card__description\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--medium\">\n\t\tVoorzitter\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   people-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"block-people-grid__item\">\n\t\t\t\t<article class=\"people-card js-people-card\">\n\t<a class=\"people-card__link\" href=\"https:\/\/d66.nl\/elsborstnetwerk\/mensen\/barbara-van-der-veen\/\" style=\"--people-card-background-color: var(--global-colors-tomato)\">\n\n\t\t<div class=\"people-card__featured-image-wrapper\" style=\"background-image: url('https:\/\/d66.nl\/elsborstnetwerk\/wp-content\/uploads\/sites\/377\/2024\/04\/Open-Call-25-03-Barbara-van-der-Veen-by-RVDA-57845c-768x768.jpg')\">\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t<\/div>\n\n\t\t<div class=\"people-card__content-wrapper\">\n\t\t\t\t\t\t\t<header class=\"people-card__header\">\n\t\t\t\t\t<h2 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-barbara-van-der-veen5034\">\n\tBarbara van der Veen<\/h2>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t<div class=\"people-card__description\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--medium\">\n\t\tBestuurslid Communicatie en vice-voorzitter\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   people-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"block-people-grid__item\">\n\t\t\t\t<article class=\"people-card js-people-card\">\n\t<a class=\"people-card__link\" href=\"https:\/\/d66.nl\/elsborstnetwerk\/mensen\/penningmeester\/\" style=\"--people-card-background-color: var(--global-colors-tomato)\">\n\n\t\t<div class=\"people-card__featured-image-wrapper\" style=\"background-image: url('https:\/\/d66.nl\/elsborstnetwerk\/wp-content\/uploads\/sites\/377\/2025\/09\/DSC3257-2.jpeg')\">\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t<\/div>\n\n\t\t<div class=\"people-card__content-wrapper\">\n\t\t\t\t\t\t\t<header class=\"people-card__header\">\n\t\t\t\t\t<h2 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-karen-maas3711\">\n\tKaren Maas<\/h2>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t<div class=\"people-card__description\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--medium\">\n\t\tPenningmeester\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   people-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"block-people-grid__item\">\n\t\t\t\t<article class=\"people-card js-people-card\">\n\t<a class=\"people-card__link\" href=\"https:\/\/d66.nl\/elsborstnetwerk\/mensen\/britt-van-de-ven\/\" style=\"--people-card-background-color: var(--global-colors-tomato)\">\n\n\t\t<div class=\"people-card__featured-image-wrapper\" style=\"background-image: url('https:\/\/d66.nl\/elsborstnetwerk\/wp-content\/uploads\/sites\/377\/2025\/09\/NH20240628-060-scaled-e1757777740171-768x831.jpg')\">\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t<\/div>\n\n\t\t<div class=\"people-card__content-wrapper\">\n\t\t\t\t\t\t\t<header class=\"people-card__header\">\n\t\t\t\t\t<h2 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-britt-van-de-ven9932\">\n\tBritt van de Ven<\/h2>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t<div class=\"people-card__description\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--medium\">\n\t\tSecretaris\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   people-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"block-people-grid__item\">\n\t\t\t\t<article class=\"people-card js-people-card\">\n\t<a class=\"people-card__link\" href=\"https:\/\/d66.nl\/elsborstnetwerk\/mensen\/jeanine-zoet\/\" style=\"--people-card-background-color: var(--global-colors-tomato)\">\n\n\t\t<div class=\"people-card__featured-image-wrapper\" style=\"background-image: url('https:\/\/d66.nl\/elsborstnetwerk\/wp-content\/uploads\/sites\/377\/2025\/09\/IMG_0515-768x1270.jpg')\">\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t<\/div>\n\n\t\t<div class=\"people-card__content-wrapper\">\n\t\t\t\t\t\t\t<header class=\"people-card__header\">\n\t\t\t\t\t<h2 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-jeanine-zoet7775\">\n\tJeanine Zoet<\/h2>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t<div class=\"people-card__description\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--medium\">\n\t\tBestuurslid Algemeen\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   people-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"block-people-grid__item\">\n\t\t\t\t<article class=\"people-card js-people-card\">\n\t<a class=\"people-card__link\" href=\"https:\/\/d66.nl\/elsborstnetwerk\/mensen\/bestuurslid-algemeen\/\" style=\"--people-card-background-color: var(--global-colors-tomato)\">\n\n\t\t<div class=\"people-card__featured-image-wrapper\" style=\"background-image: url('https:\/\/d66.nl\/elsborstnetwerk\/wp-content\/uploads\/sites\/377\/2025\/09\/463252556_1539257114138919_5823840474656845981_n-768x775.jpg')\">\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t<\/div>\n\n\t\t<div class=\"people-card__content-wrapper\">\n\t\t\t\t\t\t\t<header class=\"people-card__header\">\n\t\t\t\t\t<h2 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-sofia-schampers1735\">\n\tSofia Schampers<\/h2>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t<div class=\"people-card__description\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--medium\">\n\t\tBestuurslid algemeen\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   people-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"block-people-grid__item\">\n\t\t\t\t<article class=\"people-card js-people-card\">\n\t<a class=\"people-card__link\" href=\"https:\/\/d66.nl\/elsborstnetwerk\/mensen\/susanne-caarls\/\" style=\"--people-card-background-color: var(--global-colors-tomato)\">\n\n\t\t<div class=\"people-card__featured-image-wrapper\" style=\"background-image: url('https:\/\/d66.nl\/elsborstnetwerk\/wp-content\/uploads\/sites\/377\/2025\/09\/image0-e1757777674962.jpeg')\">\n\t\t\t<div class=\"background-overlay\"><\/div>\n\t\t<\/div>\n\n\t\t<div class=\"people-card__content-wrapper\">\n\t\t\t\t\t\t\t<header class=\"people-card__header\">\n\t\t\t\t\t<h2 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-susanne-caarls5492\">\n\tSusanne Caarls<\/h2>\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t<div class=\"people-card__description\">\n\t\t\t\t\t<p class=\"paragraph   paragraph__size--medium paragraph__weight--medium\">\n\t\tBestuurslid algemeen\t<\/p>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<button class=\"buttonV2 buttonV2__color--transparent buttonV2__size--default buttonV2__size-width--default   people-card__buttonV2\" id=\"\">\n\t<div class=\"buttonV2__top-wrapper buttonV2__arrow-align--right\">\n\t\t\t\t\t<span class=\"buttonV2__title\">\n\t\t\t\tLees verder\t\t\t<\/span>\n\t\t\n\t\t\t\t\t<div class=\"buttonV2__icon\">\n\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/button>\t\t<\/div>\n\t<\/a>\n<\/article>\t\t\t<\/div>\n\t\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":2595,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"search-tags":[],"labels":[],"themes-or-point-of-view":[],"class_list":["post-177","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D66 Els Borst Netwerk &#8212; Het bestuur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/elsborstnetwerk\/onze-mensen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D66 Els Borst Netwerk &#8212; Het bestuur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/elsborstnetwerk\/onze-mensen\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Els Borst Netwerk\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-22T20:49:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.d66.nl\/uploads\/sites\/377\/2026\/02\/260207-093-EBN-Netwerkdag-JeroenMooijman-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/onze-mensen\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/onze-mensen\\\/\",\"name\":\"D66 Els Borst Netwerk &#8212; Het bestuur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/onze-mensen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/onze-mensen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/377\\\/2026\\\/02\\\/260207-093-EBN-Netwerkdag-JeroenMooijman.jpg\",\"datePublished\":\"2021-10-26T11:24:28+00:00\",\"dateModified\":\"2026-06-22T20:49:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/onze-mensen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/onze-mensen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/onze-mensen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/377\\\/2026\\\/02\\\/260207-093-EBN-Netwerkdag-JeroenMooijman.jpg\",\"contentUrl\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/377\\\/2026\\\/02\\\/260207-093-EBN-Netwerkdag-JeroenMooijman.jpg\",\"width\":8010,\"height\":5340,\"caption\":\"EBN Netwerkdag 2025 The Color Kitchen - Utrecht Foto: Jeroen Mooijman\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/onze-mensen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Het bestuur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/\",\"name\":\"D66 Els Borst Netwerk\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/elsborstnetwerk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D66 Els Borst Netwerk &#8212; Het bestuur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/elsborstnetwerk\/onze-mensen\/","og_locale":"nl_NL","og_type":"article","og_title":"D66 Els Borst Netwerk &#8212; Het bestuur","og_url":"https:\/\/d66.nl\/elsborstnetwerk\/onze-mensen\/","og_site_name":"D66 Els Borst Netwerk","article_modified_time":"2026-06-22T20:49:35+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/media.d66.nl\/uploads\/sites\/377\/2026\/02\/260207-093-EBN-Netwerkdag-JeroenMooijman-1024x683.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/elsborstnetwerk\/onze-mensen\/","url":"https:\/\/d66.nl\/elsborstnetwerk\/onze-mensen\/","name":"D66 Els Borst Netwerk &#8212; Het bestuur","isPartOf":{"@id":"https:\/\/d66.nl\/elsborstnetwerk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d66.nl\/elsborstnetwerk\/onze-mensen\/#primaryimage"},"image":{"@id":"https:\/\/d66.nl\/elsborstnetwerk\/onze-mensen\/#primaryimage"},"thumbnailUrl":"https:\/\/media.d66.nl\/uploads\/sites\/377\/2026\/02\/260207-093-EBN-Netwerkdag-JeroenMooijman.jpg","datePublished":"2021-10-26T11:24:28+00:00","dateModified":"2026-06-22T20:49:35+00:00","breadcrumb":{"@id":"https:\/\/d66.nl\/elsborstnetwerk\/onze-mensen\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/elsborstnetwerk\/onze-mensen\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/elsborstnetwerk\/onze-mensen\/#primaryimage","url":"https:\/\/media.d66.nl\/uploads\/sites\/377\/2026\/02\/260207-093-EBN-Netwerkdag-JeroenMooijman.jpg","contentUrl":"https:\/\/media.d66.nl\/uploads\/sites\/377\/2026\/02\/260207-093-EBN-Netwerkdag-JeroenMooijman.jpg","width":8010,"height":5340,"caption":"EBN Netwerkdag 2025 The Color Kitchen - Utrecht Foto: Jeroen Mooijman"},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/elsborstnetwerk\/onze-mensen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/elsborstnetwerk\/"},{"@type":"ListItem","position":2,"name":"Het bestuur"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/elsborstnetwerk\/#website","url":"https:\/\/d66.nl\/elsborstnetwerk\/","name":"D66 Els Borst Netwerk","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/elsborstnetwerk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/elsborstnetwerk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/elsborstnetwerk\/#organization","name":"D66","url":"https:\/\/d66.nl\/elsborstnetwerk\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/elsborstnetwerk\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/elsborstnetwerk\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/elsborstnetwerk\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/elsborstnetwerk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/elsborstnetwerk\/wp-json\/wp\/v2\/pages\/177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/elsborstnetwerk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/d66.nl\/elsborstnetwerk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/elsborstnetwerk\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/d66.nl\/elsborstnetwerk\/wp-json\/wp\/v2\/comments?post=177"}],"version-history":[{"count":10,"href":"https:\/\/d66.nl\/elsborstnetwerk\/wp-json\/wp\/v2\/pages\/177\/revisions"}],"predecessor-version":[{"id":2803,"href":"https:\/\/d66.nl\/elsborstnetwerk\/wp-json\/wp\/v2\/pages\/177\/revisions\/2803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d66.nl\/elsborstnetwerk\/wp-json\/wp\/v2\/media\/2595"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/elsborstnetwerk\/wp-json\/wp\/v2\/media?parent=177"}],"wp:term":[{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/elsborstnetwerk\/wp-json\/wp\/v2\/search-tags?post=177"},{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/elsborstnetwerk\/wp-json\/wp\/v2\/labels?post=177"},{"taxonomy":"themes-or-point-of-view","embeddable":true,"href":"https:\/\/d66.nl\/elsborstnetwerk\/wp-json\/wp\/v2\/themes-or-point-of-view?post=177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}