{"id":1844,"date":"2024-12-16T15:12:45","date_gmt":"2024-12-16T15:12:45","guid":{"rendered":"https:\/\/d66.nl\/eindhoven\/?post_type=people-type&#038;p=1844"},"modified":"2025-01-09T20:44:51","modified_gmt":"2025-01-09T20:44:51","slug":"1844","status":"publish","type":"people-type","link":"https:\/\/d66.nl\/eindhoven\/mensen\/1844\/","title":{"rendered":"Robert Strijk"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--66 wrapper__spacing-bottom-mobile--76  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading heading__align--left heading__color--black heading__size--giant heading__font--serif heading__weight--regular  block-heading__heading\" id=\"nav-robert-strijk3725\"  data-nav-heading-mobile=\"Robert Strijk\" >\n\tRobert Strijk<\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--110 wrapper__spacing-bottom-desktop--60 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<section class=\"block-video\">\n\t<div\n\t\tclass=\"block-video__video-wrapper\"\n\t\tstyle=\"background-image: url('https:\/\/d66.nl\/eindhoven\/wp-content\/uploads\/sites\/159\/2024\/12\/Robert-Strijk-web-jpg.jpg')\"\n\t>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"block-video__caption-wrapper\">\n\t\t\t<div class=\"block-video__caption\">\n\t\t\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--small paragraph__weight--medium\">\n\t\tBeeld: Robert Strijk\t<\/p>\t\t\t<\/div>\n\t\t<\/div>\n\t\n<\/section>\n\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-people-introduction\">\n\t<div class=\"block-people-introduction__content\">\n\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--big\">\n\t\tRobert Strijk is wethouder van hoger- en beroepsonderwijs, mobiliteit, binnenstad en Design District.<br><br>Meer informatie vindt u op de pagina van de gemeente Eindhoven: <a href=\"https:\/\/www.eindhoven.nl\/robert-strijk\">LINK<\/a>\t<\/p><section class=\"people-bullet-point-card block-people-introduction__people-bullet-point-card\" style=\"--bg-color: var(--global-colors-texasRose)\">\n\t<div class=\"people-bullet-point-card__wrapper\">\n\t\t<div class=\"people-bullet-point-card__title\">\n\t\t\t<h2 class=\"heading    heading__font--sans heading__weight--bold\" id=\"nav-over-robert5080\" data-nav-heading-mobile=\"Over Robert\">\n\tOver Robert<\/h2>\t\t\t<div aria-hidden=\"true\" class=\"people-bullet-point-card__border\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"people-bullet-point-card__info\">\n\t\t\t<ul class=\"lists\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><label>Voornaamwoorden<\/label><span>Hij\/hem<\/span><\/li>\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div aria-hidden=\"true\" class=\"people-bullet-point-card__border\"><\/div>\n\t\t\t<div class=\"people-bullet-point-card__socialmedia\">\n\t\t\t\t<ul class=\"people-bullet-point-card__sm_panel\"><li><a href=\"https:\/\/www.linkedin.com\/in\/robert-strijk\/\" target=\"_blank\">Li<\/a><\/li><li><a href=\"https:\/\/www.facebook.com\/robert.strijk\" target=\"_blank\">Fb<\/a><\/li><\/ul>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div aria-hidden=\"true\" class=\"people-bullet-point-card__border\"><\/div>\n\n\t\t\t<div class=\"people-bullet-point-card__supportemail\">\n\t\t\t\t<span>\n\t\t\t\t\t<a href=\"https:\/\/www.eindhoven.nl\/robert-strijk\">Contact met persvoorlichting en ondersteuners<\/a>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/section><p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default\">\n\t\t\t<\/p><div class=\"content-accordion js-content-accordion\" data-accordion-opened=\"0\">\n\n\t\t\t<div aria-hidden=\"true\" class=\"content-accordion__border\"><\/div>\n\t\n\t<button id=\"content-accordion-trigger-2550763980\" class=\"content-accordion__trigger js-content-accordion-trigger\" aria-label=\"Expertises (portefeuilles)\" aria-controls>\n\t\t<div class=\"content-accordion__heading\">\n\t\t\t<h3 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-expertises--portefeuilles-6139\">\n\tExpertises (portefeuilles)<\/h3>\t\t<\/div>\n\t\t<div class=\"content-accordion__icon\" aria-hidden=\"true\"><\/div>\n\t<\/button>\n\n\t<section id=\"content-accordion-panel-2550763980\" class=\"content-accordion__panel js-content-accordion-panel\" aria-hidden=\"true\" aria-labelledby=\"content-accordion-trigger-2550763980\">\n\t\t<div class=\"content-accordion__content-wrapper\">\n\t\t\t<div class=\"content-accordion__description\">\n\t\t\t\tWethouder van hoger- en beroepsonderwijs, mobiliteit, binnenstad en Design District.\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n\t<div aria-hidden=\"true\" class=\"content-accordion__border\"><\/div>\n<\/div><div class=\"content-accordion js-content-accordion\" data-accordion-opened=\"0\">\n\n\t\n\t<button id=\"content-accordion-trigger-1453456198\" class=\"content-accordion__trigger js-content-accordion-trigger\" aria-label=\"Functie historie\" aria-controls>\n\t\t<div class=\"content-accordion__heading\">\n\t\t\t<h3 class=\"heading   heading__size--medium heading__font--sans heading__weight--bold\" id=\"nav-functie-historie8354\">\n\tFunctie historie<\/h3>\t\t<\/div>\n\t\t<div class=\"content-accordion__icon\" aria-hidden=\"true\"><\/div>\n\t<\/button>\n\n\t<section id=\"content-accordion-panel-1453456198\" class=\"content-accordion__panel js-content-accordion-panel\" aria-hidden=\"true\" aria-labelledby=\"content-accordion-trigger-1453456198\">\n\t\t<div class=\"content-accordion__content-wrapper\">\n\t\t\t<div class=\"content-accordion__description\">\n\t\t\t\t<ul class=\"content-accordion lists content-accordion__lists lists__weight--medium lists__color--black lists__type--default\"><li><label>september 2024-heden<\/label><span>Wethouder<\/span><\/li><\/ul>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n\t<div aria-hidden=\"true\" class=\"content-accordion__border\"><\/div>\n<\/div>\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"author":1380,"featured_media":1859,"menu_order":0,"template":"","search-tags":[],"labels":[33],"division-tags":[31],"class_list":["post-1844","people-type","type-people-type","status-publish","has-post-thumbnail","hentry","labels-wethouder","division-tags-stadsbestuur"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D66 Eindhoven &#8212; Onze mensen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/eindhoven\/mensen\/1844\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D66 Eindhoven &#8212; Onze mensen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/eindhoven\/mensen\/1844\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Eindhoven\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-09T20:44:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d66.nl\/eindhoven\/wp-content\/uploads\/sites\/159\/2024\/12\/Robert-Strijk-web-jpg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/mensen\\\/1844\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/mensen\\\/1844\\\/\",\"name\":\"D66 Eindhoven &#8212; Onze mensen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/mensen\\\/1844\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/mensen\\\/1844\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2024\\\/12\\\/Robert-Strijk-web-jpg.jpg\",\"datePublished\":\"2024-12-16T15:12:45+00:00\",\"dateModified\":\"2025-01-09T20:44:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/mensen\\\/1844\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/mensen\\\/1844\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/mensen\\\/1844\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2024\\\/12\\\/Robert-Strijk-web-jpg.jpg\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2024\\\/12\\\/Robert-Strijk-web-jpg.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/mensen\\\/1844\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mensen\",\"item\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/mensen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Robert Strijk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/\",\"name\":\"D66 Eindhoven\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/eindhoven\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D66 Eindhoven &#8212; Onze mensen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/eindhoven\/mensen\/1844\/","og_locale":"nl_NL","og_type":"article","og_title":"D66 Eindhoven &#8212; Onze mensen","og_url":"https:\/\/d66.nl\/eindhoven\/mensen\/1844\/","og_site_name":"D66 Eindhoven","article_modified_time":"2025-01-09T20:44:51+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/d66.nl\/eindhoven\/wp-content\/uploads\/sites\/159\/2024\/12\/Robert-Strijk-web-jpg.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/eindhoven\/mensen\/1844\/","url":"https:\/\/d66.nl\/eindhoven\/mensen\/1844\/","name":"D66 Eindhoven &#8212; Onze mensen","isPartOf":{"@id":"https:\/\/d66.nl\/eindhoven\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d66.nl\/eindhoven\/mensen\/1844\/#primaryimage"},"image":{"@id":"https:\/\/d66.nl\/eindhoven\/mensen\/1844\/#primaryimage"},"thumbnailUrl":"https:\/\/d66.nl\/eindhoven\/wp-content\/uploads\/sites\/159\/2024\/12\/Robert-Strijk-web-jpg.jpg","datePublished":"2024-12-16T15:12:45+00:00","dateModified":"2025-01-09T20:44:51+00:00","breadcrumb":{"@id":"https:\/\/d66.nl\/eindhoven\/mensen\/1844\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/eindhoven\/mensen\/1844\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/eindhoven\/mensen\/1844\/#primaryimage","url":"https:\/\/d66.nl\/eindhoven\/wp-content\/uploads\/sites\/159\/2024\/12\/Robert-Strijk-web-jpg.jpg","contentUrl":"https:\/\/d66.nl\/eindhoven\/wp-content\/uploads\/sites\/159\/2024\/12\/Robert-Strijk-web-jpg.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/eindhoven\/mensen\/1844\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/eindhoven\/"},{"@type":"ListItem","position":2,"name":"Mensen","item":"https:\/\/d66.nl\/eindhoven\/mensen\/"},{"@type":"ListItem","position":3,"name":"Robert Strijk"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/eindhoven\/#website","url":"https:\/\/d66.nl\/eindhoven\/","name":"D66 Eindhoven","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/eindhoven\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/eindhoven\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/eindhoven\/#organization","name":"D66","url":"https:\/\/d66.nl\/eindhoven\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/eindhoven\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/eindhoven\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/eindhoven\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/eindhoven\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/eindhoven\/wp-json\/wp\/v2\/people-type\/1844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/eindhoven\/wp-json\/wp\/v2\/people-type"}],"about":[{"href":"https:\/\/d66.nl\/eindhoven\/wp-json\/wp\/v2\/types\/people-type"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/eindhoven\/wp-json\/wp\/v2\/users\/1380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d66.nl\/eindhoven\/wp-json\/wp\/v2\/media\/1859"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/eindhoven\/wp-json\/wp\/v2\/media?parent=1844"}],"wp:term":[{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/eindhoven\/wp-json\/wp\/v2\/search-tags?post=1844"},{"taxonomy":"labels","embeddable":true,"href":"https:\/\/d66.nl\/eindhoven\/wp-json\/wp\/v2\/labels?post=1844"},{"taxonomy":"division-tags","embeddable":true,"href":"https:\/\/d66.nl\/eindhoven\/wp-json\/wp\/v2\/division-tags?post=1844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}