{"id":450,"date":"2026-01-21T08:00:24","date_gmt":"2026-01-21T08:00:24","guid":{"rendered":"https:\/\/d66.nl\/den-helder\/?post_type=manifesto&#038;p=450"},"modified":"2026-02-24T13:43:43","modified_gmt":"2026-02-24T13:43:43","slug":"gezondste-generatie-ooit","status":"publish","type":"manifesto","link":"https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/gezondste-generatie-ooit\/","title":{"rendered":"De gezondste generatie ooit"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper wrapper__spacing-top-large--160 wrapper__spacing-top-tablet--120 wrapper__spacing-top-mobile--100 wrapper__spacing-bottom-large--90  wrapper__gutter--none\"\n  data-background-color=\"tomato\">\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t\n<section class=\"block-video-hero js-block-video-hero\">\n\n\t<a href=\"https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/\" class=\"back-button\">\n\t<div class=\"back-button__icon\" aria-hidden=\"true\">\n\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 58.14 50.62'><path d='m32.82 50.62 25.32-25.31L32.82 0l-4.35 4.35 17.92 17.86H0v6.21h46.39L28.47 46.33l4.35 4.29z' fill='currentColor' \/><\/svg>\t<\/div>\n\t<div class=\"back-button__title back-button__title--hide-on-mobile\">\n\t\t\t<\/div>\n<\/a>\n\t<div class=\"block-video-hero__content\">\n\t\t<h1 class=\"text text-big block-video-hero__title\">De gezondste generatie ooit<\/h1><p class=\"text text-medium block-video-hero__text\">Wij willen dat iedereen in Den Helder mentaal en fysiek gezond kan leven, van jongvolwassenen die het moeilijk hebben tot eenzame ouders. Met laagdrempelige zorg, sterke wijkteams en samenwerking tussen ouders, scholen, buurtverenigingen en de gemeente ondersteunen we inwoners waar nodig. Ook investeren we in preventie, zodat problemen vroeg worden gesignaleerd en hulp snel en dichtbij huis beschikbaar is. Kinderen en jongeren verdienen een veilige, stabiele omgeving om gezond op te groeien. Daarbij is jeugdzorg een gezamenlijke verantwoordelijkheid van de hele samenleving.<\/p>\t\t<div class=\"block-video-hero__buttons-wrap\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"block-video-hero__media\">\n\t\t<div\n\t\t\tclass=\"block-video-hero__video-wrapper\"\n\t\t\tstyle=\"background-image: url('https:\/\/media.d66.nl\/uploads\/sites\/172\/2022\/01\/Blije-ouderen-660x440-1.jpeg')\">\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"block-video-hero__caption-wrapper\">\n\t\t\t\t<div class=\"block-video-hero__caption\">\n\t\t\t\t\t<p class=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--small paragraph__weight--medium\">\n\t\tBeeld: Syda Productions \/ stock.adobe.com\t<\/p>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--semiBold  block-post-content__heading\" id=\"nav--strong-wijkteams-en-preventie--strong-2359\" data-nav-heading-mobile=\"Wijkteams en preventie\">\n\t<strong>Wijkteams en preventie<\/strong><\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t\t<div class=\"block-lists  block-lists__color--black\">\n\t\t<p class=\"paragraph  paragraph__color--black paragraph__size--default\">\n\t\t\t<\/p><ul class=\"block-lists lists__lists lists__weight--medium lists__color--black lists__type--default\">\n\t<li>We zetten verder in op\u00a0<strong>wijkgericht werken<\/strong>\u00a0door de beschikbaarheid en zichtbaarheid van professionele, multidisciplinaire jeugd- en gezinsteams te vergroten, zodat gezinnen sneller passende hulp krijgen en problemen eerder worden gesignaleerd.<\/li><li>We zorgen dat gezinnen\u00a0<strong>\u00e9\u00e9n vast aanspreekpunt<\/strong>\u00a0hebben, met meer tijd en ruimte om \u00e9cht het verschil te maken.<\/li><li>We\u00a0<strong>signaleren problemen<\/strong>\u00a0in de opvoeding en in gezinnen\u00a0<strong>vroeg<\/strong>\u00a0door jeugd- en gezinsteams structureel te laten samenwerken met scholen en kinderopvang, zodat kinderen en ouders tijdig passende hulp krijgen.<\/li><li>We zetten stevig in op\u00a0<strong>preventie<\/strong>, zodat minder zwaardere zorg nodig is en\u00a0<strong>wachttijden<\/strong>\u00a0voor gezinnen met complexere problemen afnemen.<\/li><li>We maken meer gebruik van buurtteams en vrijwilligers om\u00a0<strong>eenzaamheid en sociaal isolement<\/strong>\u00a0onder jongeren en ouderen te voorkomen en problemen vroeg te signaleren, vooral bij jongeren die dreigen uit te vallen.<\/li><\/ul>\t<\/div>\n\t\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--bold  block-post-content__heading\" id=\"nav--strong-sterke-gezinnen-en-sociale-basis--strong-9001\" data-nav-heading-mobile=\"Sterke gezinnen en sociale basis\">\n\t<strong>Sterke gezinnen en sociale basis<\/strong><\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t\t<div class=\"block-lists  block-lists__color--black\">\n\t\t<p class=\"paragraph  paragraph__color--black paragraph__size--default\">\n\t\t\t<\/p><ul class=\"block-lists lists__lists lists__weight--medium lists__color--black lists__type--default\">\n\t<li>We versterken de\u00a0<strong>sociale basis<\/strong>\u00a0van gezinnen door gratis en laagdrempelige opvoedcursussen, aanspreekpunten op school voor ouders en inloopspreekuren in wijkcentra verder uit te breiden.<\/li><li>We ondersteunen\u00a0<strong>buurtinitiatieven<\/strong>\u00a0die gezinnen en wijken sterker maken.<\/li><li>We bieden ondersteuning bij\u00a0<strong>bestaanszekerheid<\/strong>, zoals energiearmoede, huisvesting en inkomen, ook voor jongeren die vanuit de jeugdzorg zelfstandig gaan wonen en extra hulp nodig hebben. Een concreet voorbeeld hiervan is de pilot basisinkomen voort te zetten.<\/li><li>We zorgen voor\u00a0<strong>praktische ondersteuning in instabiele thuissituaties<\/strong>\u00a0en snellere toegang tot schuldhulpverlening voor gezinnen met kinderen.<\/li><\/ul>\t<\/div>\n\t\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--bold  block-post-content__heading\" id=\"nav--strong-jeugdzorg-als-gezamenlijke-verantwoordelijkheid--strong-7553\" data-nav-heading-mobile=\"Jeugdzorg als gezamenlijke verantwoordelijkheid\">\n\t<strong>Jeugdzorg als gezamenlijke verantwoordelijkheid<\/strong><\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t\t<div class=\"block-lists  block-lists__color--black\">\n\t\t<p class=\"paragraph  paragraph__color--black paragraph__size--default\">\n\t\t\t<\/p><ul class=\"block-lists lists__lists lists__weight--medium lists__color--black lists__type--default\">\n\t<li>We zien\u00a0<strong>jeugdzorg als taak van de hele gemeenschap<\/strong>: ouders, scholen, buurt- en sport- en buurtverenigingen en de gemeente samen.<\/li><li>We maken meer gebruik van\u00a0<strong>buurtcoaches en jongerenwerkers<\/strong>\u00a0als verbindende schakels in de wijken, omdat zij laagdrempelig zijn, vertrouwen opbouwen en jongeren begeleiden naar sport, onderwijs en hulp.<\/li><li>We zetten sportclubs, cultuurverenigingen en buurtinitiatieven aan om meer in te spelen op\u00a0<strong>kwetsbare doelgroepen<\/strong>.<\/li><li>We bieden\u00a0<strong>trainingen aan voor vrijwilligers en opvoeders<\/strong>\u00a0om signalen van kwetsbaarheid bij jongeren beter te herkennen.<\/li><\/ul>\t<\/div>\n\t\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--bold  block-post-content__heading\" id=\"nav--strong-samenwerking-en-co--rdinatie--strong-273\" data-nav-heading-mobile=\"Samenwerking en co\u00f6rdinatie\">\n\t<strong>Samenwerking en co\u00f6rdinatie<\/strong><\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t\t<div class=\"block-lists  block-lists__color--black\">\n\t\t<p class=\"paragraph  paragraph__color--black paragraph__size--default\">\n\t\t\t<\/p><ul class=\"block-lists lists__lists lists__weight--medium lists__color--black lists__type--default\">\n\t<li>We werken\u00a0<strong>domein-overstijgend<\/strong>\u00a0samen tussen school, wijkteam en hulpverlening.<\/li><li>We zorgen dat er\u00a0<strong>\u00e9\u00e9n universele werkwijze<\/strong>\u00a0is tussen aanbieders en verschillende domeinen om onnodig werk en tijdverlies te voorkomen.<\/li><\/ul>\t<\/div>\n\t\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--bold  block-post-content__heading\" id=\"nav--strong-mentale-gezondheid-en-welzijn--strong-107\" data-nav-heading-mobile=\"Mentale gezondheid en welzijn\">\n\t<strong>Mentale gezondheid en welzijn<\/strong><\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t\t<div class=\"block-lists  block-lists__color--black\">\n\t\t<p class=\"paragraph  paragraph__color--black paragraph__size--default\">\n\t\t\t<\/p><ul class=\"block-lists lists__lists lists__weight--medium lists__color--black lists__type--default\">\n\t<li>We\u00a0<strong>verbeteren de mentale gezondheid<\/strong>\u00a0van inwoners actief door preventie, bewustwording en vroegsignalering centraal te stellen, onder meer via wijkgerichte voorzieningen, training van professionals en laagdrempelige ondersteuning dicht bij huis.<\/li><li>We breiden\u00a0<strong>mentor- en maatjesprojecten<\/strong>\u00a0voor kwetsbare doelgroepen uit, zodat zij tijdige steun en een veilige plek vinden.<\/li><li>We vergroten bewustzijn en aanpak van\u00a0<strong>su\u00efcidepreventie<\/strong>\u00a0onder jongvolwassenen in samenwerking met GGD, scholen en verenigingen.<\/li><li>We maken de zogenaamde<strong>\u00a0<a href=\"https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/manosphere\/\">manosphere<\/a><\/strong>\u00a0bespreekbaar via onderwijs, sportverenigingen en jongerenwerk, zodat jongens en jongemannen vrijer kunnen opgroeien zonder schadelijke rolpatronen.<\/li><\/ul>\t<\/div>\n\t\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"author":672,"featured_media":888,"parent":0,"menu_order":1,"template":"full-width.php","meta":{"_acf_changed":true},"search-tags":[6],"themes-or-point-of-view":[25],"class_list":["post-450","manifesto","type-manifesto","status-publish","has-post-thumbnail","hentry","search-tags-zorg-gezondheid-sport","themes-or-point-of-view-point-of-view"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D66 Den Helder &#8212; De gezondste generatie ooit | Verkiezingsprogramma<\/title>\n<meta name=\"description\" content=\"Wij zetten in om eenzaamheid onder ouderen en jongeren te verminderen en om achterstand in de jeugdzorg weg te werken. \u2714Stem 18 maart D66\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/gezondste-generatie-ooit\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D66 Den Helder &#8212; De gezondste generatie ooit | Verkiezingsprogramma\" \/>\n<meta property=\"og:description\" content=\"Wij zetten in om eenzaamheid onder ouderen en jongeren te verminderen en om achterstand in de jeugdzorg weg te werken. \u2714Stem 18 maart D66\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/gezondste-generatie-ooit\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Den Helder\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-24T13:43:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.d66.nl\/uploads\/sites\/172\/2022\/01\/Blije-ouderen-660x440-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/verkiezingsprogramma\\\/gezondste-generatie-ooit\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/verkiezingsprogramma\\\/gezondste-generatie-ooit\\\/\",\"name\":\"D66 Den Helder &#8212; De gezondste generatie ooit | Verkiezingsprogramma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/verkiezingsprogramma\\\/gezondste-generatie-ooit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/verkiezingsprogramma\\\/gezondste-generatie-ooit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/172\\\/2022\\\/01\\\/Blije-ouderen-660x440-1.jpeg\",\"datePublished\":\"2026-01-21T08:00:24+00:00\",\"dateModified\":\"2026-02-24T13:43:43+00:00\",\"description\":\"Wij zetten in om eenzaamheid onder ouderen en jongeren te verminderen en om achterstand in de jeugdzorg weg te werken. \u2714Stem 18 maart D66\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/verkiezingsprogramma\\\/gezondste-generatie-ooit\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/den-helder\\\/verkiezingsprogramma\\\/gezondste-generatie-ooit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/verkiezingsprogramma\\\/gezondste-generatie-ooit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/172\\\/2022\\\/01\\\/Blije-ouderen-660x440-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/media.d66.nl\\\/uploads\\\/sites\\\/172\\\/2022\\\/01\\\/Blije-ouderen-660x440-1.jpeg\",\"width\":660,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/verkiezingsprogramma\\\/gezondste-generatie-ooit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De gezondste generatie ooit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/\",\"name\":\"D66 Den Helder\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D66 Den Helder &#8212; De gezondste generatie ooit | Verkiezingsprogramma","description":"Wij zetten in om eenzaamheid onder ouderen en jongeren te verminderen en om achterstand in de jeugdzorg weg te werken. \u2714Stem 18 maart D66","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/gezondste-generatie-ooit\/","og_locale":"nl_NL","og_type":"article","og_title":"D66 Den Helder &#8212; De gezondste generatie ooit | Verkiezingsprogramma","og_description":"Wij zetten in om eenzaamheid onder ouderen en jongeren te verminderen en om achterstand in de jeugdzorg weg te werken. \u2714Stem 18 maart D66","og_url":"https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/gezondste-generatie-ooit\/","og_site_name":"D66 Den Helder","article_modified_time":"2026-02-24T13:43:43+00:00","og_image":[{"width":660,"height":440,"url":"https:\/\/media.d66.nl\/uploads\/sites\/172\/2022\/01\/Blije-ouderen-660x440-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/gezondste-generatie-ooit\/","url":"https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/gezondste-generatie-ooit\/","name":"D66 Den Helder &#8212; De gezondste generatie ooit | Verkiezingsprogramma","isPartOf":{"@id":"https:\/\/d66.nl\/den-helder\/#website"},"primaryImageOfPage":{"@id":"https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/gezondste-generatie-ooit\/#primaryimage"},"image":{"@id":"https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/gezondste-generatie-ooit\/#primaryimage"},"thumbnailUrl":"https:\/\/media.d66.nl\/uploads\/sites\/172\/2022\/01\/Blije-ouderen-660x440-1.jpeg","datePublished":"2026-01-21T08:00:24+00:00","dateModified":"2026-02-24T13:43:43+00:00","description":"Wij zetten in om eenzaamheid onder ouderen en jongeren te verminderen en om achterstand in de jeugdzorg weg te werken. \u2714Stem 18 maart D66","breadcrumb":{"@id":"https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/gezondste-generatie-ooit\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/gezondste-generatie-ooit\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/gezondste-generatie-ooit\/#primaryimage","url":"https:\/\/media.d66.nl\/uploads\/sites\/172\/2022\/01\/Blije-ouderen-660x440-1.jpeg","contentUrl":"https:\/\/media.d66.nl\/uploads\/sites\/172\/2022\/01\/Blije-ouderen-660x440-1.jpeg","width":660,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/den-helder\/verkiezingsprogramma\/gezondste-generatie-ooit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/den-helder\/"},{"@type":"ListItem","position":2,"name":"De gezondste generatie ooit"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/den-helder\/#website","url":"https:\/\/d66.nl\/den-helder\/","name":"D66 Den Helder","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/den-helder\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/den-helder\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/den-helder\/#organization","name":"D66","url":"https:\/\/d66.nl\/den-helder\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/den-helder\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/den-helder\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/den-helder\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/den-helder\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/den-helder\/wp-json\/wp\/v2\/verkiezingsprogramma\/450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/den-helder\/wp-json\/wp\/v2\/verkiezingsprogramma"}],"about":[{"href":"https:\/\/d66.nl\/den-helder\/wp-json\/wp\/v2\/types\/manifesto"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/den-helder\/wp-json\/wp\/v2\/users\/672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d66.nl\/den-helder\/wp-json\/wp\/v2\/media\/888"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/den-helder\/wp-json\/wp\/v2\/media?parent=450"}],"wp:term":[{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/den-helder\/wp-json\/wp\/v2\/search-tags?post=450"},{"taxonomy":"themes-or-point-of-view","embeddable":true,"href":"https:\/\/d66.nl\/den-helder\/wp-json\/wp\/v2\/themes-or-point-of-view?post=450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}