{"id":1,"count":22,"description":"","link":"https:\/\/d66.nl\/den-helder\/category\/d66\/","name":"D66","slug":"d66","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D66 Archives &#8212; D66 Den Helder<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/den-helder\/category\/d66\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D66 Archives &#8212; D66 Den Helder\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/den-helder\/category\/d66\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Den Helder\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/category\\\/d66\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/category\\\/d66\\\/\",\"name\":\"D66 Archives &#8212; D66 Den Helder\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/category\\\/d66\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/category\\\/d66\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D66\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/\",\"name\":\"D66 Den Helder\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/den-helder\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D66 Archives &#8212; D66 Den Helder","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/den-helder\/category\/d66\/","og_locale":"nl_NL","og_type":"article","og_title":"D66 Archives &#8212; D66 Den Helder","og_url":"https:\/\/d66.nl\/den-helder\/category\/d66\/","og_site_name":"D66 Den Helder","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/d66.nl\/den-helder\/category\/d66\/","url":"https:\/\/d66.nl\/den-helder\/category\/d66\/","name":"D66 Archives &#8212; D66 Den Helder","isPartOf":{"@id":"https:\/\/d66.nl\/den-helder\/#website"},"breadcrumb":{"@id":"https:\/\/d66.nl\/den-helder\/category\/d66\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/den-helder\/category\/d66\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/den-helder\/"},{"@type":"ListItem","position":2,"name":"D66"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/den-helder\/#website","url":"https:\/\/d66.nl\/den-helder\/","name":"D66 Den Helder","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/den-helder\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/den-helder\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/den-helder\/#organization","name":"D66","url":"https:\/\/d66.nl\/den-helder\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/den-helder\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/den-helder\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/den-helder\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/den-helder\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/den-helder\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/den-helder\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/d66.nl\/den-helder\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/d66.nl\/den-helder\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}