{"id":2,"count":18,"description":"","link":"https:\/\/d66.nl\/bunnik\/search-tags\/optimale-kansen-voor-iedereen\/","name":"Optimale kansen voor iedereen","slug":"optimale-kansen-voor-iedereen","taxonomy":"search-tags","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tag: Optimale kansen voor iedereen &#8212; D66 Bunnik<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/bunnik\/search-tags\/optimale-kansen-voor-iedereen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tag: Optimale kansen voor iedereen &#8212; D66 Bunnik\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/bunnik\/search-tags\/optimale-kansen-voor-iedereen\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Bunnik\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d66.nl\/bunnik\/wp-content\/uploads\/sites\/202\/2025\/08\/PXL_20250522_125126536.MP_-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1928\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/search-tags\\\/optimale-kansen-voor-iedereen\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/search-tags\\\/optimale-kansen-voor-iedereen\\\/\",\"name\":\"Tag: Optimale kansen voor iedereen &#8212; D66 Bunnik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/search-tags\\\/optimale-kansen-voor-iedereen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/search-tags\\\/optimale-kansen-voor-iedereen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Optimale kansen voor iedereen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/\",\"name\":\"D66 Bunnik\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/#organization\"},\"alternateName\":\"D66 Bunnik, Odijk en Werkhoven\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/#organization\",\"name\":\"D66 Bunnik, Odijk en Werkhoven\",\"alternateName\":\"D66 Bunnik\",\"url\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2021\\\/12\\\/Logo-D66-Bunnik.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2021\\\/12\\\/Logo-D66-Bunnik.png\",\"width\":3702,\"height\":2521,\"caption\":\"D66 Bunnik, Odijk en Werkhoven\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/bunnik\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/D66Bunnik\",\"https:\\\/\\\/instagram.com\\\/D66Bunnik\",\"https:\\\/\\\/mastodon.online\\\/@d66bunnik\",\"https:\\\/\\\/bsky.app\\\/profile\\\/d66bunnik.bsky.social\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tag: Optimale kansen voor iedereen &#8212; D66 Bunnik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/bunnik\/search-tags\/optimale-kansen-voor-iedereen\/","og_locale":"nl_NL","og_type":"article","og_title":"Tag: Optimale kansen voor iedereen &#8212; D66 Bunnik","og_url":"https:\/\/d66.nl\/bunnik\/search-tags\/optimale-kansen-voor-iedereen\/","og_site_name":"D66 Bunnik","og_image":[{"width":2560,"height":1928,"url":"https:\/\/d66.nl\/bunnik\/wp-content\/uploads\/sites\/202\/2025\/08\/PXL_20250522_125126536.MP_-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/d66.nl\/bunnik\/search-tags\/optimale-kansen-voor-iedereen\/","url":"https:\/\/d66.nl\/bunnik\/search-tags\/optimale-kansen-voor-iedereen\/","name":"Tag: Optimale kansen voor iedereen &#8212; D66 Bunnik","isPartOf":{"@id":"https:\/\/d66.nl\/bunnik\/#website"},"breadcrumb":{"@id":"https:\/\/d66.nl\/bunnik\/search-tags\/optimale-kansen-voor-iedereen\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/bunnik\/search-tags\/optimale-kansen-voor-iedereen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/bunnik\/"},{"@type":"ListItem","position":2,"name":"Optimale kansen voor iedereen"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/bunnik\/#website","url":"https:\/\/d66.nl\/bunnik\/","name":"D66 Bunnik","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/bunnik\/#organization"},"alternateName":"D66 Bunnik, Odijk en Werkhoven","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/bunnik\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/bunnik\/#organization","name":"D66 Bunnik, Odijk en Werkhoven","alternateName":"D66 Bunnik","url":"https:\/\/d66.nl\/bunnik\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/bunnik\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/bunnik\/wp-content\/uploads\/sites\/202\/2021\/12\/Logo-D66-Bunnik.png","contentUrl":"https:\/\/d66.nl\/bunnik\/wp-content\/uploads\/sites\/202\/2021\/12\/Logo-D66-Bunnik.png","width":3702,"height":2521,"caption":"D66 Bunnik, Odijk en Werkhoven"},"image":{"@id":"https:\/\/d66.nl\/bunnik\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/D66Bunnik","https:\/\/instagram.com\/D66Bunnik","https:\/\/mastodon.online\/@d66bunnik","https:\/\/bsky.app\/profile\/d66bunnik.bsky.social"]}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/bunnik\/wp-json\/wp\/v2\/search-tags\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/bunnik\/wp-json\/wp\/v2\/search-tags"}],"about":[{"href":"https:\/\/d66.nl\/bunnik\/wp-json\/wp\/v2\/taxonomies\/search-tags"}],"wp:post_type":[{"href":"https:\/\/d66.nl\/bunnik\/wp-json\/wp\/v2\/posts?search-tags=2"},{"href":"https:\/\/d66.nl\/bunnik\/wp-json\/wp\/v2\/pages?search-tags=2"},{"href":"https:\/\/d66.nl\/bunnik\/wp-json\/wp\/v2\/people-type?search-tags=2"},{"href":"https:\/\/d66.nl\/bunnik\/wp-json\/wp\/v2\/events?search-tags=2"},{"href":"https:\/\/d66.nl\/bunnik\/wp-json\/wp\/v2\/vacatures?search-tags=2"},{"href":"https:\/\/d66.nl\/bunnik\/wp-json\/wp\/v2\/publications?search-tags=2"},{"href":"https:\/\/d66.nl\/bunnik\/wp-json\/wp\/v2\/initiatieven?search-tags=2"},{"href":"https:\/\/d66.nl\/bunnik\/wp-json\/wp\/v2\/verkiezingsprogramma?search-tags=2"},{"href":"https:\/\/d66.nl\/bunnik\/wp-json\/wp\/v2\/standpunten?search-tags=2"},{"href":"https:\/\/d66.nl\/bunnik\/wp-json\/wp\/v2\/liveblog?search-tags=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}