{"id":3,"count":2,"description":"","link":"https:\/\/d66.nl\/boxtel\/search-tags\/klimaat\/","name":"Klimaat, natuur en milieu","slug":"klimaat","taxonomy":"search-tags","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Klimaat, natuur en milieu Archives &#8212; D66 Boxtel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/boxtel\/search-tags\/klimaat\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Klimaat, natuur en milieu Archives &#8212; D66 Boxtel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/boxtel\/search-tags\/klimaat\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Boxtel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/search-tags\\\/klimaat\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/search-tags\\\/klimaat\\\/\",\"name\":\"Klimaat, natuur en milieu Archives &#8212; D66 Boxtel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/search-tags\\\/klimaat\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/search-tags\\\/klimaat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Klimaat, natuur en milieu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/\",\"name\":\"D66 Boxtel\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/boxtel\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Klimaat, natuur en milieu Archives &#8212; D66 Boxtel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/boxtel\/search-tags\/klimaat\/","og_locale":"nl_NL","og_type":"article","og_title":"Klimaat, natuur en milieu Archives &#8212; D66 Boxtel","og_url":"https:\/\/d66.nl\/boxtel\/search-tags\/klimaat\/","og_site_name":"D66 Boxtel","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/d66.nl\/boxtel\/search-tags\/klimaat\/","url":"https:\/\/d66.nl\/boxtel\/search-tags\/klimaat\/","name":"Klimaat, natuur en milieu Archives &#8212; D66 Boxtel","isPartOf":{"@id":"https:\/\/d66.nl\/boxtel\/#website"},"breadcrumb":{"@id":"https:\/\/d66.nl\/boxtel\/search-tags\/klimaat\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/boxtel\/search-tags\/klimaat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/boxtel\/"},{"@type":"ListItem","position":2,"name":"Klimaat, natuur en milieu"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/boxtel\/#website","url":"https:\/\/d66.nl\/boxtel\/","name":"D66 Boxtel","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/boxtel\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/boxtel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/boxtel\/#organization","name":"D66","url":"https:\/\/d66.nl\/boxtel\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/boxtel\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/boxtel\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/boxtel\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/boxtel\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/boxtel\/wp-json\/wp\/v2\/search-tags\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/boxtel\/wp-json\/wp\/v2\/search-tags"}],"about":[{"href":"https:\/\/d66.nl\/boxtel\/wp-json\/wp\/v2\/taxonomies\/search-tags"}],"wp:post_type":[{"href":"https:\/\/d66.nl\/boxtel\/wp-json\/wp\/v2\/posts?search-tags=3"},{"href":"https:\/\/d66.nl\/boxtel\/wp-json\/wp\/v2\/pages?search-tags=3"},{"href":"https:\/\/d66.nl\/boxtel\/wp-json\/wp\/v2\/people-type?search-tags=3"},{"href":"https:\/\/d66.nl\/boxtel\/wp-json\/wp\/v2\/events?search-tags=3"},{"href":"https:\/\/d66.nl\/boxtel\/wp-json\/wp\/v2\/vacatures?search-tags=3"},{"href":"https:\/\/d66.nl\/boxtel\/wp-json\/wp\/v2\/publications?search-tags=3"},{"href":"https:\/\/d66.nl\/boxtel\/wp-json\/wp\/v2\/initiatieven?search-tags=3"},{"href":"https:\/\/d66.nl\/boxtel\/wp-json\/wp\/v2\/verkiezingsprogramma?search-tags=3"},{"href":"https:\/\/d66.nl\/boxtel\/wp-json\/wp\/v2\/standpunten?search-tags=3"},{"href":"https:\/\/d66.nl\/boxtel\/wp-json\/wp\/v2\/liveblog?search-tags=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}