{"id":9,"count":10,"description":"","link":"https:\/\/d66.nl\/amstelveen\/search-tags\/veiligheid-criminaliteit\/","name":"Veiligheid en criminaliteit","slug":"veiligheid-criminaliteit","taxonomy":"search-tags","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veiligheid en criminaliteit Archives &#8212; D66 Amstelveen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/amstelveen\/search-tags\/veiligheid-criminaliteit\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veiligheid en criminaliteit Archives &#8212; D66 Amstelveen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/amstelveen\/search-tags\/veiligheid-criminaliteit\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Amstelveen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/amstelveen\\\/search-tags\\\/veiligheid-criminaliteit\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/amstelveen\\\/search-tags\\\/veiligheid-criminaliteit\\\/\",\"name\":\"Veiligheid en criminaliteit Archives &#8212; D66 Amstelveen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/amstelveen\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/amstelveen\\\/search-tags\\\/veiligheid-criminaliteit\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/amstelveen\\\/search-tags\\\/veiligheid-criminaliteit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/amstelveen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veiligheid en criminaliteit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/amstelveen\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/amstelveen\\\/\",\"name\":\"D66 Amstelveen\",\"description\":\"Just another D66 Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/amstelveen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veiligheid en criminaliteit Archives &#8212; D66 Amstelveen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/amstelveen\/search-tags\/veiligheid-criminaliteit\/","og_locale":"nl_NL","og_type":"article","og_title":"Veiligheid en criminaliteit Archives &#8212; D66 Amstelveen","og_url":"https:\/\/d66.nl\/amstelveen\/search-tags\/veiligheid-criminaliteit\/","og_site_name":"D66 Amstelveen","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/d66.nl\/amstelveen\/search-tags\/veiligheid-criminaliteit\/","url":"https:\/\/d66.nl\/amstelveen\/search-tags\/veiligheid-criminaliteit\/","name":"Veiligheid en criminaliteit Archives &#8212; D66 Amstelveen","isPartOf":{"@id":"https:\/\/d66.nl\/amstelveen\/#website"},"breadcrumb":{"@id":"https:\/\/d66.nl\/amstelveen\/search-tags\/veiligheid-criminaliteit\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/amstelveen\/search-tags\/veiligheid-criminaliteit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/amstelveen\/"},{"@type":"ListItem","position":2,"name":"Veiligheid en criminaliteit"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/amstelveen\/#website","url":"https:\/\/d66.nl\/amstelveen\/","name":"D66 Amstelveen","description":"Just another D66 Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/amstelveen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/amstelveen\/wp-json\/wp\/v2\/search-tags\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/amstelveen\/wp-json\/wp\/v2\/search-tags"}],"about":[{"href":"https:\/\/d66.nl\/amstelveen\/wp-json\/wp\/v2\/taxonomies\/search-tags"}],"wp:post_type":[{"href":"https:\/\/d66.nl\/amstelveen\/wp-json\/wp\/v2\/posts?search-tags=9"},{"href":"https:\/\/d66.nl\/amstelveen\/wp-json\/wp\/v2\/pages?search-tags=9"},{"href":"https:\/\/d66.nl\/amstelveen\/wp-json\/wp\/v2\/people-type?search-tags=9"},{"href":"https:\/\/d66.nl\/amstelveen\/wp-json\/wp\/v2\/events?search-tags=9"},{"href":"https:\/\/d66.nl\/amstelveen\/wp-json\/wp\/v2\/vacatures?search-tags=9"},{"href":"https:\/\/d66.nl\/amstelveen\/wp-json\/wp\/v2\/publications?search-tags=9"},{"href":"https:\/\/d66.nl\/amstelveen\/wp-json\/wp\/v2\/initiatieven?search-tags=9"},{"href":"https:\/\/d66.nl\/amstelveen\/wp-json\/wp\/v2\/verkiezingsprogramma?search-tags=9"},{"href":"https:\/\/d66.nl\/amstelveen\/wp-json\/wp\/v2\/standpunten?search-tags=9"},{"href":"https:\/\/d66.nl\/amstelveen\/wp-json\/wp\/v2\/liveblog?search-tags=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}