{"id":734,"date":"2021-12-28T17:25:39","date_gmt":"2021-12-28T17:25:39","guid":{"rendered":"https:\/\/d66.nl\/aalten\/?post_type=manifesto&#038;p=734"},"modified":"2021-12-28T17:25:40","modified_gmt":"2021-12-28T17:25:40","slug":"digitale-veiligheid","status":"publish","type":"manifesto","link":"https:\/\/d66.nl\/aalten\/verkiezingsprogramma\/voor-een-sterke-en-veilige-achterhoek\/digitale-veiligheid\/","title":{"rendered":"Digitale veiligheid"},"content":{"rendered":"<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--66 wrapper__spacing-bottom-mobile--76  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--14 wrapper__width-desktop--20 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--4 wrapper__offset-mobile--0\">\n\t\t<h1 class=\"heading   heading__size--giant heading__font--serif heading__weight--regular  block-heading__heading\" id=\"nav--strong-digitale-veiligheid--strong-3833\"  data-nav-heading-mobile=\"Digitale veiligheid\" >\n\t<strong>Digitale veiligheid<\/strong><\/h1>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-mobile--40  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--13 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<p\n\t\tclass=\"paragraph   paragraph__size--big   block-paragraph__paragraph\"\n\t\t\t>\n\t\tD66 staat ook voor vrijheid, privacy en veiligheid in de digitale wereld. De Achterhoeker is eigenzinnig en wil vrij kunnen zijn, hierbij horen ook digitale vrijheid en veiligheid en niet constant digitaal gevolgd worden. Digitaal volgen moet alleen ingezet worden bij zwaarwegend algemeen belang.\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--semiBold  block-post-content__heading\" id=\"nav-cyberveiligheid8531\" data-nav-heading-mobile=\"Cyberveiligheid\">\n\tCyberveiligheid<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tDe gemeente betaalt uit principe geen losgeld aan criminelen voor ransomware. De gemeente heeft een actueel plan om met cyber aanval om te gaan.\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t\t<div class=\"block-lists  block-lists__color--black\">\n\t\t<p class=\"paragraph  paragraph__color--black paragraph__size--default\">\n\t\t\t<\/p><ul class=\"block-lists lists__lists lists__weight--medium lists__color--black lists__type--arrow\">\n\t<li><strong>De gemeente betaalt uit principe geen losgeld aan criminelen voor cybergijzeling.<\/strong><\/li><\/ul>\t<\/div>\n\t\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--50 wrapper__spacing-bottom-desktop--70 wrapper__spacing-bottom-mobile--50  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--18 wrapper__width-desktop--22 wrapper__width-mobile--24 wrapper__offset-large--6 wrapper__offset-desktop--2 wrapper__offset-mobile--0\">\n\t\t<section class=\"block-post-content\">\n\t<div class=\"block-post-content__title\">\n\t\t<h3 class=\"heading  heading__color--black heading__size--medium heading__font--sans heading__weight--semiBold  block-post-content__heading\" id=\"nav-persoonsgegevens2053\" data-nav-heading-mobile=\"Persoonsgegevens\">\n\tPersoonsgegevens<\/h3>\t<\/div>\n\t<div class=\"block-post-content__content\">\n\t\t\n<div\n  id=\"\"\n  class=\"wrapper  wrapper__spacing-bottom-large--30 wrapper__spacing-bottom-desktop--20  wrapper__gutter--none\"\n  >\n  \t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t  <div class=\"wrapper__inner wrapper__width-large--24 wrapper__width-mobile--24\">\n\t\t<p\n\t\tclass=\"paragraph paragraph__align--left paragraph__color--black paragraph__size--default   block-paragraph__paragraph\"\n\t\t\t>\n\t\tBij het bewaren van persoonlijke informatie is terughoudendheid geboden. Datalekken worden altijd gemeld en openbaar gemaakt, hoe klein ook. De gemeente moet zich er bewust van zijn dat het toepassen van algoritmes kan leiden tot onbedoelde vooroordelen.\t<\/p>\t  <\/div>\n\t<\/div>\n  <\/div>\n\n\t<\/div>\n\n\t<div class=\"block-post-content__sidebar\">\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/section>\n\t  <\/div>\n\t<\/div>\n  <\/div>\n","protected":false},"author":437,"featured_media":0,"parent":475,"menu_order":5,"template":"","meta":{"_acf_changed":false},"themes-or-point-of-view":[25],"search-tags":[9,7],"class_list":["post-734","manifesto","type-manifesto","status-publish","hentry","themes-or-point-of-view-point-of-view","search-tags-veiligheid-criminaliteit","search-tags-vrijheid-gelijkheid"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D66 Aalten-Dinxperlo &#8212; Digitale veiligheid | Verkiezingsprogramma<\/title>\n<meta name=\"description\" content=\"D66 staat ook voor vrijheid, privacy en veiligheid in de digitale wereld. De gemeente betaalt uit principe geen losgeld aan criminelen voor cybergijzeling.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d66.nl\/aalten\/verkiezingsprogramma\/voor-een-sterke-en-veilige-achterhoek\/digitale-veiligheid\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D66 Aalten-Dinxperlo &#8212; Digitale veiligheid | Verkiezingsprogramma\" \/>\n<meta property=\"og:description\" content=\"D66 staat ook voor vrijheid, privacy en veiligheid in de digitale wereld. De gemeente betaalt uit principe geen losgeld aan criminelen voor cybergijzeling.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d66.nl\/aalten\/verkiezingsprogramma\/voor-een-sterke-en-veilige-achterhoek\/digitale-veiligheid\/\" \/>\n<meta property=\"og:site_name\" content=\"D66 Aalten-Dinxperlo\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-28T17:25:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/verkiezingsprogramma\\\/voor-een-sterke-en-veilige-achterhoek\\\/digitale-veiligheid\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/verkiezingsprogramma\\\/voor-een-sterke-en-veilige-achterhoek\\\/digitale-veiligheid\\\/\",\"name\":\"D66 Aalten-Dinxperlo &#8212; Digitale veiligheid | Verkiezingsprogramma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/#website\"},\"datePublished\":\"2021-12-28T17:25:39+00:00\",\"dateModified\":\"2021-12-28T17:25:40+00:00\",\"description\":\"D66 staat ook voor vrijheid, privacy en veiligheid in de digitale wereld. De gemeente betaalt uit principe geen losgeld aan criminelen voor cybergijzeling.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/verkiezingsprogramma\\\/voor-een-sterke-en-veilige-achterhoek\\\/digitale-veiligheid\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/d66.nl\\\/aalten\\\/verkiezingsprogramma\\\/voor-een-sterke-en-veilige-achterhoek\\\/digitale-veiligheid\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/verkiezingsprogramma\\\/voor-een-sterke-en-veilige-achterhoek\\\/digitale-veiligheid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voor een sterke en veilige Achterhoek\",\"item\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/verkiezingsprogramma\\\/voor-een-sterke-en-veilige-achterhoek\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Digitale veiligheid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/#website\",\"url\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/\",\"name\":\"D66 Aalten-Dinxperlo\",\"description\":\"Just another D66 Sites site\",\"publisher\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/#organization\",\"name\":\"D66\",\"url\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"contentUrl\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/d66-themas-algemeen-og.png\",\"width\":1200,\"height\":628,\"caption\":\"D66\"},\"image\":{\"@id\":\"https:\\\/\\\/d66.nl\\\/aalten\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D66 Aalten-Dinxperlo &#8212; Digitale veiligheid | Verkiezingsprogramma","description":"D66 staat ook voor vrijheid, privacy en veiligheid in de digitale wereld. De gemeente betaalt uit principe geen losgeld aan criminelen voor cybergijzeling.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d66.nl\/aalten\/verkiezingsprogramma\/voor-een-sterke-en-veilige-achterhoek\/digitale-veiligheid\/","og_locale":"nl_NL","og_type":"article","og_title":"D66 Aalten-Dinxperlo &#8212; Digitale veiligheid | Verkiezingsprogramma","og_description":"D66 staat ook voor vrijheid, privacy en veiligheid in de digitale wereld. De gemeente betaalt uit principe geen losgeld aan criminelen voor cybergijzeling.","og_url":"https:\/\/d66.nl\/aalten\/verkiezingsprogramma\/voor-een-sterke-en-veilige-achterhoek\/digitale-veiligheid\/","og_site_name":"D66 Aalten-Dinxperlo","article_modified_time":"2021-12-28T17:25:40+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/d66.nl\/aalten\/verkiezingsprogramma\/voor-een-sterke-en-veilige-achterhoek\/digitale-veiligheid\/","url":"https:\/\/d66.nl\/aalten\/verkiezingsprogramma\/voor-een-sterke-en-veilige-achterhoek\/digitale-veiligheid\/","name":"D66 Aalten-Dinxperlo &#8212; Digitale veiligheid | Verkiezingsprogramma","isPartOf":{"@id":"https:\/\/d66.nl\/aalten\/#website"},"datePublished":"2021-12-28T17:25:39+00:00","dateModified":"2021-12-28T17:25:40+00:00","description":"D66 staat ook voor vrijheid, privacy en veiligheid in de digitale wereld. De gemeente betaalt uit principe geen losgeld aan criminelen voor cybergijzeling.","breadcrumb":{"@id":"https:\/\/d66.nl\/aalten\/verkiezingsprogramma\/voor-een-sterke-en-veilige-achterhoek\/digitale-veiligheid\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/d66.nl\/aalten\/verkiezingsprogramma\/voor-een-sterke-en-veilige-achterhoek\/digitale-veiligheid\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/d66.nl\/aalten\/verkiezingsprogramma\/voor-een-sterke-en-veilige-achterhoek\/digitale-veiligheid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/d66.nl\/aalten\/"},{"@type":"ListItem","position":2,"name":"Voor een sterke en veilige Achterhoek","item":"https:\/\/d66.nl\/aalten\/verkiezingsprogramma\/voor-een-sterke-en-veilige-achterhoek\/"},{"@type":"ListItem","position":3,"name":"Digitale veiligheid"}]},{"@type":"WebSite","@id":"https:\/\/d66.nl\/aalten\/#website","url":"https:\/\/d66.nl\/aalten\/","name":"D66 Aalten-Dinxperlo","description":"Just another D66 Sites site","publisher":{"@id":"https:\/\/d66.nl\/aalten\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d66.nl\/aalten\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/d66.nl\/aalten\/#organization","name":"D66","url":"https:\/\/d66.nl\/aalten\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/d66.nl\/aalten\/#\/schema\/logo\/image\/","url":"https:\/\/d66.nl\/aalten\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","contentUrl":"https:\/\/d66.nl\/aalten\/wp-content\/uploads\/sites\/2\/2021\/10\/d66-themas-algemeen-og.png","width":1200,"height":628,"caption":"D66"},"image":{"@id":"https:\/\/d66.nl\/aalten\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d66.nl\/aalten\/wp-json\/wp\/v2\/verkiezingsprogramma\/734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d66.nl\/aalten\/wp-json\/wp\/v2\/verkiezingsprogramma"}],"about":[{"href":"https:\/\/d66.nl\/aalten\/wp-json\/wp\/v2\/types\/manifesto"}],"author":[{"embeddable":true,"href":"https:\/\/d66.nl\/aalten\/wp-json\/wp\/v2\/users\/437"}],"up":[{"embeddable":true,"href":"https:\/\/d66.nl\/aalten\/wp-json\/wp\/v2\/verkiezingsprogramma\/475"}],"wp:attachment":[{"href":"https:\/\/d66.nl\/aalten\/wp-json\/wp\/v2\/media?parent=734"}],"wp:term":[{"taxonomy":"themes-or-point-of-view","embeddable":true,"href":"https:\/\/d66.nl\/aalten\/wp-json\/wp\/v2\/themes-or-point-of-view?post=734"},{"taxonomy":"search-tags","embeddable":true,"href":"https:\/\/d66.nl\/aalten\/wp-json\/wp\/v2\/search-tags?post=734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}